{"id":171625,"date":"2021-08-03T07:55:33","date_gmt":"2021-08-03T10:55:33","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=171625"},"modified":"2021-08-03T20:54:33","modified_gmt":"2021-08-03T23:54:33","slug":"btg-pactual-bpac11-juros-sobre-capital-proprio","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/","title":{"rendered":"BTG Pactual (BPAC11) aprova pagamento de JCP para 12 de agosto"},"content":{"rendered":"<p>O <a href=\"https:\/\/www.suno.com.br\/acoes\/BPAC11\/\">Banco BTG Pactual (BPAC11)<\/a> anunciou a distribui\u00e7\u00e3o de proventos no formato de <a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/artigos\/entenda-o-jcp\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-force=\"no\" data-priority=\"1\">juros sobre o capital pr\u00f3prio<\/a>.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/34822677-btg-pactual-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/34822677-btg-pactual-800x450.webp\" width=\"800\" height=\"450\" alt=\"BTG Pactual (BPAC11) aprova pagamento de JCP para 12 de agosto\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">BTG Pactual. Foto: Reprodu\u00e7\u00e3o Facebook<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-controle-gastos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Planilha-controle-de-gastos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t\tdata-promo-id=\"101751\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>Segundo o <a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/artigos\/fato-relevante\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-force=\"no\" data-priority=\"1\">fato relevante<\/a>, os JCP ser\u00e3o creditados aos detentores de a\u00e7\u00f5es na propor\u00e7\u00e3o de suas participa\u00e7\u00f5es no capital social do BTG e sofrer\u00e3o reten\u00e7\u00e3o de 15% referente ao Imposto de Renda. O pagamento ocorrer\u00e1 em 12 de agosto deste ano.<\/p>\n<p>Veja abaixo os valores individualizados:<\/p>\n<ul>\n<li>Valor bruto por a\u00e7\u00e3o ordin\u00e1ria ou preferencial: R$ 0,056635082;<\/li>\n<li>Valor l\u00edquido por a\u00e7\u00e3o ordin\u00e1ria ou a\u00e7\u00e3o preferencial: R$ 0,048139820;<\/li>\n<li>Valor bruto por Unit: R$ 0,169905246;<\/li>\n<li>Valor l\u00edquido por Unit: R$ 0,144419460.<\/li>\n<\/ul>\n<p>Os <a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/artigos\/entenda-o-jcp\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-force=\"no\" data-priority=\"1\">juros sobre capital pr\u00f3prio<\/a> ser\u00e3o creditados aos acionistas que se encontrarem inscritos nos registro do BTG no final do dia 5 de agosto, sendo as a\u00e7\u00f5es do banco negociadas &#8220;ex-direitos&#8221; a partir de 6 deste m\u00eas.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"106682\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p><strong>Veja Tamb\u00e9m:<\/strong><\/p>\n<h2>Cade aprova compra da Empiricus e V\u00edtreo pelo BTG<\/h2>\n<p>No m\u00eas passado, o Conselho Administrativo de Defesa Econ\u00f4mica (Cade) aprovou, sem restri\u00e7\u00f5es, a aquisi\u00e7\u00e3o da <strong>Empiricus<\/strong> e <strong>Vitreo<\/strong> Holding e de suas subsidi\u00e1rias pelo BTG Pactual.<\/p>\n<p>No fim de maio, a institui\u00e7\u00e3o havia anunciado a compra de 100% do Grupo Universa, conglomerado que re\u00fane as empresas Empiricus, Vitreo, Money Times, Seu Dinheiro e Real Valor.<\/p>\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Veja Tamb\u00e9m<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/btg-bpac11-dois-etfs-guerra-xp-itau-itub4\/\">\n\t\t\tBTG (BPAC11) lan\u00e7a dois novos ETFs e vai \u00e0 guerra contra XP e Ita\u00fa (ITUB4)\t\t<\/a>\n\t<\/div>\n\n\n<p>Pela compra, a institui\u00e7\u00e3o far\u00e1 o pagamento de R$ 440 milh\u00f5es \u00e0 vista e R$ 250 milh\u00f5es em units da institui\u00e7\u00e3o, ambos mediante a conclus\u00e3o da transa\u00e7\u00e3o. Adicionalmente, poder\u00e1 haver o pagamento de valores financeiros no per\u00edodo de 4 anos, a depender do atingimento de metas operacionais e financeiras.<\/p>\n<p>Em nota divulgada \u00e0 imprensa, o <strong>BTG<\/strong> destaca que, com o neg\u00f3cio, avan\u00e7a em sua consolida\u00e7\u00e3o como uma das principais institui\u00e7\u00f5es da ind\u00fastria de investimentos de varejo no Brasil. A Universa, por sua vez, ganha musculatura para ampliar sua atua\u00e7\u00e3o junto ao investidor <a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/artigos\/pessoa-fisica\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-force=\"no\" data-priority=\"1\">pessoa f\u00edsica<\/a>, mantendo a independ\u00eancia editorial e de cria\u00e7\u00e3o de produtos.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-de-controle-de-investimentos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Controle-de-Investimentos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t\tdata-promo-id=\"75934\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>O Banco BTG Pactual (BPAC11) anunciou a distribui\u00e7\u00e3o de proventos no formato de juros sobre o capital pr\u00f3prio. BTG Pactual. Foto: Reprodu\u00e7\u00e3o Facebook Segundo o fato relevante, os JCP ser\u00e3o creditados aos detentores de a\u00e7\u00f5es na propor\u00e7\u00e3o de suas participa\u00e7\u00f5es no capital social do BTG e sofrer\u00e3o reten\u00e7\u00e3o de 15% referente ao Imposto de Renda. [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":152850,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[399,1957],"suno_strategy":[],"class_list":["post-171625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-btg-pactual-bpac11-bpac3-bpac5","tag-juros-sobre-capital-proprio-jcp"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BTG Pactual (BPAC11) aprova pagamento de JCP para 12 de agosto<\/title>\n<meta name=\"description\" content=\"O Banco BTG Pactual (BPAC11) anunciou a distribui\u00e7\u00e3o de proventos no formato de juros sobre o capital pr\u00f3prio.\u00a0Clique aqui e saiba mais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BTG Pactual (BPAC11) aprova pagamento de JCP para 12 de agosto\" \/>\n<meta property=\"og:description\" content=\"O Banco BTG Pactual (BPAC11) anunciou a distribui\u00e7\u00e3o de proventos no formato de juros sobre o capital pr\u00f3prio.\u00a0Clique aqui e saiba mais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/34822677-btg-pactual.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Poliana Santos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Poliana Santos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/\"},\"author\":{\"name\":\"Poliana Santos\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda\"},\"headline\":\"BTG Pactual (BPAC11) aprova pagamento de JCP para 12 de agosto\",\"datePublished\":\"2021-08-03T10:55:33+00:00\",\"dateModified\":\"2021-08-03T23:54:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/\"},\"wordCount\":359,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/34822677-btg-pactual-jpg.webp\",\"keywords\":[\"BTG Pactual (BPAC11\/BPAC3\/BPAC5)\",\"juros sobre capital pr\u00f3prio (JCP)\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/\",\"name\":\"BTG Pactual (BPAC11) aprova pagamento de JCP para 12 de agosto\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/34822677-btg-pactual-jpg.webp\",\"datePublished\":\"2021-08-03T10:55:33+00:00\",\"dateModified\":\"2021-08-03T23:54:33+00:00\",\"description\":\"O Banco BTG Pactual (BPAC11) anunciou a distribui\u00e7\u00e3o de proventos no formato de juros sobre o capital pr\u00f3prio.\u00a0Clique aqui e saiba mais.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/34822677-btg-pactual-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/34822677-btg-pactual-jpg.webp\",\"width\":1200,\"height\":1200,\"caption\":\"BTG Pactual. Foto: Reprodu\u00e7\u00e3o Facebook\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BTG Pactual (BPAC11) aprova pagamento de JCP para 12 de agosto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda\",\"name\":\"Poliana Santos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g\",\"caption\":\"Poliana Santos\"},\"description\":\"Rep\u00f3rter no Suno Not\u00edcias, com cobertura em mercado financeiro, economia, finan\u00e7as pessoais, renda fixa e varejo. Jornalista formada pela Faculdade C\u00e1sper L\u00edbero e possui passagem na R\u00e1dio Gazeta AM com a produ\u00e7\u00e3o de conte\u00fado sobre economia, pol\u00edtica, sa\u00fade, moda e m\u00fasica. Possui certificado de conclus\u00e3o do curso de An\u00e1lise de Balan\u00e7os pela Funda\u00e7\u00e3o Bradesco, Agenda Brasil pela FAAP, Educa\u00e7\u00e3o Pol\u00edtica por Alexandre Garcia e do Tesouro Direto e Mercado de A\u00e7\u00f5es pela B3.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BTG Pactual (BPAC11) aprova pagamento de JCP para 12 de agosto","description":"O Banco BTG Pactual (BPAC11) anunciou a distribui\u00e7\u00e3o de proventos no formato de juros sobre o capital pr\u00f3prio.\u00a0Clique aqui e saiba mais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/","og_locale":"pt_BR","og_type":"article","og_title":"BTG Pactual (BPAC11) aprova pagamento de JCP para 12 de agosto","og_description":"O Banco BTG Pactual (BPAC11) anunciou a distribui\u00e7\u00e3o de proventos no formato de juros sobre o capital pr\u00f3prio.\u00a0Clique aqui e saiba mais.","og_url":"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1200,"height":1200,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/34822677-btg-pactual.jpg","type":"image\/jpeg"}],"author":"Poliana Santos","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Poliana Santos","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/"},"author":{"name":"Poliana Santos","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda"},"headline":"BTG Pactual (BPAC11) aprova pagamento de JCP para 12 de agosto","datePublished":"2021-08-03T10:55:33+00:00","dateModified":"2021-08-03T23:54:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/"},"wordCount":359,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/34822677-btg-pactual-jpg.webp","keywords":["BTG Pactual (BPAC11\/BPAC3\/BPAC5)","juros sobre capital pr\u00f3prio (JCP)"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/","url":"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/","name":"BTG Pactual (BPAC11) aprova pagamento de JCP para 12 de agosto","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/34822677-btg-pactual-jpg.webp","datePublished":"2021-08-03T10:55:33+00:00","dateModified":"2021-08-03T23:54:33+00:00","description":"O Banco BTG Pactual (BPAC11) anunciou a distribui\u00e7\u00e3o de proventos no formato de juros sobre o capital pr\u00f3prio.\u00a0Clique aqui e saiba mais.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/34822677-btg-pactual-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/34822677-btg-pactual-jpg.webp","width":1200,"height":1200,"caption":"BTG Pactual. Foto: Reprodu\u00e7\u00e3o Facebook"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"BTG Pactual (BPAC11) aprova pagamento de JCP para 12 de agosto"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda","name":"Poliana Santos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g","caption":"Poliana Santos"},"description":"Rep\u00f3rter no Suno Not\u00edcias, com cobertura em mercado financeiro, economia, finan\u00e7as pessoais, renda fixa e varejo. Jornalista formada pela Faculdade C\u00e1sper L\u00edbero e possui passagem na R\u00e1dio Gazeta AM com a produ\u00e7\u00e3o de conte\u00fado sobre economia, pol\u00edtica, sa\u00fade, moda e m\u00fasica. Possui certificado de conclus\u00e3o do curso de An\u00e1lise de Balan\u00e7os pela Funda\u00e7\u00e3o Bradesco, Agenda Brasil pela FAAP, Educa\u00e7\u00e3o Pol\u00edtica por Alexandre Garcia e do Tesouro Direto e Mercado de A\u00e7\u00f5es pela B3.","url":"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/34822677-btg-pactual-400x200.webp\" alt=\"BTG Pactual (BPAC11) aprova pagamento de JCP para 12 de agosto\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/btg-pactual-bpac11-juros-sobre-capital-proprio\/\"><h2 class=\"content__title\">BTG Pactual (BPAC11) aprova pagamento de JCP para 12 de agosto<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/7ef34026-whatsapp-image-2020-08-03-at-12.37.57-150x150.webp\" alt=\"Poliana Santos\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\"><span itemprop=\"author\">Poliana Santos<\/span><\/a><\/span><time datetime=\"2021-08-03T07:55:33-03:00\" itemprop=\"datePublished\">03\/08\/2021 07:55<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/171625"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=171625"}],"version-history":[{"count":3,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/171625\/revisions"}],"predecessor-version":[{"id":172032,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/171625\/revisions\/172032"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/152850"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=171625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=171625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=171625"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=171625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}