{"id":163477,"date":"2021-07-03T12:59:40","date_gmt":"2021-07-03T15:59:40","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=163477"},"modified":"2021-07-03T12:59:40","modified_gmt":"2021-07-03T15:59:40","slug":"ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/","title":{"rendered":"Ibovespa: Banco Inter (BIDI11) e Braskem (BRKM5) t\u00eam maiores altas na semana"},"content":{"rendered":"<p>A <a href=\"https:\/\/www.suno.com.br\/acoes\/ugpa3\/\">Ultrapar (UGPA3)<\/a> e o <a href=\"https:\/\/www.suno.com.br\/acoes\/bidi11\/\">Banco Inter (BIDI11)<\/a> foram as duas empresas que lideraram as maiores altas do <strong>Ibovespa<\/strong> nesta semana. Al\u00e9m disso, a \u00a0<a href=\"https:\/\/www.suno.com.br\/acoes\/prio3\/\">PetroRio (PRIO3)<\/a>, a<a href=\"https:\/\/www.suno.com.br\/acoes\/brkm5\/\"> Braskem (BRKM5)<\/a> e a <a href=\"https:\/\/www.suno.com.br\/acoes\/brdt3\/\">BR Distribuidora (BRDT3)<\/a> tamb\u00e9m decolaram\u00a0 na primeira semana do m\u00eas.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/06\/f4184141-entrepreneur-1340649_1280-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/06\/f4184141-entrepreneur-1340649_1280-800x450.webp\" width=\"800\" height=\"450\" alt=\"Ibovespa: Banco Inter (BIDI11) e Braskem (BRKM5) t\u00eam maiores altas na semana\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Ibovespa. Foto: Pixabay.<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-controle-gastos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Planilha-controle-de-gastos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t\tdata-promo-id=\"101751\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>Por sua vez, o Ibovespa teve um desemprenho positivo e encerrou a semana acumulando uma alta de 0,29%.<\/p>\n<p>Confira o tamanho do salto dos cinco ativos que mais avan\u00e7aram na semana:<\/p>\n<ul>\n<li><strong>Ultrapar (UGPA3)\u00a0<\/strong>subiu 116,57%<\/li>\n<li><strong> Banco Inter (BIDI11)<\/strong> subiu 12,49%<\/li>\n<li><strong>PetroRio (PRIO3)<\/strong> subiu 11,43%<\/li>\n<li><strong>Braskem (BRKM5)\u00a0<\/strong>subiu 8,26%<\/li>\n<li><strong>BR Distribuidora (BRDT3) <\/strong>subiu 6,56%<\/li>\n<\/ul>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"106682\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<h2>1. Ultrapar (UGPA3) lidera altas do Ibovespa<\/h2>\n<p>A a\u00e7\u00f5es da Ultrapar ficaram no topo das <strong>valoriza\u00e7\u00f5es do Ibovespa<\/strong>, impulsionada pela venda de 50% das a\u00e7\u00f5es da <strong>ConectCar<\/strong> para a <a href=\"https:\/\/www.suno.com.br\/acoes\/pssa3\/\"><strong>Porto Seguro<\/strong> (PSSA3)<\/a>.<\/p>\n<p>O valor da opera\u00e7\u00e3o \u00e9 de R$ 165 milh\u00f5es, sujeito a ajuste at\u00e9 a liquida\u00e7\u00e3o final da transa\u00e7\u00e3o.<\/p>\n<p>A ConectCar \u00e9 uma das principais companhias do mercado no segmento de <strong>pagamentos eletr\u00f4nicos autom\u00e1ticos<\/strong> em ped\u00e1gios, estacionamentos, drive thrus e outros servi\u00e7os, por meio de tag.<\/p>\n<p>Assim, o papel da Ultrapar (UGPA3) encerrou a semana com uma alta de 116,57%, valendo R$ 18,95.<\/p>\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Saiba mais <\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/porto-seguro-pssa3-compra-50-conectcar-ultraparugpa3r-r-165-mi\/\">\n\t\t\tPorto Seguro (PSSA3) adquire 50% da ConectCar, da Ultrapar (UGPA3), por R$ 165 mi\t\t<\/a>\n\t<\/div>\n\n\n<h2>2. <strong>Banco Inter<\/strong><\/h2>\n<p>A segunda <strong>a\u00e7\u00e3o que faz parte do Ibovespa<\/strong> que mais avan\u00e7ou na semana foi a do Banco Inter (BIDI11), que acumulou uma alta de 12,49%, e encerrou o \u00faltimo <strong>preg\u00e3o<\/strong>, sexta-feira (2), valendo R$ 78,74.<\/p>\n<p>O <strong>banco digital<\/strong>\u00a0concluiu, na \u00faltima ter\u00e7a-feira (29), o acordo de acionistas com a <strong>Stone<\/strong> (NASDAQ: STNE). A companhia comprou 4,99% do banco no \u00e2mbito da oferta subsequente de a\u00e7\u00f5es (<strong>follow-on<\/strong>), <a href=\"https:\/\/www.suno.com.br\/noticias\/banco-inter-bidi11-precifica-oferta\/\">realizada neste m\u00eas<\/a>.<\/p>\n<p>Na opera\u00e7\u00e3o, a <strong>Stone<\/strong> levou 85.904.674 a\u00e7\u00f5es ordin\u00e1rias e 42.726.032 a\u00e7\u00f5es preferenciais do Banco Inter. As <strong>units<\/strong> foram compradas a R$ 57,84, sendo que hoje s\u00e3o negociadas no mercado a R$ 73,83.<\/p>\n<p>Ap\u00f3s a <strong>oferta subsequente<\/strong>\u00a0 do Banco Inter, a S&amp;P elevou o rating do banco de &#8216;brAA&#8217; para &#8216;brAA+&#8217; com perspectiva est\u00e1vel.<\/p>\n<p>Al\u00e9m disso, no in\u00edcio da semana a <a href=\"https:\/\/www.suno.com.br\/acoes\/qual3\/\"><strong>Qualicorp (QUAL3)<\/strong><\/a> e o banco firmaram uma parceria para comercializa\u00e7\u00e3o de planos de sa\u00fade coletivos por ades\u00e3o.<\/p>\n\n\t<div data-element=\"shortcode-read-more\" class=\"readToo\">\n\t\t\t\t<span class=\"readToo__title\">Saiba mais <\/span>\n\t\t\t\t<ul class=\"readToo__list\">\n\t\t\t<li><a href=\"https:\/\/www.suno.com.br\/noticias\/inter-bidi11-tira-banco-aposta-superapp\/\">Inter (BIDI11) tira &#8216;banco&#8217; do nome e aposta em superapp<\/a><\/li><li><a href=\"https:\/\/www.suno.com.br\/noticias\/banco-inter-bidi11-rating-stone\/\">Banco Inter (BIDI11): S&#038;P eleva rating e v\u00ea oportunidades com a Stone como s\u00f3cia<\/a><\/li><li><a href=\"https:\/\/www.suno.com.br\/noticias\/banco-inter-bidi11-qualicorp-qual3-plano-de-saude\/\">Banco Inter (BIDI11) e Qualicorp (QUAL3) firmam acordo de planos de sa\u00fade<\/a><\/li>\t\t<\/ul>\n\t<\/div>\n\n\n<h2>3. PetroRio<\/h2>\n<p>A terceira a\u00e7\u00e3o do<a href=\"https:\/\/www.suno.com.br\/artigos\/ibovespa\/\"><strong> \u00edndice Bovespa<\/strong><\/a> que mais valorizou na semana foi a da PetroRio (PRIO3), que subiu 11,43%, para R$ 21,26.<\/p>\n<p>Ao final da \u00faltima semana, a<strong> Ag\u00eancia Nacional de Petr\u00f3leo, G\u00e1s Natural e Biocombust\u00edveis (ANP)<\/strong> aprovou o plano de desenvolvimento para o<strong> Campo de Frade<\/strong> desenvolvido pela PetroRio, que inclui a perfura\u00e7\u00e3o de quatro po\u00e7os produtores e tr\u00eas po\u00e7os injetores horizontais.<\/p>\n<p>&#8220;Na mesma decis\u00e3o, a <strong>ANP<\/strong> autorizou a retomada imediata da inje\u00e7\u00e3o de \u00e1gua em dois po\u00e7os injetores existentes, at\u00e9 o in\u00edcio da opera\u00e7\u00e3o dos novos po\u00e7os injetores (ou um ano)&#8221;, diz a companhia, em<strong> <a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/artigos\/fato-relevante\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-force=\"no\" data-priority=\"1\">fato relevante.<\/a><\/strong><\/p>\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Saiba mais <\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/petrorio-prio3-aval-anp-perfuracoes-frade\/\">\n\t\t\tPetroRio (PRIO3) ganha aval da ANP e far\u00e1 novas perfura\u00e7\u00f5es no Campo de Frade, no pr\u00e9-sal\t\t<\/a>\n\t<\/div>\n\n\n<h2>4. Braskem<\/h2>\n<p>A <strong>a\u00e7\u00e3o da Braskem (BRKM5)<\/strong> tamb\u00e9m foi <strong>destaque do Ibovespa<\/strong> nesta semana, quando valorizou 8,26%, para R$ 60,00.<\/p>\n<p>Na \u00faltima quarta-feira (30) se encerraria o prazo de recebimento das propostas n\u00e3o-vinculantes de compra da Braskem, mas o per\u00edodo foi postergado para 9 de julho.<\/p>\n<p>Segundo o jornal <em>Valor Econ\u00f4mico<\/em>, a decis\u00e3o foi tomada pela <strong>Novonor<\/strong> (antiga <strong>Odebrecht<\/strong>) por conta do pedido de potenciais compradores da petroqu\u00edmica. Ao menos dois interessados pediram mais tempo.<\/p>\n<p>Segundo relatou o jornal, a <strong>Novonor<\/strong> optou pela abertura de um processo competitivo para vender a fatia de 38,3% no capital total da empresa. Com base no <a href=\"https:\/\/www.suno.com.br\/artigos\/valor-de-mercado\/\">valor de mercado<\/a> atual, essa participa\u00e7\u00e3o corresponde a R$ 17,69 bilh\u00f5es.<\/p>\n<h2>5. BR Distribuidora tamb\u00e9m se destacou no Ibovespa<\/h2>\n<p>Outro destaque de queda do Ibovespa na semana foi a<strong> privatiza\u00e7\u00e3o da BR Distribuidora<\/strong> ap\u00f3s a <strong>maior\u00a0oferta de a\u00e7\u00f5es<\/strong> do ano. A a\u00e7\u00e3o da companhia acumulou uma alta de 6,56%, e encerrou o \u00faltimo preg\u00e3o valendo R$ 29,39.<\/p>\n<p>A <a href=\"https:\/\/www.suno.com.br\/acoes\/petr4\/\"><strong>Petrobras<\/strong> (PETR4)<\/a> confirmou na \u00faltima quarta-feira (30), em <a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/artigos\/fato-relevante\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-force=\"no\" data-priority=\"1\">fato relevante<\/a> que seu <a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/artigos\/conselho-administracao\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-force=\"no\" data-priority=\"1\">conselho de administra\u00e7\u00e3o<\/a> aprovou o pre\u00e7o de R$ 26 por a\u00e7\u00e3o para as a\u00e7\u00f5es da BR Distribuidora , no \u00e2mbito da oferta p\u00fablica de distribui\u00e7\u00e3o secund\u00e1ria de a\u00e7\u00f5es (follow-on), movimentando R$ 11,358 bilh\u00f5es.<\/p>\n<p>A <strong>demanda pela a\u00e7\u00e3o<\/strong> a R$ 26,00, pre\u00e7o fechado na venda, chegou a encostar em R$ 25 bilh\u00f5es, n\u00famero que surpreendeu os envolvidos. A oferta, uma das maiores opera\u00e7\u00f5es secund\u00e1rias (venda de a\u00e7\u00f5es j\u00e1 existentes) j\u00e1 feitas no Brasil, atraiu ordens de 120 fundos, locais e estrangeiros, de acordo com fontes.<\/p>\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Saiba mais<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/petrobras-petr4-follow-on-br-distribuidora-brdt3-2\/\">\n\t\t\tPetrobras (PETR4) levanta R$ 11,3 bilh\u00f5es com follow-on da BR Distribuidora (BRDT3)\t\t<\/a>\n\t<\/div>\n\n\n<h2>\u00daltima cota\u00e7\u00e3o do Ibovespa<\/h2>\n<p>O <strong>Ibovespa<\/strong> encerrou as negocia\u00e7\u00f5es na \u00faltima sexta-feira com alta de 1,56% e devolveu as perdas da semana, chegando aos 127.621,65 pontos. No acumulado semanal, o \u00edndice acion\u00e1rio subiu 0,29%.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-de-controle-de-investimentos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Controle-de-Investimentos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t\tdata-promo-id=\"75934\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>A Ultrapar (UGPA3) e o Banco Inter (BIDI11) foram as duas empresas que lideraram as maiores altas do Ibovespa nesta semana. Al\u00e9m disso, a \u00a0PetroRio (PRIO3), a Braskem (BRKM5) e a BR Distribuidora (BRDT3) tamb\u00e9m decolaram\u00a0 na primeira semana do m\u00eas. Banco Inter (BIDI11) &#8211; Foto: Divulga\u00e7\u00e3o Por sua vez, o Ibovespa teve um desemprenho [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":155666,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[369,395,721,597,671,596],"suno_strategy":[],"class_list":["post-163477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-banco-inter-bidi11-bidi4-bidi3","tag-braskem-brkm3-brkm5-brkm6","tag-ibovespa","tag-petrorio-prio3","tag-ultrapar-ugpa3","tag-vibra-energia-vbbr3"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ibovespa: Banco Inter (BIDI11) e Braskem (BRKM5) t\u00eam maiores altas<\/title>\n<meta name=\"description\" content=\"A Ultrapar (UGPA3) e o Banco Inter (BIDI11) lideraram as maiores altas do Ibovespa nesta semana. Veja as 5 a\u00e7\u00f5es que mais valorizaram!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ibovespa: Banco Inter (BIDI11) e Braskem (BRKM5) t\u00eam maiores altas\" \/>\n<meta property=\"og:description\" content=\"A Ultrapar (UGPA3) e o Banco Inter (BIDI11) lideraram as maiores altas do Ibovespa nesta semana. Veja as 5 a\u00e7\u00f5es que mais valorizaram!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/06\/f4184141-entrepreneur-1340649_1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"905\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Laura Moutinho\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laura Moutinho\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/\"},\"author\":{\"name\":\"Laura Moutinho\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/3df0d2808748b74496efe5dbeaef2c72\"},\"headline\":\"Ibovespa: Banco Inter (BIDI11) e Braskem (BRKM5) t\u00eam maiores altas na semana\",\"datePublished\":\"2021-07-03T15:59:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/\"},\"wordCount\":817,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/06\/f4184141-entrepreneur-1340649_1280-jpg.webp\",\"keywords\":[\"Banco Inter (BIDI11\/BIDI4\/BIDI3)\",\"Braskem (BRKM3\/BRKM5\/BRKM6)\",\"Ibovespa\",\"PetroRio (PRIO3)\",\"Ultrapar (UGPA3)\",\"Vibra Energia (VBBR3)\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/\",\"name\":\"Ibovespa: Banco Inter (BIDI11) e Braskem (BRKM5) t\u00eam maiores altas\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/06\/f4184141-entrepreneur-1340649_1280-jpg.webp\",\"datePublished\":\"2021-07-03T15:59:40+00:00\",\"description\":\"A Ultrapar (UGPA3) e o Banco Inter (BIDI11) lideraram as maiores altas do Ibovespa nesta semana. Veja as 5 a\u00e7\u00f5es que mais valorizaram!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/06\/f4184141-entrepreneur-1340649_1280-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/06\/f4184141-entrepreneur-1340649_1280-jpg.webp\",\"width\":1280,\"height\":905,\"caption\":\"Ibovespa. Foto: Pixabay.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ibovespa: Banco Inter (BIDI11) e Braskem (BRKM5) t\u00eam maiores altas na semana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/3df0d2808748b74496efe5dbeaef2c72\",\"name\":\"Laura Moutinho\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7571c7c8ca3a6fca5e41384ece5557ff?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7571c7c8ca3a6fca5e41384ece5557ff?s=96&r=g\",\"caption\":\"Laura Moutinho\"},\"description\":\"Estagi\u00e1ria na Suno Not\u00edcias, escreve not\u00edcias que afetam o mercado financeiro. Estuda administra\u00e7\u00e3o na Universidade Presbiteriana Mackenzie.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/laura-moutinho\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ibovespa: Banco Inter (BIDI11) e Braskem (BRKM5) t\u00eam maiores altas","description":"A Ultrapar (UGPA3) e o Banco Inter (BIDI11) lideraram as maiores altas do Ibovespa nesta semana. Veja as 5 a\u00e7\u00f5es que mais valorizaram!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/","og_locale":"pt_BR","og_type":"article","og_title":"Ibovespa: Banco Inter (BIDI11) e Braskem (BRKM5) t\u00eam maiores altas","og_description":"A Ultrapar (UGPA3) e o Banco Inter (BIDI11) lideraram as maiores altas do Ibovespa nesta semana. Veja as 5 a\u00e7\u00f5es que mais valorizaram!","og_url":"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1280,"height":905,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/06\/f4184141-entrepreneur-1340649_1280.jpg","type":"image\/jpeg"}],"author":"Laura Moutinho","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Laura Moutinho","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/"},"author":{"name":"Laura Moutinho","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/3df0d2808748b74496efe5dbeaef2c72"},"headline":"Ibovespa: Banco Inter (BIDI11) e Braskem (BRKM5) t\u00eam maiores altas na semana","datePublished":"2021-07-03T15:59:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/"},"wordCount":817,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/06\/f4184141-entrepreneur-1340649_1280-jpg.webp","keywords":["Banco Inter (BIDI11\/BIDI4\/BIDI3)","Braskem (BRKM3\/BRKM5\/BRKM6)","Ibovespa","PetroRio (PRIO3)","Ultrapar (UGPA3)","Vibra Energia (VBBR3)"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/","url":"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/","name":"Ibovespa: Banco Inter (BIDI11) e Braskem (BRKM5) t\u00eam maiores altas","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/06\/f4184141-entrepreneur-1340649_1280-jpg.webp","datePublished":"2021-07-03T15:59:40+00:00","description":"A Ultrapar (UGPA3) e o Banco Inter (BIDI11) lideraram as maiores altas do Ibovespa nesta semana. Veja as 5 a\u00e7\u00f5es que mais valorizaram!","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/06\/f4184141-entrepreneur-1340649_1280-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/06\/f4184141-entrepreneur-1340649_1280-jpg.webp","width":1280,"height":905,"caption":"Ibovespa. Foto: Pixabay."},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/ibovespa-banco-inter-bidi11-braskem-brkm5-maiores-altas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Ibovespa: Banco Inter (BIDI11) e Braskem (BRKM5) t\u00eam maiores altas na semana"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/3df0d2808748b74496efe5dbeaef2c72","name":"Laura Moutinho","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7571c7c8ca3a6fca5e41384ece5557ff?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7571c7c8ca3a6fca5e41384ece5557ff?s=96&r=g","caption":"Laura Moutinho"},"description":"Estagi\u00e1ria na Suno Not\u00edcias, escreve not\u00edcias que afetam o mercado financeiro. Estuda administra\u00e7\u00e3o na Universidade Presbiteriana Mackenzie.","url":"https:\/\/www.suno.com.br\/noticias\/author\/laura-moutinho\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/banco-inter-bidi11-qualicorp-qual3-plano-de-saude\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/06\/dad9092c-fachada_inter-400x200.jpeg\" alt=\"Banco Inter (BIDI11) e Qualicorp (QUAL3) firmam acordo de planos de sa\u00fade\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/banco-inter-bidi11-qualicorp-qual3-plano-de-saude\/\"><h2 class=\"content__title\">Banco Inter (BIDI11) e Qualicorp (QUAL3) firmam acordo de planos de sa\u00fade<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/7ef34026-whatsapp-image-2020-08-03-at-12.37.57-150x150.webp\" alt=\"Poliana Santos\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\"><span itemprop=\"author\">Poliana Santos<\/span><\/a><\/span><time datetime=\"2021-06-28T09:29:31-03:00\" itemprop=\"datePublished\">28\/06\/2021 09:29<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/163477"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=163477"}],"version-history":[{"count":2,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/163477\/revisions"}],"predecessor-version":[{"id":163480,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/163477\/revisions\/163480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/155666"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=163477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=163477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=163477"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=163477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}