{"id":160858,"date":"2021-06-24T11:55:56","date_gmt":"2021-06-24T14:55:56","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=160858"},"modified":"2021-06-24T11:55:56","modified_gmt":"2021-06-24T14:55:56","slug":"dolar-24062021","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/","title":{"rendered":"D\u00f3lar tem queda de 0,6%, a R$ 4,93, com PIB dos EUA e Selic no radar do mercado"},"content":{"rendered":"<p>O <strong>d\u00f3lar<\/strong> apresenta queda nesta quinta-feira (24) com investidores acompanhando a <a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/artigos\/politica-monetaria\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-force=\"no\" data-priority=\"1\">pol\u00edtica monet\u00e1ria<\/a> do Brasil ap\u00f3s a divulga\u00e7\u00e3o do Relat\u00f3rio Trimestral de Infla\u00e7\u00e3o.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/475ceeb8-dollar-2931882_1280-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/475ceeb8-dollar-2931882_1280-800x450.webp\" width=\"800\" height=\"450\" alt=\"D\u00f3lar tem queda de 0,6%, a R$ 4,93, com PIB dos EUA e Selic no radar do mercado\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">D\u00f3lar. Foto: Pixabay<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-controle-gastos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Planilha-controle-de-gastos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t\tdata-promo-id=\"101751\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>Por volta 11h40, o d\u00f3lar tinha queda de 067%, negociado a R$ 4,93. Para a economista-chefe do Banco Ourinvest, Fernanda Consorte, o que movimenta o c\u00e2mbio hoje \u00e9 a taxa de juros do Brasil, revis\u00e3o do Produto Interno Bruto (PIB) dos Estados Unidos e o caso da Covaxin.<\/p>\n<p><a href=\"https:\/\/lp.suno.com.br\/suno-one\/\"><span style=\"font-weight: 400;\">Suno One: acesse gratuitamente eBooks, Minicursos, Artigos e Video Aulas sobre investimentos com um \u00fanico cadastro. Clique para saber mais!<\/span><\/a><\/p>\n<p>&#8220;O tema central \u00e9 taxa de juros no Brasil. E, nos Estados Unidos teremos a revis\u00e3o do PIB do primeiro trimestre e os discursos dos membros do Fed, em que o mercado deve acompanhar atentamente. O mercado tamb\u00e9m pode colocar no balan\u00e7o de risco o caso de Covaxin&#8221;.<\/p>\n<h2>Not\u00edcias que movimentam o d\u00f3lar hoje<\/h2>\n<p>Confira outras not\u00edcias que movimentaram o mercado hoje:<\/p>\n<ul>\n<li>BC volta indicar outro reajuste de 0,75 ponto percentual da Selic<\/li>\n<li>PIB dos EUA sobe 6,4% no primeiro trimestre<\/li>\n<li>Bolsonaro foi alertado sobre ind\u00edcios de regularidades na compra da Covaxin<\/li>\n<\/ul>\n<h2>Taxa Selic<\/h2>\n<p>O <a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/artigos\/bacen\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-force=\"no\" data-priority=\"3\">Banco Central (BC)<\/a> voltou a indicar nesta quinta-feira (24), por meio do Relat\u00f3rio Trimestral de Infla\u00e7\u00e3o (RTI), que deve promover novo aumento de 0,75 ponto porcentual da <a class=\"suno-keyword\" href=\"https:\/\/www.suno.com.br\/artigos\/taxa-basica-de-juros\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-force=\"no\" data-priority=\"1\">taxa b\u00e1sica de juros<\/a> (<strong>Selic<\/strong>) em agosto. Atualmente, a Selic est\u00e1 em 4,25% ao ano.<\/p>\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Saiba Mais<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/bc-volta-a-indicar-outro-ajuste-de-075-ponto-porcentual-da-selic-em-agosto\/\">\n\t\t\tBC volta a indicar outro ajuste de 0,75 ponto porcentual da Selic em agosto\t\t<\/a>\n\t<\/div>\n\n\n<p>&#8220;Para a pr\u00f3xima reuni\u00e3o, o Comit\u00ea antev\u00ea a continua\u00e7\u00e3o do processo de normaliza\u00e7\u00e3o monet\u00e1ria com outro ajuste da mesma magnitude (0,75 ponto)&#8221;, registrou o <strong>RTI<\/strong>. &#8220;Contudo, uma deteriora\u00e7\u00e3o das expectativas de infla\u00e7\u00e3o para o horizonte relevante pode exigir uma redu\u00e7\u00e3o mais tempestiva dos est\u00edmulos monet\u00e1rios. O Comit\u00ea ressalta que essa avalia\u00e7\u00e3o tamb\u00e9m depender\u00e1 da evolu\u00e7\u00e3o da atividade econ\u00f4mica, do balan\u00e7o de riscos e de como esses fatores afetam as proje\u00e7\u00f5es de infla\u00e7\u00e3o&#8221;.<\/p>\n<h2>PIB dos EUA<\/h2>\n<p>O PIB dos EUA cresceu \u00e0 taxa anualizada de 6,4% no 1\u00ba trimestre de 2021 em rela\u00e7\u00e3o aos tr\u00eas meses anteriores, de acordo com a terceira e \u00faltima estimativa. Os dados s\u00e3o do escrit\u00f3rio de estat\u00edsticas do BEA (Bureau of Economic Analysis), do Departamento de Com\u00e9rcio do pa\u00eds divulgados nesta quinta.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"106682\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>A primeira estimativa, divulgada em 29 de abril, tamb\u00e9m foi de alta de 6,4% na compara\u00e7\u00e3o trimestral, assim como a segunda estimativa relevada em 27 de maio. A proje\u00e7\u00e3o, segundo consenso Refinitiv, era de que o dado se mantivesse em avan\u00e7o de 6,4%.<\/p>\n<h2>Covaxin<\/h2>\n<p>De acordo com o jornal Folha de S.Paulo, as suspeitas envolvendo a compra da vacina indiana Covaxin atingiram o Pal\u00e1cio do Planalto, com o relato que o presidente Jair Bolsonaro foi alertado h\u00e1 mais de tr\u00eas meses dos ind\u00edcios de irregularidades.<\/p>\n<p>O contrato de R$ 1,6 bilh\u00e3o entrou na mira da CPI, que suspeita de favorecimento para a vacina indiana e, em particular, para a empresa brasileira Precisa Medicamentos, que atuou como intermedi\u00e1ria no neg\u00f3cio.<\/p>\n<p>A Covaxin foi a vacina mais cara negociada pelo governo federal, com valor de R$ 80 a dose. Al\u00e9m disso, as negocia\u00e7\u00f5es foram conclu\u00eddas em tempo recorde, quando comparada com os processos com a Pfizer e o Instituto Butantan.<\/p>\n<h2>Cota\u00e7\u00f5es das principais moedas<\/h2>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Euro: -0,57% \/\/ R$ 5,88<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Libra: -0,93% \/\/ R$6,86<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Yuan: -0,42% \/\/ R$ 0,76<\/span><\/li>\n<\/ul>\n<h2>\u00daltima cota\u00e7\u00e3o do d\u00f3lar<\/h2>\n<p>Na \u00faltima sess\u00e3o, quarta-feira, o <strong>d\u00f3lar<\/strong> encerrou em leve queda de 0,07%, negociado a R$ 4,96.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-de-controle-de-investimentos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Controle-de-Investimentos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t\tdata-promo-id=\"75934\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>O d\u00f3lar apresenta queda nesta quinta-feira (24) com investidores acompanhando a pol\u00edtica monet\u00e1ria do Brasil ap\u00f3s a divulga\u00e7\u00e3o do Relat\u00f3rio Trimestral de Infla\u00e7\u00e3o. D\u00f3lar. Foto: Pixabay Por volta 11h40, o d\u00f3lar tinha queda de 067%, negociado a R$ 4,93. Para a economista-chefe do Banco Ourinvest, Fernanda Consorte, o que movimenta o c\u00e2mbio hoje \u00e9 a [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":148884,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[60],"tags":[326,105816],"suno_strategy":[],"class_list":["post-160858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado","tag-dolar","tag-especialistas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>D\u00f3lar tem queda de 0,6%, a R$ 4,93, com PIB dos EUA e Selic no radar<\/title>\n<meta name=\"description\" content=\"Por volta 11h40, nesta quinta-feira (24), o d\u00f3lar hoje tinha queda de 067%, negociado a R$ 4,93. Para saber mais clique aqui e saiba mais\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00f3lar tem queda de 0,6%, a R$ 4,93, com PIB dos EUA e Selic no radar\" \/>\n<meta property=\"og:description\" content=\"Por volta 11h40, nesta quinta-feira (24), o d\u00f3lar hoje tinha queda de 067%, negociado a R$ 4,93. Para saber mais clique aqui e saiba mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/475ceeb8-dollar-2931882_1280.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"863\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Poliana Santos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Poliana Santos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/\"},\"author\":{\"name\":\"Poliana Santos\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda\"},\"headline\":\"D\u00f3lar tem queda de 0,6%, a R$ 4,93, com PIB dos EUA e Selic no radar do mercado\",\"datePublished\":\"2021-06-24T14:55:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/\"},\"wordCount\":618,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/475ceeb8-dollar-2931882_1280-png.webp\",\"keywords\":[\"d\u00f3lar\",\"Especialistas\"],\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/\",\"name\":\"D\u00f3lar tem queda de 0,6%, a R$ 4,93, com PIB dos EUA e Selic no radar\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/475ceeb8-dollar-2931882_1280-png.webp\",\"datePublished\":\"2021-06-24T14:55:56+00:00\",\"description\":\"Por volta 11h40, nesta quinta-feira (24), o d\u00f3lar hoje tinha queda de 067%, negociado a R$ 4,93. Para saber mais clique aqui e saiba mais\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/475ceeb8-dollar-2931882_1280-png.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/475ceeb8-dollar-2931882_1280-png.webp\",\"width\":1280,\"height\":863,\"caption\":\"D\u00f3lar. Foto: Pixabay\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/mercado\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"D\u00f3lar tem queda de 0,6%, a R$ 4,93, com PIB dos EUA e Selic no radar do mercado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda\",\"name\":\"Poliana Santos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g\",\"caption\":\"Poliana Santos\"},\"description\":\"Rep\u00f3rter no Suno Not\u00edcias, com cobertura em mercado financeiro, economia, finan\u00e7as pessoais, renda fixa e varejo. Jornalista formada pela Faculdade C\u00e1sper L\u00edbero e possui passagem na R\u00e1dio Gazeta AM com a produ\u00e7\u00e3o de conte\u00fado sobre economia, pol\u00edtica, sa\u00fade, moda e m\u00fasica. Possui certificado de conclus\u00e3o do curso de An\u00e1lise de Balan\u00e7os pela Funda\u00e7\u00e3o Bradesco, Agenda Brasil pela FAAP, Educa\u00e7\u00e3o Pol\u00edtica por Alexandre Garcia e do Tesouro Direto e Mercado de A\u00e7\u00f5es pela B3.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00f3lar tem queda de 0,6%, a R$ 4,93, com PIB dos EUA e Selic no radar","description":"Por volta 11h40, nesta quinta-feira (24), o d\u00f3lar hoje tinha queda de 067%, negociado a R$ 4,93. Para saber mais clique aqui e saiba mais","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/","og_locale":"pt_BR","og_type":"article","og_title":"D\u00f3lar tem queda de 0,6%, a R$ 4,93, com PIB dos EUA e Selic no radar","og_description":"Por volta 11h40, nesta quinta-feira (24), o d\u00f3lar hoje tinha queda de 067%, negociado a R$ 4,93. Para saber mais clique aqui e saiba mais","og_url":"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1280,"height":863,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/475ceeb8-dollar-2931882_1280.png","type":"image\/png"}],"author":"Poliana Santos","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Poliana Santos","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/"},"author":{"name":"Poliana Santos","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda"},"headline":"D\u00f3lar tem queda de 0,6%, a R$ 4,93, com PIB dos EUA e Selic no radar do mercado","datePublished":"2021-06-24T14:55:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/"},"wordCount":618,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/475ceeb8-dollar-2931882_1280-png.webp","keywords":["d\u00f3lar","Especialistas"],"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/","url":"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/","name":"D\u00f3lar tem queda de 0,6%, a R$ 4,93, com PIB dos EUA e Selic no radar","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/475ceeb8-dollar-2931882_1280-png.webp","datePublished":"2021-06-24T14:55:56+00:00","description":"Por volta 11h40, nesta quinta-feira (24), o d\u00f3lar hoje tinha queda de 067%, negociado a R$ 4,93. Para saber mais clique aqui e saiba mais","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/475ceeb8-dollar-2931882_1280-png.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/475ceeb8-dollar-2931882_1280-png.webp","width":1280,"height":863,"caption":"D\u00f3lar. Foto: Pixabay"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/www.suno.com.br\/noticias\/mercado\/"},{"@type":"ListItem","position":3,"name":"D\u00f3lar tem queda de 0,6%, a R$ 4,93, com PIB dos EUA e Selic no radar do mercado"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda","name":"Poliana Santos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g","caption":"Poliana Santos"},"description":"Rep\u00f3rter no Suno Not\u00edcias, com cobertura em mercado financeiro, economia, finan\u00e7as pessoais, renda fixa e varejo. Jornalista formada pela Faculdade C\u00e1sper L\u00edbero e possui passagem na R\u00e1dio Gazeta AM com a produ\u00e7\u00e3o de conte\u00fado sobre economia, pol\u00edtica, sa\u00fade, moda e m\u00fasica. Possui certificado de conclus\u00e3o do curso de An\u00e1lise de Balan\u00e7os pela Funda\u00e7\u00e3o Bradesco, Agenda Brasil pela FAAP, Educa\u00e7\u00e3o Pol\u00edtica por Alexandre Garcia e do Tesouro Direto e Mercado de A\u00e7\u00f5es pela B3.","url":"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/475ceeb8-dollar-2931882_1280-400x200.webp\" alt=\"D\u00f3lar tem queda de 0,6%, a R$ 4,93, com PIB dos EUA e Selic no radar do mercado\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/mercado\/\">Mercado<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/dolar-24062021\/\"><h2 class=\"content__title\">D\u00f3lar tem queda de 0,6%, a R$ 4,93, com PIB dos EUA e Selic no radar do mercado<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/7ef34026-whatsapp-image-2020-08-03-at-12.37.57-150x150.webp\" alt=\"Poliana Santos\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\"><span itemprop=\"author\">Poliana Santos<\/span><\/a><\/span><time datetime=\"2021-06-24T11:55:56-03:00\" itemprop=\"datePublished\">24\/06\/2021 11:55<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/160858"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=160858"}],"version-history":[{"count":3,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/160858\/revisions"}],"predecessor-version":[{"id":160941,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/160858\/revisions\/160941"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/148884"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=160858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=160858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=160858"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=160858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}