{"id":148075,"date":"2021-05-13T15:08:40","date_gmt":"2021-05-13T18:08:40","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=148075"},"modified":"2021-05-13T15:08:40","modified_gmt":"2021-05-13T18:08:40","slug":"lucro-liquido-bndes-1t21","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/","title":{"rendered":"BNDES tem lucro l\u00edquido de R$ 9,8 bi no 1T21, alta de 78%"},"content":{"rendered":"<p>O <a href=\"https:\/\/www.suno.com.br\/artigos\/bndes\/\">Banco Nacional de Desenvolvimento Econ\u00f4mico e Social (<strong>BNDES<\/strong>)<\/a> registrou <a href=\"https:\/\/www.suno.com.br\/artigos\/lucro-liquido\/\">lucro l\u00edquido<\/a> de R$ 9,8 bilh\u00f5es no primeiro trimestre deste ano, alta de 78% ante igual per\u00edodo de 2020, informou nesta quinta-feira (13) a institui\u00e7\u00e3o de fomento.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/4e3b1f5c-bndes_1103200718-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/4e3b1f5c-bndes_1103200718-800x450.webp\" width=\"800\" height=\"450\" alt=\"BNDES tem lucro l\u00edquido de R$ 9,8 bi no 1T21, alta de 78%\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">BNDES. Foto: Tomaz Silva\/Ag\u00eancia Brasil  Local: RJ<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-controle-gastos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Planilha-controle-de-gastos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t\tdata-promo-id=\"101751\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>De acordo com o BNDES, o resultado do primeiro trimestre do ano foi impulsionado pela venda de a\u00e7\u00f5es e pela intermedia\u00e7\u00e3o financeira.<\/p>\n<p>Os desembolsos para empr\u00e9stimos j\u00e1 aprovados somaram R$ 11,3 bilh\u00f5es nos tr\u00eas primeiros meses do ano, alta de 35% ante igual per\u00edodo de 2020. J\u00e1 as vendas de a\u00e7\u00f5es de grandes companhias somaram R$ 12,6 bilh\u00f5es, com destaques para os desinvestimentos das participa\u00e7\u00f5es na mineradora <a href=\"https:\/\/www.suno.com.br\/acoes\/vale3\/\">Vale (VALE3)<\/a> e na fabricante de papel e celulose <a href=\"https:\/\/www.suno.com.br\/acoes\/klbn4\/\">Klabin (KLBN11)<\/a>.<\/p>\n<p><a href=\"https:\/\/lp.suno.com.br\/suno-one\/\"><span style=\"font-weight: 400;\">Suno One: acesse gratuitamente eBooks, Minicursos, Artigos e Video Aulas sobre investimentos com um \u00fanico cadastro. Clique para saber mais!<\/span><\/a><\/p>\n<p>Com isso, a carteira de participa\u00e7\u00f5es societ\u00e1rias encerrou o primeiro trimestre avaliada em R$ 61,5 bilh\u00f5es, 21,1% abaixo do valor do fechamento do quarto trimestre de 2020.<\/p>\n<p>Al\u00e9m das vendas, a queda foi impactada pela &#8220;desvaloriza\u00e7\u00e3o dos investimentos em n\u00e3o coligadas, com destaque para <a href=\"https:\/\/www.suno.com.br\/acoes\/petr4\/\">Petrobras (PETR4)<\/a> e <a href=\"https:\/\/www.suno.com.br\/acoes\/elet3\/\">Eletrobras (ELET3)<\/a>&#8220;, informa nota divulgada pelo BNDES.<\/p>\n<p>O presidente do banco, Gustavo Montezano, destacou a sa\u00edda total do capital da Vale, incluindo as deb\u00eantures participativas da companhia. O executivo ressaltou que o banco continuou com a estrat\u00e9gica de se retirar &#8220;de posi\u00e7\u00f5es financeiras meramente especulativas&#8221;.<\/p>\n<p>&#8220;Continuamos com o reposicionamento da nossa carteira de a\u00e7\u00f5es&#8221;, afirmou Montezano, que classificou os resultados do primeiro trimestre de &#8220;robustos&#8221; e afirmou que s\u00e3o uma continuidade dos resultados anuais de 2020.<\/p>\n<p>O produto de intermedia\u00e7\u00e3o financeira atingiu R$ 4,4 bilh\u00f5es, aumento de 7,8% em compara\u00e7\u00e3o ao primeiro trimestre de 2020, segundo o banco de fomento. &#8220;A receita com opera\u00e7\u00f5es de cr\u00e9dito e repasses aumentou 10,8% em rela\u00e7\u00e3o ao primeiro trimestre de 2020, chegando a R$ 9,2 bilh\u00f5es&#8221;, diz a nota.<\/p>\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Saiba Mais<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/consorcio-aegea-blocos-1-e-4-leilao-da-cedae\/\">\n\t\t\tCons\u00f3rcio liderado por Aegea leva blocos 1 e 4 em leil\u00e3o da Cedae por R$ 15,4 bi\t\t<\/a>\n\t<\/div>\n\n\n<p>A inadimpl\u00eancia acima de 90 dias subiu de 0,01% da carteira, em 31 de dezembro de 2020, para 0,04% em 31 de mar\u00e7o de 2021, &#8220;ficando bem aqu\u00e9m da inadimpl\u00eancia do Sistema Financeiro Nacional (2,19% em 31 de mar\u00e7o de 2021)&#8221;, conforme a nota do BNDES.<\/p>\n<p>Ap\u00f3s adotar uma suspens\u00e3o das cobran\u00e7as de d\u00edvidas, como medida para mitigar a crise causada pela covid-19, o \u00edndice de renegocia\u00e7\u00e3o atingiu 51,85% da carteira bruta em 31 de mar\u00e7o de 2021. A medida de suspens\u00e3o tempor\u00e1ria das cobran\u00e7as alcan\u00e7ou 44,5% da carteira bruta.<\/p>\n<p>O lucro do primeiro trimestre foi beneficiado ainda pela revers\u00e3o de R$ 432 milh\u00f5es de provis\u00e3o para risco de cr\u00e9dito.<\/p>\n<p>&#8220;A revers\u00e3o decorre de recupera\u00e7\u00e3o de cr\u00e9ditos, principalmente por honra do Fundo de Garantia \u00e0 Exporta\u00e7\u00e3o (<strong>FGE<\/strong>), al\u00e9m da melhora da classifica\u00e7\u00e3o de risco de algumas empresas&#8221;, diz a nota do BNDES. No primeiro trimestre de 2020, o BNDES registrou provis\u00e3o de R$ 1,7 bilh\u00e3o, influenciada pela revis\u00e3o dos ratings dos setores mais afetados pela pandemia da covid-19.<\/p>\n<p>Com isso, o BNDES fechou o primeiro trimestre com ativo total de R$ 737,2 bilh\u00f5es em 31 de mar\u00e7o de 2021, diminui\u00e7\u00e3o de R$ 41,1 bilh\u00f5es (5,3%) no trimestre. &#8220;A redu\u00e7\u00e3o se deu, principalmente, devido ao pagamento antecipado de R$ 38 bilh\u00f5es ao Tesouro Nacional e \u00e0 desvaloriza\u00e7\u00e3o da carteira de participa\u00e7\u00f5es societ\u00e1rias em fun\u00e7\u00e3o de oscila\u00e7\u00f5es dos pap\u00e9is no mercado financeiro&#8221;, diz a nota.<\/p>\n<p>Ap\u00f3s a devolu\u00e7\u00e3o antecipada de R$ 38 bilh\u00f5es, a d\u00edvida do BNDES com a Uni\u00e3o ficou em R$ 153,9 bilh\u00f5es no encerramento do primeiro trimestre, uma queda de 21,2% em rela\u00e7\u00e3o \u00e0 posi\u00e7\u00e3o em 31 de dezembro de 2020. Al\u00e9m do pagamento antecipado, houve pagamentos ordin\u00e1rios de R$ 3,4 bilh\u00f5es.<\/p>\n<p>A posi\u00e7\u00e3o de Tesouraria do <strong>BNDES<\/strong> ficou em R$ 139,4 bilh\u00f5es, disse a diretora financeira, Bianca Nasser.<\/p>\n<p><em>(Com informa\u00e7\u00f5es do Estad\u00e3o Conte\u00fado)\u00a0<\/em><\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"106682\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>O Banco Nacional de Desenvolvimento Econ\u00f4mico e Social (BNDES) registrou lucro l\u00edquido de R$ 9,8 bilh\u00f5es no primeiro trimestre deste ano, alta de 78% ante igual per\u00edodo de 2020, informou nesta quinta-feira (13) a institui\u00e7\u00e3o de fomento. BNDES. Foto: Tomaz Silva\/Ag\u00eancia Brasil Local: RJ De acordo com o BNDES, o resultado do primeiro trimestre do [&hellip;]<\/p>\n","protected":false},"author":56,"featured_media":148085,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[757,455,529,595,676],"suno_strategy":[],"class_list":["post-148075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-bndes","tag-eletrobras-elet3-elet5-elet6","tag-klabin-klbn11-klbn3-klbn4","tag-petrobras-petr4","tag-vale-vale3"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BNDES tem lucro l\u00edquido de R$ 9,8 bi no 1T21, alta de 78%<\/title>\n<meta name=\"description\" content=\"Segundo o BNDES, o resultado foi impulsionado pela venda de a\u00e7\u00f5es e pela intermedia\u00e7\u00e3o financeira. Clique aqui para saber mais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BNDES tem lucro l\u00edquido de R$ 9,8 bi no 1T21, alta de 78%\" \/>\n<meta property=\"og:description\" content=\"Segundo o BNDES, o resultado foi impulsionado pela venda de a\u00e7\u00f5es e pela intermedia\u00e7\u00e3o financeira. Clique aqui para saber mais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/4e3b1f5c-bndes_1103200718.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rafaela La Regina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rafaela La Regina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/\"},\"author\":{\"name\":\"Rafaela La Regina\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/e672ca8cea627fe715fa29bca7da95e0\"},\"headline\":\"BNDES tem lucro l\u00edquido de R$ 9,8 bi no 1T21, alta de 78%\",\"datePublished\":\"2021-05-13T18:08:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/\"},\"wordCount\":675,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/4e3b1f5c-bndes_1103200718-jpg.webp\",\"keywords\":[\"BNDES\",\"Eletrobras (ELET3\/ELET5\/ELET6)\",\"Klabin (KLBN11\/KLBN3\/KLBN4)\",\"Petrobras (PETR4)\",\"Vale (VALE3)\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/\",\"name\":\"BNDES tem lucro l\u00edquido de R$ 9,8 bi no 1T21, alta de 78%\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/4e3b1f5c-bndes_1103200718-jpg.webp\",\"datePublished\":\"2021-05-13T18:08:40+00:00\",\"description\":\"Segundo o BNDES, o resultado foi impulsionado pela venda de a\u00e7\u00f5es e pela intermedia\u00e7\u00e3o financeira. Clique aqui para saber mais.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/4e3b1f5c-bndes_1103200718-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/4e3b1f5c-bndes_1103200718-jpg.webp\",\"width\":1024,\"height\":768,\"caption\":\"BNDES. Foto: Tomaz Silva\/Ag\u00eancia Brasil Local: RJ\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BNDES tem lucro l\u00edquido de R$ 9,8 bi no 1T21, alta de 78%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/e672ca8cea627fe715fa29bca7da95e0\",\"name\":\"Rafaela La Regina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d2c75a52d243deb93d0465fdcb21bd37?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d2c75a52d243deb93d0465fdcb21bd37?s=96&r=g\",\"caption\":\"Rafaela La Regina\"},\"description\":\"Estagi\u00e1ria no Suno Not\u00edcias. Escreve sobre economia, pol\u00edtica e neg\u00f3cios. Estuda Rela\u00e7\u00f5es Internacionais no IBMEC-SP.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/rafaela-la-regina\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BNDES tem lucro l\u00edquido de R$ 9,8 bi no 1T21, alta de 78%","description":"Segundo o BNDES, o resultado foi impulsionado pela venda de a\u00e7\u00f5es e pela intermedia\u00e7\u00e3o financeira. Clique aqui para saber mais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/","og_locale":"pt_BR","og_type":"article","og_title":"BNDES tem lucro l\u00edquido de R$ 9,8 bi no 1T21, alta de 78%","og_description":"Segundo o BNDES, o resultado foi impulsionado pela venda de a\u00e7\u00f5es e pela intermedia\u00e7\u00e3o financeira. Clique aqui para saber mais.","og_url":"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1024,"height":768,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/4e3b1f5c-bndes_1103200718.jpg","type":"image\/jpeg"}],"author":"Rafaela La Regina","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Rafaela La Regina","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/"},"author":{"name":"Rafaela La Regina","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/e672ca8cea627fe715fa29bca7da95e0"},"headline":"BNDES tem lucro l\u00edquido de R$ 9,8 bi no 1T21, alta de 78%","datePublished":"2021-05-13T18:08:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/"},"wordCount":675,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/4e3b1f5c-bndes_1103200718-jpg.webp","keywords":["BNDES","Eletrobras (ELET3\/ELET5\/ELET6)","Klabin (KLBN11\/KLBN3\/KLBN4)","Petrobras (PETR4)","Vale (VALE3)"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/","url":"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/","name":"BNDES tem lucro l\u00edquido de R$ 9,8 bi no 1T21, alta de 78%","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/4e3b1f5c-bndes_1103200718-jpg.webp","datePublished":"2021-05-13T18:08:40+00:00","description":"Segundo o BNDES, o resultado foi impulsionado pela venda de a\u00e7\u00f5es e pela intermedia\u00e7\u00e3o financeira. Clique aqui para saber mais.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/4e3b1f5c-bndes_1103200718-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/4e3b1f5c-bndes_1103200718-jpg.webp","width":1024,"height":768,"caption":"BNDES. Foto: Tomaz Silva\/Ag\u00eancia Brasil Local: RJ"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"BNDES tem lucro l\u00edquido de R$ 9,8 bi no 1T21, alta de 78%"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/e672ca8cea627fe715fa29bca7da95e0","name":"Rafaela La Regina","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d2c75a52d243deb93d0465fdcb21bd37?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d2c75a52d243deb93d0465fdcb21bd37?s=96&r=g","caption":"Rafaela La Regina"},"description":"Estagi\u00e1ria no Suno Not\u00edcias. Escreve sobre economia, pol\u00edtica e neg\u00f3cios. Estuda Rela\u00e7\u00f5es Internacionais no IBMEC-SP.","url":"https:\/\/www.suno.com.br\/noticias\/author\/rafaela-la-regina\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/05\/4e3b1f5c-bndes_1103200718-400x200.webp\" alt=\"BNDES tem lucro l\u00edquido de R$ 9,8 bi no 1T21, alta de 78%\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/lucro-liquido-bndes-1t21\/\"><h2 class=\"content__title\">BNDES tem lucro l\u00edquido de R$ 9,8 bi no 1T21, alta de 78%<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/rafaela-la-regina\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/secure.gravatar.com\/avatar\/d2c75a52d243deb93d0465fdcb21bd37?s=96&#038;r=g\" alt=\"Rafaela La Regina\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/rafaela-la-regina\/\"><span itemprop=\"author\">Rafaela La Regina<\/span><\/a><\/span><time datetime=\"2021-05-13T15:08:40-03:00\" itemprop=\"datePublished\">13\/05\/2021 15:08<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/148075"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=148075"}],"version-history":[{"count":3,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/148075\/revisions"}],"predecessor-version":[{"id":148144,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/148075\/revisions\/148144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/148085"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=148075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=148075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=148075"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=148075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}