{"id":145066,"date":"2021-05-05T17:39:28","date_gmt":"2021-05-05T20:39:28","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=145066"},"modified":"2021-05-29T20:28:09","modified_gmt":"2021-05-29T23:28:09","slug":"bcff11-maiores-altas-ifix-fecha-queda","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/","title":{"rendered":"BCFF11 fica entre as maiores altas, mas IFIX fecha em queda"},"content":{"rendered":"<p>O <b>IFIX<\/b>, \u00edndice de Fundos Imobili\u00e1rios da B3, fechou nesta quarta-feira (5), aos 2.855,05 pontos, apresentando uma leve queda de 0,041%.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/03\/4c14e6e8-chicago-1791002_1280-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/03\/4c14e6e8-chicago-1791002_1280-800x450.webp\" width=\"800\" height=\"450\" alt=\"BCFF11 fica entre as maiores altas, mas IFIX fecha em queda\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Foto: David Mark por Pixabay<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-controle-gastos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Planilha-controle-de-gastos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t\tdata-promo-id=\"101751\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>Com o resultado do <strong><a href=\"https:\/\/www.suno.com.br\/artigos\/ifix\/\">IFIX<\/a> hoje,<\/strong> o \u00edndice apresenta uma queda de 0,53% no ano. Vale destacar que em 2020 o indicador reportou uma queda de 11,79%.<\/p>\n<p>Al\u00e9m disso, durante o dia o mercado ficou atento aos <strong>VPSI11,<\/strong> que pagar\u00e1 R$ 0,013 por cota no dia 12 de maio, enquanto a o \u00faltimo dia de negocia\u00e7\u00e3o das cotas com direito ao rendimento foi ontem (4) e os proventos se referem ao m\u00eas de abril.<\/p>\n<p><a href=\"https:\/\/lp.suno.com.br\/suno-one\/\">Suno One: acesse gratuitamente eBooks, Minicursos, Artigos e V\u00eddeo Aulas sobre investimentos com um \u00fanico cadastro. Clique para saber mais!<\/a><\/p>\n<p>Os investidores tamb\u00e9m ficaram de olho no BTLG11, que assinou um compromisso de venda e compra de im\u00f3veis referente \u00e0 venda de quatro im\u00f3veis:<\/p>\n<ul>\n<li>Itamb\u00e9 S\u00e3o Paulo, localizado na capital paulista;<\/li>\n<li>Supermarket Rio de Janeiro, localizado na Estrada Rio D&#8217;Ouro<\/li>\n<li>Magna Vinhedo, localizado na cidade de Vinhedo<\/li>\n<li>Ceratti Vinhedo, tamb\u00e9m em Vinhedo.<\/li>\n<\/ul>\n<p>O fundo se comprometeu a vender os im\u00f3veis por R$ 168.881.601,80, que ser\u00e3o pagos em em tr\u00eas parcelas.<\/p>\n<p>A primeira parcela ser\u00e1 de R$ 43.770.864,38, a ser paga\u00a0 na data de fechamento da venda. A segunda tranche \u00e9 de R$ 82.412.222,64, a ser paga em agosto desse ano, ao passo que a terceira e \u00faltima parcela \u00e9 de R$ 42.698.514,78, e ser\u00e1 paga em janeiro do ano que vem.<\/p>\n<p>&#8220;Considerando o Pre\u00e7o de Venda e a Venda parcelada a receita do<br \/>\nFundo dever\u00e1 ser impactada positivamente em, aproximadamente, R$ 4,88 por cota conforme forem pagas as tr\u00eas parcelas&#8221;, destaca o <strong>BTLG11<\/strong>.<\/p>\n<h2>FIIs que pagar\u00e3o rendimentos na semana<\/h2>\n<p>Confira tamb\u00e9m os FIIs que pagar\u00e3o rendimentos durante esta semana:<\/p>\n<ul>\n<li><strong>BPFF11<\/strong>: R$ 0,57 por cota, no dia 7 de maio<\/li>\n<li><strong>BRCO11<\/strong>: R$ 0,54 por cota, no dia 7 de maio<\/li>\n<li><strong>HSML11<\/strong>: R$ 0,22 por cota, no dia 7 de maio<\/li>\n<li><strong>LVBI11<\/strong>: R$ 0,56 por cota, no dia 7 de maio<\/li>\n<li><strong>PVBI11<\/strong>: R$ 0,50 por cota, no dia 7 de maio<\/li>\n<\/ul>\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Veja tamb\u00e9m<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/ifix-fecha-em-queda-vilg11\/\">\n\t\t\tVILG11 fica entre maiores altas, mas IFIX fecha em queda\t\t<\/a>\n\t<\/div>\n\n\n<h2>Maiores altas e baixas do dia<\/h2>\n<p>Veja as maiores altas e baixas do dia no IFIX:<\/p>\n<h3>Maiores Altas do dia\u00a0no IFIX:<\/h3>\n<ul>\n<li><strong>HCTR11<\/strong>: +1,25%\/ R$ 143,30<\/li>\n<li><strong>TEPP11<\/strong>: +1,08% \/ R$ 84,00<\/li>\n<li><strong>XPPR11<\/strong>: + 1,02% \/R$ 66,34<\/li>\n<li><strong>BCFF11<\/strong>: +0,97% \/R$ 87,67<\/li>\n<li><strong>KNHY11<\/strong>: +0,97% \/R$ 113,30<\/li>\n<\/ul>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"106682\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<h3>Maiores Baixas do dia no IFIX:<\/h3>\n<ul>\n<li><strong>JSRE11<\/strong>: -2,27% \/ R$ 91,00<\/li>\n<li><strong>GTWR11<\/strong>: -1,98% \/ R$ 107,33<\/li>\n<li><b>RECT11<\/b>: -1,52% \/ R$ 80,26<\/li>\n<li><strong>QAGR11<\/strong>: -0,96% \/ R$ 53,52<\/li>\n<li><strong>PATL11<\/strong>: -0,79% \/ R$ 92,23<\/li>\n<\/ul>\n<h2>O que \u00e9 o IFIX<\/h2>\n<p>O <b>IFIX <\/b>\u00e9 um indicador criado pela <a href=\"https:\/\/www.suno.com.br\/artigos\/b3\/\"><strong>Bolsa de Valores de S\u00e3o Paulo (B3)<\/strong><\/a> que tem como objetivo a medi\u00e7\u00e3o da performance de uma carteira composta por cotas de <strong>Fundos Imobili\u00e1rios.<\/strong><\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-de-controle-de-investimentos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Controle-de-Investimentos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t\tdata-promo-id=\"75934\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>O IFIX, \u00edndice de Fundos Imobili\u00e1rios da B3, fechou nesta quarta-feira (5), aos 2.855,05 pontos, apresentando uma leve queda de 0,041%. Foto: David Mark por Pixabay Com o resultado do IFIX hoje, o \u00edndice apresenta uma queda de 0,53% no ano. Vale destacar que em 2020 o indicador reportou uma queda de 11,79%. Al\u00e9m disso, [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":136209,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[66,60],"tags":[105768,315,2689,105934],"suno_strategy":[],"class_list":["post-145066","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiis","category-mercado","tag-btlg11","tag-fundos-imobiliarios-fiis","tag-ifix","tag-vpsi11"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BCFF11 fica entre as maiores altas, mas IFIX fecha em queda<\/title>\n<meta name=\"description\" content=\"O IFIX fechou nesta quarta-feira (5), aos 2.855,05 pontos, apresentando uma leve queda de 0,041%. Clique aqui e saiba mais sobre o IFIX hoje!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BCFF11 fica entre as maiores altas, mas IFIX fecha em queda\" \/>\n<meta property=\"og:description\" content=\"O IFIX fechou nesta quarta-feira (5), aos 2.855,05 pontos, apresentando uma leve queda de 0,041%. Clique aqui e saiba mais sobre o IFIX hoje!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/03\/4c14e6e8-chicago-1791002_1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"787\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Laura Moutinho\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laura Moutinho\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/\"},\"author\":{\"name\":\"Laura Moutinho\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/3df0d2808748b74496efe5dbeaef2c72\"},\"headline\":\"BCFF11 fica entre as maiores altas, mas IFIX fecha em queda\",\"datePublished\":\"2021-05-05T20:39:28+00:00\",\"dateModified\":\"2021-05-29T23:28:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/\"},\"wordCount\":444,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/03\/4c14e6e8-chicago-1791002_1280-jpg.webp\",\"keywords\":[\"BTLG11\",\"Fundos Imobili\u00e1rios (FIIs)\",\"IFIX\",\"VPSI11\"],\"articleSection\":[\"FIIs\",\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/\",\"name\":\"BCFF11 fica entre as maiores altas, mas IFIX fecha em queda\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/03\/4c14e6e8-chicago-1791002_1280-jpg.webp\",\"datePublished\":\"2021-05-05T20:39:28+00:00\",\"dateModified\":\"2021-05-29T23:28:09+00:00\",\"description\":\"O IFIX fechou nesta quarta-feira (5), aos 2.855,05 pontos, apresentando uma leve queda de 0,041%. Clique aqui e saiba mais sobre o IFIX hoje!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/03\/4c14e6e8-chicago-1791002_1280-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/03\/4c14e6e8-chicago-1791002_1280-jpg.webp\",\"width\":1280,\"height\":787,\"caption\":\"Foto: David Mark por Pixabay\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FIIs\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/fiis\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BCFF11 fica entre as maiores altas, mas IFIX fecha em queda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/3df0d2808748b74496efe5dbeaef2c72\",\"name\":\"Laura Moutinho\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7571c7c8ca3a6fca5e41384ece5557ff?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7571c7c8ca3a6fca5e41384ece5557ff?s=96&r=g\",\"caption\":\"Laura Moutinho\"},\"description\":\"Estagi\u00e1ria na Suno Not\u00edcias, escreve not\u00edcias que afetam o mercado financeiro. Estuda administra\u00e7\u00e3o na Universidade Presbiteriana Mackenzie.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/laura-moutinho\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BCFF11 fica entre as maiores altas, mas IFIX fecha em queda","description":"O IFIX fechou nesta quarta-feira (5), aos 2.855,05 pontos, apresentando uma leve queda de 0,041%. Clique aqui e saiba mais sobre o IFIX hoje!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/","og_locale":"pt_BR","og_type":"article","og_title":"BCFF11 fica entre as maiores altas, mas IFIX fecha em queda","og_description":"O IFIX fechou nesta quarta-feira (5), aos 2.855,05 pontos, apresentando uma leve queda de 0,041%. Clique aqui e saiba mais sobre o IFIX hoje!","og_url":"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1280,"height":787,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/03\/4c14e6e8-chicago-1791002_1280.jpg","type":"image\/jpeg"}],"author":"Laura Moutinho","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Laura Moutinho","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/"},"author":{"name":"Laura Moutinho","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/3df0d2808748b74496efe5dbeaef2c72"},"headline":"BCFF11 fica entre as maiores altas, mas IFIX fecha em queda","datePublished":"2021-05-05T20:39:28+00:00","dateModified":"2021-05-29T23:28:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/"},"wordCount":444,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/03\/4c14e6e8-chicago-1791002_1280-jpg.webp","keywords":["BTLG11","Fundos Imobili\u00e1rios (FIIs)","IFIX","VPSI11"],"articleSection":["FIIs","Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/","url":"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/","name":"BCFF11 fica entre as maiores altas, mas IFIX fecha em queda","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/03\/4c14e6e8-chicago-1791002_1280-jpg.webp","datePublished":"2021-05-05T20:39:28+00:00","dateModified":"2021-05-29T23:28:09+00:00","description":"O IFIX fechou nesta quarta-feira (5), aos 2.855,05 pontos, apresentando uma leve queda de 0,041%. Clique aqui e saiba mais sobre o IFIX hoje!","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/03\/4c14e6e8-chicago-1791002_1280-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/03\/4c14e6e8-chicago-1791002_1280-jpg.webp","width":1280,"height":787,"caption":"Foto: David Mark por Pixabay"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"FIIs","item":"https:\/\/www.suno.com.br\/noticias\/fiis\/"},{"@type":"ListItem","position":3,"name":"BCFF11 fica entre as maiores altas, mas IFIX fecha em queda"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/3df0d2808748b74496efe5dbeaef2c72","name":"Laura Moutinho","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7571c7c8ca3a6fca5e41384ece5557ff?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7571c7c8ca3a6fca5e41384ece5557ff?s=96&r=g","caption":"Laura Moutinho"},"description":"Estagi\u00e1ria na Suno Not\u00edcias, escreve not\u00edcias que afetam o mercado financeiro. Estuda administra\u00e7\u00e3o na Universidade Presbiteriana Mackenzie.","url":"https:\/\/www.suno.com.br\/noticias\/author\/laura-moutinho\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/03\/4c14e6e8-chicago-1791002_1280-400x200.webp\" alt=\"BCFF11 fica entre as maiores altas, mas IFIX fecha em queda\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/fiis\/\">FIIs<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/bcff11-maiores-altas-ifix-fecha-queda\/\"><h2 class=\"content__title\">BCFF11 fica entre as maiores altas, mas IFIX fecha em queda<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/laura-moutinho\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/531ff69d-whatsapp-image-2020-08-03-at-14.54.38-150x150.webp\" alt=\"Laura Moutinho\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/laura-moutinho\/\"><span itemprop=\"author\">Laura Moutinho<\/span><\/a><\/span><time datetime=\"2021-05-05T17:39:28-03:00\" itemprop=\"datePublished\">05\/05\/2021 17:39<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/145066"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=145066"}],"version-history":[{"count":2,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/145066\/revisions"}],"predecessor-version":[{"id":145091,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/145066\/revisions\/145091"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/136209"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=145066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=145066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=145066"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=145066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}