{"id":119116,"date":"2021-02-05T09:44:41","date_gmt":"2021-02-05T12:44:41","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=119116"},"modified":"2021-02-05T09:44:41","modified_gmt":"2021-02-05T12:44:41","slug":"dolar-alta-5-44-05022021","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/","title":{"rendered":"D\u00f3lar opera em alta de 0,2%, negociado acima dos R$ 5,40"},"content":{"rendered":"<p>O <strong>d\u00f3lar<\/strong> opera em alta com o mercado atento a reuni\u00e3o que dever\u00e1 acontecer nesta sexta-feira (5) entre o mandat\u00e1rio Jair Bolsonaro e o presidente da Petrobras sobre os pre\u00e7os dos combust\u00edveis, pauta da greve dos caminhoneiros.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/02\/be22ae84-dolar-11042019-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/02\/be22ae84-dolar-11042019-jpg.webp\" width=\"800\" height=\"450\" alt=\"D\u00f3lar opera em alta de 0,2%, negociado acima dos R$ 5,40\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Por volta das 9h39, nesta sexta-feira (5), o d\u00f3lar tinha alta de de 0,26%, negociado a R$ 5,4461. <\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-como-analisar-uma-acao\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Mobile.jpg\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t\tdata-promo-id=\"378302\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='286'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>Por volta das 9h39, o d\u00f3lar tinha alta de de 0,26%, negociado a R$ 5,4461. Al\u00e9m da reuni\u00e3o, os investidores acompanham as <strong>bolsas mundiais<\/strong> hoje.<\/p>\n<p><a href=\"https:\/\/lp.suno.com.br\/suno-one\/\">Suno One: acesse gratuitamente eBooks, Minicursos, Artigos e Video Aulas sobre investimentos com um \u00fanico cadastro. Clique para saber mais!<\/a><\/p>\n<p>No cen\u00e1rio pol\u00edtico, a aten\u00e7\u00e3o dos investidores est\u00e1 voltada para os pre\u00e7os do <strong>combust\u00edveis<\/strong> e a<strong> greve dos caminhoneiros.<\/strong><\/p>\n<p>O presidente da Rep\u00fablica Jair Bolsonaro disse ter convocado ministros e o presidente da<a href=\"https:\/\/www.suno.com.br\/acoes\/petr4\/\"> Petrobras (PETR4)<\/a>, <a href=\"https:\/\/www.suno.com.br\/tudo-sobre\/roberto-castello-branco\/\">Roberto Castello Branco<\/a>, para explicarem a alta nos pre\u00e7os dos combust\u00edveis, motivo pelo qual os caminhoneiros realizaram uma paralisa\u00e7\u00e3o no in\u00edcio desta semana. A reuni\u00e3o dever\u00e1 acontecer nesta sexta-feira.<\/p>\n<p>&#8220;Convoquei todos os ministros e o presidente da Petrobras. Estava previsto que iriam dar um novo reajuste em cima do combust\u00edvel. \u00c9 justo ou n\u00e3o? \u00c9 isso que vamos conversar amanh\u00e3&#8221;, afirmou o presidente durante sua live semanal.<\/p>\n<p>&#8220;Ningu\u00e9m est\u00e1 interferindo na <strong>Petrobras<\/strong>, mas voc\u00ea tem que saber qual a composi\u00e7\u00e3o do pre\u00e7o final do diesel&#8221;, completou o presidente.<\/p>\n<h2>Mercado Internacional<\/h2>\n<p>J\u00e1 no cen\u00e1rio internacional, os principais indicadores devem acompanhar o relat\u00f3rio de emprego de janeiro da principal economia do mundo, os <strong>Estados Unidos<\/strong>. <a href=\"https:\/\/www.suno.com.br\/noticias\/pedidos-auxilio-desemprego-eua\/\">Os novos pedidos totalizaram 779 mil<\/a> na semana encerrada em 30 de janeiro, ante 812 mil na semana anterior, o que representa queda de 33 mil pedidos. As informa\u00e7\u00f5es foram divulgadas na \u00faltima quinta pelo Departamento do Trabalho.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-controle-gastos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Planilha-controle-de-gastos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t\tdata-promo-id=\"101751\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>Dessa forma, as <strong>bolsas mundiais<\/strong> operam em alta nesta manh\u00e3, confirmando a tend\u00eancia positiva de toda a semana.<\/p>\n<p>Confira o desempenho das principais bolsas mundiais por volta das 7h58:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.suno.com.br\/artigos\/sp-500\/\">S&amp;P 500 futuro<\/a>: +0,43%<\/li>\n<li><a href=\"https:\/\/www.suno.com.br\/artigos\/nasdaq\/\">Nasdaq futuro<\/a>: +0,32%<\/li>\n<li><a href=\"https:\/\/www.suno.com.br\/artigos\/dax-30\/\">DAX 30<\/a>: +0,22%<\/li>\n<li><a href=\"https:\/\/www.suno.com.br\/artigos\/ftse-100\/\">FTSE 100<\/a>: +0,14%<\/li>\n<li><a href=\"https:\/\/www.suno.com.br\/artigos\/euro-stoxx-50\/\">Euro Stoxx 50<\/a>: +0,52%<\/li>\n<li>SSE Composite: -0,16%<\/li>\n<li><a href=\"https:\/\/www.suno.com.br\/artigos\/nikkei-225\/\">Nikkei 225<\/a>: +1,54%<\/li>\n<\/ul>\n<h2>\u00daltima cota\u00e7\u00e3o do d\u00f3lar<\/h2>\n<p>Na \u00faltima sess\u00e3o, quinta-feira (4), o <strong>d\u00f3lar<\/strong> encerrou em alta de 1,47%, negociado a R$ 5,44.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-de-controle-de-investimentos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Controle-de-Investimentos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t\tdata-promo-id=\"75934\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>O d\u00f3lar opera em alta com o mercado atento a reuni\u00e3o que dever\u00e1 acontecer nesta sexta-feira (5) entre o mandat\u00e1rio Jair Bolsonaro e o presidente da Petrobras sobre os pre\u00e7os dos combust\u00edveis, pauta da greve dos caminhoneiros. Por volta das 9h39, nesta sexta-feira (5), o d\u00f3lar tinha alta de de 0,26%, negociado a R$ 5,4461. [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":119135,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[60],"tags":[326,793],"suno_strategy":[],"class_list":["post-119116","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado","tag-dolar","tag-estados-unidos-eua"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>D\u00f3lar opera em alta de 0,2%, negociado acima dos R$ 5,40<\/title>\n<meta name=\"description\" content=\"Por volta das 9h39, nesta sexta-feira (5), o d\u00f3lar tinha alta de de 0,26%, negociado a R$ 5,4461. Clique aqui e saiba mais\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00f3lar opera em alta de 0,2%, negociado acima dos R$ 5,40\" \/>\n<meta property=\"og:description\" content=\"Por volta das 9h39, nesta sexta-feira (5), o d\u00f3lar tinha alta de de 0,26%, negociado a R$ 5,4461. Clique aqui e saiba mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/02\/be22ae84-dolar-11042019.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"712\" \/>\n\t<meta property=\"og:image:height\" content=\"475\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Poliana Santos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Poliana Santos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/\"},\"author\":{\"name\":\"Poliana Santos\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda\"},\"headline\":\"D\u00f3lar opera em alta de 0,2%, negociado acima dos R$ 5,40\",\"datePublished\":\"2021-02-05T12:44:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/\"},\"wordCount\":370,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/02\/be22ae84-dolar-11042019-jpg.webp\",\"keywords\":[\"d\u00f3lar\",\"Estados Unidos (EUA)\"],\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/\",\"name\":\"D\u00f3lar opera em alta de 0,2%, negociado acima dos R$ 5,40\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/02\/be22ae84-dolar-11042019-jpg.webp\",\"datePublished\":\"2021-02-05T12:44:41+00:00\",\"description\":\"Por volta das 9h39, nesta sexta-feira (5), o d\u00f3lar tinha alta de de 0,26%, negociado a R$ 5,4461. Clique aqui e saiba mais\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/02\/be22ae84-dolar-11042019-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/02\/be22ae84-dolar-11042019-jpg.webp\",\"width\":712,\"height\":475,\"caption\":\"Por volta das 9h39, nesta sexta-feira (5), o d\u00f3lar tinha alta de de 0,26%, negociado a R$ 5,4461.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/mercado\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"D\u00f3lar opera em alta de 0,2%, negociado acima dos R$ 5,40\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda\",\"name\":\"Poliana Santos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g\",\"caption\":\"Poliana Santos\"},\"description\":\"Rep\u00f3rter no Suno Not\u00edcias, com cobertura em mercado financeiro, economia, finan\u00e7as pessoais, renda fixa e varejo. Jornalista formada pela Faculdade C\u00e1sper L\u00edbero e possui passagem na R\u00e1dio Gazeta AM com a produ\u00e7\u00e3o de conte\u00fado sobre economia, pol\u00edtica, sa\u00fade, moda e m\u00fasica. Possui certificado de conclus\u00e3o do curso de An\u00e1lise de Balan\u00e7os pela Funda\u00e7\u00e3o Bradesco, Agenda Brasil pela FAAP, Educa\u00e7\u00e3o Pol\u00edtica por Alexandre Garcia e do Tesouro Direto e Mercado de A\u00e7\u00f5es pela B3.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00f3lar opera em alta de 0,2%, negociado acima dos R$ 5,40","description":"Por volta das 9h39, nesta sexta-feira (5), o d\u00f3lar tinha alta de de 0,26%, negociado a R$ 5,4461. Clique aqui e saiba mais","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/","og_locale":"pt_BR","og_type":"article","og_title":"D\u00f3lar opera em alta de 0,2%, negociado acima dos R$ 5,40","og_description":"Por volta das 9h39, nesta sexta-feira (5), o d\u00f3lar tinha alta de de 0,26%, negociado a R$ 5,4461. Clique aqui e saiba mais","og_url":"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":712,"height":475,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/02\/be22ae84-dolar-11042019.jpg","type":"image\/jpeg"}],"author":"Poliana Santos","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Poliana Santos","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/"},"author":{"name":"Poliana Santos","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda"},"headline":"D\u00f3lar opera em alta de 0,2%, negociado acima dos R$ 5,40","datePublished":"2021-02-05T12:44:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/"},"wordCount":370,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/02\/be22ae84-dolar-11042019-jpg.webp","keywords":["d\u00f3lar","Estados Unidos (EUA)"],"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/","url":"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/","name":"D\u00f3lar opera em alta de 0,2%, negociado acima dos R$ 5,40","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/02\/be22ae84-dolar-11042019-jpg.webp","datePublished":"2021-02-05T12:44:41+00:00","description":"Por volta das 9h39, nesta sexta-feira (5), o d\u00f3lar tinha alta de de 0,26%, negociado a R$ 5,4461. Clique aqui e saiba mais","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/02\/be22ae84-dolar-11042019-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/02\/be22ae84-dolar-11042019-jpg.webp","width":712,"height":475,"caption":"Por volta das 9h39, nesta sexta-feira (5), o d\u00f3lar tinha alta de de 0,26%, negociado a R$ 5,4461."},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/www.suno.com.br\/noticias\/mercado\/"},{"@type":"ListItem","position":3,"name":"D\u00f3lar opera em alta de 0,2%, negociado acima dos R$ 5,40"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda","name":"Poliana Santos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g","caption":"Poliana Santos"},"description":"Rep\u00f3rter no Suno Not\u00edcias, com cobertura em mercado financeiro, economia, finan\u00e7as pessoais, renda fixa e varejo. Jornalista formada pela Faculdade C\u00e1sper L\u00edbero e possui passagem na R\u00e1dio Gazeta AM com a produ\u00e7\u00e3o de conte\u00fado sobre economia, pol\u00edtica, sa\u00fade, moda e m\u00fasica. Possui certificado de conclus\u00e3o do curso de An\u00e1lise de Balan\u00e7os pela Funda\u00e7\u00e3o Bradesco, Agenda Brasil pela FAAP, Educa\u00e7\u00e3o Pol\u00edtica por Alexandre Garcia e do Tesouro Direto e Mercado de A\u00e7\u00f5es pela B3.","url":"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/02\/be22ae84-dolar-11042019-400x200.webp\" alt=\"D\u00f3lar opera em alta de 0,2%, negociado acima dos R$ 5,40\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/mercado\/\">Mercado<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/dolar-alta-5-44-05022021\/\"><h2 class=\"content__title\">D\u00f3lar opera em alta de 0,2%, negociado acima dos R$ 5,40<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/7ef34026-whatsapp-image-2020-08-03-at-12.37.57-150x150.webp\" alt=\"Poliana Santos\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\"><span itemprop=\"author\">Poliana Santos<\/span><\/a><\/span><time datetime=\"2021-02-05T09:44:41-03:00\" itemprop=\"datePublished\">05\/02\/2021 09:44<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/119116"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=119116"}],"version-history":[{"count":0,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/119116\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/119135"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=119116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=119116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=119116"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=119116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}