{"id":113613,"date":"2021-01-15T09:00:02","date_gmt":"2021-01-15T12:00:02","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=113613"},"modified":"2021-06-14T00:28:33","modified_gmt":"2021-06-14T03:28:33","slug":"agenda-do-dia-estimulos-resultados-sabesp-15012021","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/","title":{"rendered":"Agenda do Dia: pacote de est\u00edmulos, resultados trimestrais e Sabesp (SBSP3)"},"content":{"rendered":"<p>A <strong>Agenda do Dia<\/strong> desta sexta-feira (15) destaca os assuntos que devem movimentar o mercado no \u00fatimo dia desta semana. Os investidores continuam atentos ao avan\u00e7o da pandemia do <a href=\"https:\/\/www.suno.com.br\/noticias\/search\/coronav%C3%ADrus\">novo coronav\u00edrus (Covid-19)<\/a> e como os pa\u00edses far\u00e3o para enfrentar uma nova onda de infec\u00e7\u00f5es &#8212; nos Estados Unidos, Joe Biden quer que seja com US$ 1,9 trilh\u00e3o em est\u00edmulos.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/8d78130b-joe-biden-irlanda-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/8d78130b-joe-biden-irlanda-800x450.webp\" width=\"800\" height=\"450\" alt=\"Agenda do Dia: pacote de est\u00edmulos, resultados trimestrais e Sabesp (SBSP3)\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">A Agenda do Dia desta sexta-feira (15) destaca os assuntos que devem movimentar o mercado no \u00fatimo dia desta semana. <\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-controle-gastos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Planilha-controle-de-gastos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t\tdata-promo-id=\"101751\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>Os resultados corporativos estadunidenses tamb\u00e9m voltam a mexer com os mercados. No front interno, chama aten\u00e7\u00e3o a inten\u00e7\u00e3o de privatiza\u00e7\u00e3o da <a href=\"https:\/\/www.suno.com.br\/acoes\/sbsp3\/\"><strong>Sabesp<\/strong> (SBSP3)<\/a> pelo governo de S\u00e3o Paulo em 2021. Confira os destaques da Agenda do Dia:<\/p>\n<h2>Pacote trilion\u00e1rio de Biden \u00e9 destaque da Agenda do Dia<\/h2>\n<p>Em an\u00fancio realizado na noite da \u00faltima quinta-feira (14), o presidente eleito dos Estados Unidos, <strong>Joe Biden<\/strong>, apresentou um plano de US$ 1,9 trilh\u00e3o em est\u00edmulos \u00e0 economia e sustento em meio \u00e0 crise do coronav\u00edrus.<\/p>\n<p><a href=\"https:\/\/lp.suno.com.br\/suno-one\/\"><span style=\"font-weight: 400;\">Suno One: acesse gratuitamente eBooks, Minicursos, Artigos e Video Aulas sobre investimentos com um \u00fanico cadastro. Clique para saber mais!<\/span><\/a><\/p>\n<p>O plano conta com US$ 400 bilh\u00f5es para conter o avan\u00e7o da pandemia do <a href=\"https:\/\/www.suno.com.br\/noticias\/search\/coronav%C3%ADrus\">novo <strong>coronav\u00edrus<\/strong> (Covid-19)<\/a> e acelerar a abertura da economia, assim como US$ 1.400 em pagamentos adicionais por pessoa na maioria das fam\u00edlias do pa\u00eds, como forma de um est\u00edmulo direto. Ele tamb\u00e9m prop\u00f5e um seguro-desemprego de US$ 400 por semana at\u00e9 setembro, f\u00e9rias remuneradas ampliadas e aumento no cr\u00e9dito tribut\u00e1rio infantil.<\/p>\n<p>\u201cN\u00e3o \u00e9 dif\u00edcil ver que estamos em uma crise econ\u00f4mica que ocorre uma vez em v\u00e1rias gera\u00e7\u00f5es\u201d, disse Biden ao revelar seu plano na noite da \u00faltima quinta-feira (14). \u201cTemos que agir e temos que agir agora.\u201d<\/p>\n<h2>Resultados trimestrais<\/h2>\n<p>A temporada de resultados corporativos do quarto trimestre de 2020 j\u00e1 foi iniciada nos <strong>Estados Unidos<\/strong>. \u00c9 esperado que<strong> J.P. Morgan<\/strong> e <strong>Citigroup<\/strong> apresentem seus n\u00fameros nesta sexta-feira, apresentando o balan\u00e7o do per\u00edodo entre outubro e dezembro, al\u00e9m do acumulado de 2020.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-como-analisar-uma-acao\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Mobile.jpg\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t\tdata-promo-id=\"378302\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='286'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>As institui\u00e7\u00f5es financeiras tradicionalmente s\u00e3o algumas das primeiras a apresentarem seus n\u00fameros, dando um panorama sobre a tend\u00eancia da temporada de resultados e acerca do andamento da <strong>economia<\/strong>, sobretudo no que se refere \u00e0 concess\u00e3o de cr\u00e9dito e provis\u00f5es realizadas.<\/p>\n<h2>Agenda do Dia destaca poss\u00edvel privatiza\u00e7\u00e3o da Sabesp<\/h2>\n<p>Em meio \u00e0 queda da arrecada\u00e7\u00e3o tribut\u00e1ria causada pela pandemia, o governo de S\u00e3o Paulo estaria buscando formas de arrecadar at\u00e9 R$ 8 bilh\u00f5es em recursos. Segundo o jornal <em>Folha de S. Paulo<\/em>, entre as possibilidades para o governo est\u00e1 a venda da Sabesp.<\/p>\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Leia tamb\u00e9m<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/joe-biden-pacote-alivio-19-tri\/\">\n\t\t\tJoe Biden vai propor pacote de al\u00edvio de US$ 1,9 tri\t\t<\/a>\n\t<\/div>\n\n\n<p>O governador Jo\u00e3o Doria, governador do estado, est\u00e1 planejando, segundo fontes escutadas pelo jornal, contratar em breve estudos para analisar a <a href=\"https:\/\/www.suno.com.br\/artigos\/privatizacao\/\"><strong>privatiza\u00e7\u00e3o<\/strong><\/a>\u00a0da Sabesp ou, pelo menos, a aliena\u00e7\u00e3o de a\u00e7\u00f5es ou a\u00a0<a href=\"https:\/\/www.suno.com.br\/artigos\/capitalizacao-de-mercado\/\">capitaliza\u00e7\u00e3o<\/a>\u00a0da estatal.<\/p>\n<h2>PIB do Reino Unido recua<\/h2>\n<p>De acordo com informa\u00e7\u00f5es preliminares divulgadas nesta manh\u00e3, o <a href=\"https:\/\/www.suno.com.br\/artigos\/pib-produto-interno-bruto\/\">Produto Interno Bruto (<strong>PIB<\/strong>)<\/a> do<strong> Reino Unido<\/strong> caiu 2,6% em novembro, quebrando a sequ\u00eancia de seis meses consecutivos de alta. O pa\u00eds \u00e9 o mais castigado pela pandemia, com quase 90 mil mortos.<\/p>\n<p>Foi estabelecido um novo lockdown para a conten\u00e7\u00e3o da dissemina\u00e7\u00e3o do v\u00edrus, determinado pelo primeiro-ministro Boris Johnson. S\u00f3 \u00e9 aconselh\u00e1vel sair de casa para atividades essenciais e praticar exerc\u00edcios. Para especialistas, as novas restri\u00e7\u00f5es podem trazer impactos \u00e0 <strong>economia<\/strong> em 2021, ap\u00f3s 2020 ter certamente fechado no vermelho.<\/p>\n<p>A <strong>Agenda do Dia<\/strong> tamb\u00e9m destaca, no \u00e2mbito interno, a divulga\u00e7\u00e3o do \u00edndice IGP-10 mensal de janeiro pela Funda\u00e7\u00e3o Getulio Vargas (FGV). Al\u00e9m disso, tamb\u00e9m ser\u00e3o apresentados os resultados das vendas no varejo de novembro &#8212; \u00e9 esperado um crescimento de mensal de 0,4% e anual de 4,9%.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-de-controle-de-investimentos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Controle-de-Investimentos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t\tdata-promo-id=\"75934\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>A Agenda do Dia desta sexta-feira (15) destaca os assuntos que devem movimentar o mercado no \u00fatimo dia desta semana. Os investidores continuam atentos ao avan\u00e7o da pandemia do novo coronav\u00edrus (Covid-19) e como os pa\u00edses far\u00e3o para enfrentar uma nova onda de infec\u00e7\u00f5es &#8212; nos Estados Unidos, Joe Biden quer que seja com US$ [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":113625,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[60],"tags":[1980,2487,793,73481,2748,807,621,12552],"suno_strategy":[],"class_list":["post-113613","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado","tag-agenda-do-dia","tag-coronavirus","tag-estados-unidos-eua","tag-joe-biden","tag-pandemia","tag-produto-interno-bruto-pib","tag-sabesp","tag-sbsp3"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Agenda do Dia: pacote de est\u00edmulos, resultados trimestrais e Sabesp<\/title>\n<meta name=\"description\" content=\"A Agenda do Dia desta sexta-feira (15) destaca os assuntos que devem movimentar o mercado no \u00fatimo dia desta semana. Saiba mais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agenda do Dia: pacote de est\u00edmulos, resultados trimestrais e Sabesp\" \/>\n<meta property=\"og:description\" content=\"A Agenda do Dia desta sexta-feira (15) destaca os assuntos que devem movimentar o mercado no \u00fatimo dia desta semana. Saiba mais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/8d78130b-joe-biden-irlanda.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"773\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jader Lazarini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jader Lazarini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/\"},\"author\":{\"name\":\"Jader Lazarini\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/918d79de1f0281f01599b93f9ea6e23f\"},\"headline\":\"Agenda do Dia: pacote de est\u00edmulos, resultados trimestrais e Sabesp (SBSP3)\",\"datePublished\":\"2021-01-15T12:00:02+00:00\",\"dateModified\":\"2021-06-14T03:28:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/\"},\"wordCount\":663,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/8d78130b-joe-biden-irlanda-jpg.webp\",\"keywords\":[\"agenda do dia\",\"coronav\u00edrus\",\"Estados Unidos (EUA)\",\"Joe Biden\",\"pandemia\",\"Produto Interno Bruto (PIB)\",\"Sabesp\",\"SBSP3\"],\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/\",\"name\":\"Agenda do Dia: pacote de est\u00edmulos, resultados trimestrais e Sabesp\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/8d78130b-joe-biden-irlanda-jpg.webp\",\"datePublished\":\"2021-01-15T12:00:02+00:00\",\"dateModified\":\"2021-06-14T03:28:33+00:00\",\"description\":\"A Agenda do Dia desta sexta-feira (15) destaca os assuntos que devem movimentar o mercado no \u00fatimo dia desta semana. Saiba mais.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/8d78130b-joe-biden-irlanda-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/8d78130b-joe-biden-irlanda-jpg.webp\",\"width\":1160,\"height\":773,\"caption\":\"A Agenda do Dia desta sexta-feira (15) destaca os assuntos que devem movimentar o mercado no \u00fatimo dia desta semana.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/mercado\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Agenda do Dia: pacote de est\u00edmulos, resultados trimestrais e Sabesp (SBSP3)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/918d79de1f0281f01599b93f9ea6e23f\",\"name\":\"Jader Lazarini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3c1ad8caa51589841baeb923fcddea97?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3c1ad8caa51589841baeb923fcddea97?s=96&r=g\",\"caption\":\"Jader Lazarini\"},\"description\":\"Jader Lazarini escreve sobre investimentos, finan\u00e7as, economia e neg\u00f3cios. \u00c9 bacharel em Rela\u00e7\u00f5es Internacionais e analista CNPI (2619).\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/jader-lazarini\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Agenda do Dia: pacote de est\u00edmulos, resultados trimestrais e Sabesp","description":"A Agenda do Dia desta sexta-feira (15) destaca os assuntos que devem movimentar o mercado no \u00fatimo dia desta semana. Saiba mais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/","og_locale":"pt_BR","og_type":"article","og_title":"Agenda do Dia: pacote de est\u00edmulos, resultados trimestrais e Sabesp","og_description":"A Agenda do Dia desta sexta-feira (15) destaca os assuntos que devem movimentar o mercado no \u00fatimo dia desta semana. Saiba mais.","og_url":"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":1160,"height":773,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/8d78130b-joe-biden-irlanda.jpg","type":"image\/jpeg"}],"author":"Jader Lazarini","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Jader Lazarini","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/"},"author":{"name":"Jader Lazarini","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/918d79de1f0281f01599b93f9ea6e23f"},"headline":"Agenda do Dia: pacote de est\u00edmulos, resultados trimestrais e Sabesp (SBSP3)","datePublished":"2021-01-15T12:00:02+00:00","dateModified":"2021-06-14T03:28:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/"},"wordCount":663,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/8d78130b-joe-biden-irlanda-jpg.webp","keywords":["agenda do dia","coronav\u00edrus","Estados Unidos (EUA)","Joe Biden","pandemia","Produto Interno Bruto (PIB)","Sabesp","SBSP3"],"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/","url":"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/","name":"Agenda do Dia: pacote de est\u00edmulos, resultados trimestrais e Sabesp","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/8d78130b-joe-biden-irlanda-jpg.webp","datePublished":"2021-01-15T12:00:02+00:00","dateModified":"2021-06-14T03:28:33+00:00","description":"A Agenda do Dia desta sexta-feira (15) destaca os assuntos que devem movimentar o mercado no \u00fatimo dia desta semana. Saiba mais.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/8d78130b-joe-biden-irlanda-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/8d78130b-joe-biden-irlanda-jpg.webp","width":1160,"height":773,"caption":"A Agenda do Dia desta sexta-feira (15) destaca os assuntos que devem movimentar o mercado no \u00fatimo dia desta semana."},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/www.suno.com.br\/noticias\/mercado\/"},{"@type":"ListItem","position":3,"name":"Agenda do Dia: pacote de est\u00edmulos, resultados trimestrais e Sabesp (SBSP3)"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/918d79de1f0281f01599b93f9ea6e23f","name":"Jader Lazarini","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3c1ad8caa51589841baeb923fcddea97?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3c1ad8caa51589841baeb923fcddea97?s=96&r=g","caption":"Jader Lazarini"},"description":"Jader Lazarini escreve sobre investimentos, finan\u00e7as, economia e neg\u00f3cios. \u00c9 bacharel em Rela\u00e7\u00f5es Internacionais e analista CNPI (2619).","url":"https:\/\/www.suno.com.br\/noticias\/author\/jader-lazarini\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/8d78130b-joe-biden-irlanda-400x200.webp\" alt=\"Agenda do Dia: pacote de est\u00edmulos, resultados trimestrais e Sabesp (SBSP3)\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/mercado\/\">Mercado<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/agenda-do-dia-estimulos-resultados-sabesp-15012021\/\"><h2 class=\"content__title\">Agenda do Dia: pacote de est\u00edmulos, resultados trimestrais e Sabesp (SBSP3)<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/jader-lazarini\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/178e6598-foto-perfil-2-150x150.jpg\" alt=\"Jader Lazarini\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/jader-lazarini\/\"><span itemprop=\"author\">Jader Lazarini<\/span><\/a><\/span><time datetime=\"2021-01-15T09:00:02-03:00\" itemprop=\"datePublished\">15\/01\/2021 09:00<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/113613"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=113613"}],"version-history":[{"count":1,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/113613\/revisions"}],"predecessor-version":[{"id":156735,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/113613\/revisions\/156735"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/113625"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=113613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=113613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=113613"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=113613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}