{"id":112653,"date":"2021-01-12T11:56:08","date_gmt":"2021-01-12T14:56:08","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=112653"},"modified":"2021-06-01T22:15:11","modified_gmt":"2021-06-02T01:15:11","slug":"ultrapar-ugpa3-ataque-hacker-empresas","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/","title":{"rendered":"Ultrapar (UGPA3) sofre ataque hacker e opera em conting\u00eancia"},"content":{"rendered":"<p>A <a href=\"https:\/\/www.suno.com.br\/acoes\/ugpa3\/\"><strong>Ultrapar<\/strong> (UGPA3)<\/a> comunicou ao mercado que sofreu ontem um ataque hacker em seu ambiente de tecnologia de informa\u00e7\u00e3o. A companhia informou que &#8220;preventivamente interrompeu alguns sistemas&#8221;.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/bed53c65-hacker-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/bed53c65-hacker-jpg.webp\" width=\"800\" height=\"450\" alt=\"Ultrapar (UGPA3) sofre ataque hacker e opera em conting\u00eancia\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Ultrapar (UGPA3) sofre ataque hacker e opera em conting\u00eancia  <\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-controle-gastos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Planilha-controle-de-gastos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t\tdata-promo-id=\"101751\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>Com a interrup\u00e7\u00e3o, as opera\u00e7\u00f5es das subsidi\u00e1rias da Ultrapar foram parcialmente afetadas, conforme informa o<a href=\"https:\/\/www.suno.com.br\/artigos\/fato-relevante\/\" target=\"_blank\" rel=\"noopener noreferrer\"> fato relevante<\/a> da empresa. Dessa forma, a companhia est\u00e1 operando em <strong>regime<\/strong> de <strong>conting\u00eancia<\/strong> como modo de minimizar eventuais impactos.<\/p>\n<p><a href=\"https:\/\/lp.suno.com.br\/suno-one\/\">Suno One: acesse gratuitamente eBooks, Minicursos, Artigos e Video Aulas sobre investimentos com um \u00fanico cadastro. Clique para saber mais!<\/a><\/p>\n<p>&#8220;A Ultrapar est\u00e1 avaliando a extens\u00e3o desse incidente e atuando para mitigar seus efeitos empreendendo todos os esfor\u00e7os para normalizar suas opera\u00e7\u00f5es&#8221;, informou o documento.<\/p>\n<h2>Ataque hacker contra empresas brasileiras<\/h2>\n<p>Os ataques hackers contra empresas brasileiras t\u00eam sido mais reportados ao longo dos \u00faltimos meses. S\u00f3 no ano passado, empresas como <strong>Natura<\/strong>, <strong>Catho<\/strong>, <a href=\"https:\/\/www.suno.com.br\/acoes\/brkm5\/\"><strong>Braskem<\/strong> (BRKM5)<\/a>,<a href=\"https:\/\/www.suno.com.br\/acoes\/alsc3\/\"><strong> Aliansce Sonae<\/strong> (ALSC3)<\/a> e <a href=\"https:\/\/www.suno.com.br\/acoes\/embr3\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Embraer<\/strong> (EMBR3)<\/a> informaram que foram v\u00edtimas de ataques cibern\u00e9ticos.<\/p>\n<p>Segundo o levantamento realizado pela companhia de <strong>ciberseguran\u00e7a<\/strong> russa Kaspersky, o n\u00famero de ataques contra empresas no Brasil disparou no ano passado. O Pa\u00eds foi alvo de mais de 60% dos <strong>ataques hackers<\/strong> identificados na Am\u00e9rica Latina.<\/p>\n<p>A Aliansce Sonae foi atingida por <strong>ataques cibern\u00e9ticos<\/strong> em maio. Segundo a administradora de shoppings3, a invas\u00e3o n\u00e3o teve impacto relevante sobre as opera\u00e7\u00f5es.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-como-analisar-uma-acao\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Mobile.jpg\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t\tdata-promo-id=\"378302\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='286'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>J\u00e1 em meados de junho, a <strong>Avon<\/strong>, subsidi\u00e1ria do grupo <a href=\"https:\/\/www.suno.com.br\/acoes\/ntco3\/\">Natura &amp;Co. (NTCO3)<\/a> informou ao mercado que havia sofrido um <strong>incidente cibern\u00e9tico<\/strong> em seu ambiente de tecnologia da informa\u00e7\u00e3o, fazendo com que suas opera\u00e7\u00f5es fossem impactadas.<\/p>\n<p>No mesmo m\u00eas, a <strong>Catho<\/strong>, empresa de classificados de empregos, afirmou aos seus clientes que uma parte de sua base de dados foi invadida. Apesar do <strong>ataque hacker<\/strong>, a Catho destacou que dados de pagamento, bem como curr\u00edculos de seus usu\u00e1rios n\u00e3o foram expostos.<\/p>\n<p>Em outubro, a <strong>Braskem<\/strong> sofreu uma invas\u00e3o, ap\u00f3s a identifica\u00e7\u00e3o do ataque a empresa,. Como medida de precau\u00e7\u00e3o, interrompeu o acesso a alguns dos seus servidores o que fez com que as opera\u00e7\u00f5es fossem impactadas.<\/p>\n<p>J\u00e1 no m\u00eas passado, a Embraer informou ao mercado que os hackers, que invadiram os sistemas da companhia, come\u00e7aram a vazar os dados na internet ap\u00f3s a fabricante de aeronaves ter se recusado a negociar o pagamento aos criminosos.<\/p>\n<h2>Empresas do setor el\u00e9trico tamb\u00e9m s\u00e3o alvos de ataques cibern\u00e9ticos<\/h2>\n<p>As companhias do segmento energ\u00e9tico acabam sendo alvos preferenciais dos criminosos em todo o mundo por serem considerados servi\u00e7os essenciais. Dessa forma, espera-se que haja maior chance de pagamentos de resgates, cobrados em criptomoedas, segundo o levantamento da Kaspersky.<\/p>\n<p>Por aqui, grandes empresas do setor el\u00e9trico tamb\u00e9m foram atingidas por esse tipo de ataque cibern\u00e9tico, como as dom\u00e9sticas <a href=\"https:\/\/www.suno.com.br\/acoes\/engi11\/\">Energisa (ENGI11)<\/a>, <a href=\"https:\/\/www.suno.com.br\/acoes\/ligt3\/\">Light S.A (LIGT3)<\/a> e <a href=\"https:\/\/www.suno.com.br\/acoes\/cpfe3\/\"> CPFL Energia (CPFE3)<\/a> e as europeias <a href=\"https:\/\/www.suno.com.br\/acoes\/enbr3\/\">EDP Brasil (ENBR3)<\/a> e Enel.<\/p>\n<p>A <strong>Energisa<\/strong> teve seus sistemas invadidos em abril, os criminosos pediram R$ 5 milh\u00f5es de recompensa em Bitcoin, segundo o site The Hack. A empresa confirmou a invas\u00e3o mas n\u00e3o comentou sobre o pedido de resgate.<\/p>\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Veja Tamb\u00e9m<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/ataques-hackers-empresas-aumentam-brasil\/\">\n\t\t\tAtaques hackers contra empresas no Brasil aumentam com pandemia\t\t<\/a>\n\t<\/div>\n\n\n<p>J\u00e1 a <strong>Light<\/strong> foi v\u00edtima em junho de um ataque de v\u00edrus. Os hackers invadiram o sistema e enviaram um v\u00edrus que criptografava todos os arquivos do sistema Windows. Os criminosos pediram um resgate de US$ 7 milh\u00f5es, que deveriam ser pagos em criptomoedas, segundo a revista &#8220;Veja&#8221;. A empresa confirmou o ataque mas n\u00e3o comentou sobre o pedido de resgaste.<\/p>\n<p>No mesmo m\u00eas, os cibercriminosos que operam o <em>ransoware Maze<\/em> publicaram em seu site informa\u00e7\u00f5es indicando que invadiram a empresa de distribui\u00e7\u00e3o de energia <strong>CPFL<\/strong>.<\/p>\n<p>N\u00e3o somente empresas no Brasil, mas \u00f3rg\u00e3os p\u00fablicos como o<strong> Superior Tribunal de Justi\u00e7a<\/strong> (STF) tamb\u00e9m foram v\u00edtimas de invas\u00e3o de hackers. O ataque, que aconteceu em novembro, resultou na interrup\u00e7\u00e3o de diversos julgamentos e suspens\u00e3o de prazos processuais.<\/p>\n<p>Ap\u00f3s a not\u00edcia, por volta das 11h50, as a\u00e7\u00f5es da <strong>Ultrapar<\/strong> ca\u00edam a 0,92%, negociadas a R$ 23,57. Por sua vez, o <a href=\"https:\/\/www.suno.com.br\/artigos\/ibovespa\/\">Ibovespa<\/a> tinha alta de 0,22%, a 123.441,28 pontos.<\/p>\n<p><span style=\"font-weight: 400;\">\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-de-controle-de-investimentos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Controle-de-Investimentos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t\tdata-promo-id=\"75934\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Ultrapar (UGPA3) comunicou ao mercado que sofreu ontem um ataque hacker em seu ambiente de tecnologia de informa\u00e7\u00e3o. A companhia informou que &#8220;preventivamente interrompeu alguns sistemas&#8221;. Ultrapar (UGPA3) sofre ataque hacker e opera em conting\u00eancia Com a interrup\u00e7\u00e3o, as opera\u00e7\u00f5es das subsidi\u00e1rias da Ultrapar foram parcialmente afetadas, conforme informa o fato relevante da empresa. [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":112674,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[105312,671],"suno_strategy":[],"class_list":["post-112653","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-ataques-ciberneticos","tag-ultrapar-ugpa3"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ultrapar (UGPA3) sofre ataque hacker e opera em conting\u00eancia<\/title>\n<meta name=\"description\" content=\"A Ultrapar (UGPA3) comunicou ao mercado que sofreu ontem um ataque hacker em seu ambiente de tecnologia de informa\u00e7\u00e3o. Clique aqui\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ultrapar (UGPA3) sofre ataque hacker e opera em conting\u00eancia\" \/>\n<meta property=\"og:description\" content=\"A Ultrapar (UGPA3) comunicou ao mercado que sofreu ontem um ataque hacker em seu ambiente de tecnologia de informa\u00e7\u00e3o. Clique aqui\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/bed53c65-hacker.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Poliana Santos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Poliana Santos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/\"},\"author\":{\"name\":\"Poliana Santos\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda\"},\"headline\":\"Ultrapar (UGPA3) sofre ataque hacker e opera em conting\u00eancia\",\"datePublished\":\"2021-01-12T14:56:08+00:00\",\"dateModified\":\"2021-06-02T01:15:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/\"},\"wordCount\":744,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/bed53c65-hacker-jpg.webp\",\"keywords\":[\"ataques cibern\u00e9ticos\",\"Ultrapar (UGPA3)\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/\",\"name\":\"Ultrapar (UGPA3) sofre ataque hacker e opera em conting\u00eancia\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/bed53c65-hacker-jpg.webp\",\"datePublished\":\"2021-01-12T14:56:08+00:00\",\"dateModified\":\"2021-06-02T01:15:11+00:00\",\"description\":\"A Ultrapar (UGPA3) comunicou ao mercado que sofreu ontem um ataque hacker em seu ambiente de tecnologia de informa\u00e7\u00e3o. Clique aqui\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/bed53c65-hacker-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/bed53c65-hacker-jpg.webp\",\"width\":640,\"height\":340,\"caption\":\"Ultrapar (UGPA3) sofre ataque hacker e opera em conting\u00eancia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ultrapar (UGPA3) sofre ataque hacker e opera em conting\u00eancia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda\",\"name\":\"Poliana Santos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g\",\"caption\":\"Poliana Santos\"},\"description\":\"Rep\u00f3rter no Suno Not\u00edcias, com cobertura em mercado financeiro, economia, finan\u00e7as pessoais, renda fixa e varejo. Jornalista formada pela Faculdade C\u00e1sper L\u00edbero e possui passagem na R\u00e1dio Gazeta AM com a produ\u00e7\u00e3o de conte\u00fado sobre economia, pol\u00edtica, sa\u00fade, moda e m\u00fasica. Possui certificado de conclus\u00e3o do curso de An\u00e1lise de Balan\u00e7os pela Funda\u00e7\u00e3o Bradesco, Agenda Brasil pela FAAP, Educa\u00e7\u00e3o Pol\u00edtica por Alexandre Garcia e do Tesouro Direto e Mercado de A\u00e7\u00f5es pela B3.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ultrapar (UGPA3) sofre ataque hacker e opera em conting\u00eancia","description":"A Ultrapar (UGPA3) comunicou ao mercado que sofreu ontem um ataque hacker em seu ambiente de tecnologia de informa\u00e7\u00e3o. Clique aqui","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/","og_locale":"pt_BR","og_type":"article","og_title":"Ultrapar (UGPA3) sofre ataque hacker e opera em conting\u00eancia","og_description":"A Ultrapar (UGPA3) comunicou ao mercado que sofreu ontem um ataque hacker em seu ambiente de tecnologia de informa\u00e7\u00e3o. Clique aqui","og_url":"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":640,"height":340,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/bed53c65-hacker.jpg","type":"image\/jpeg"}],"author":"Poliana Santos","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Poliana Santos","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/"},"author":{"name":"Poliana Santos","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda"},"headline":"Ultrapar (UGPA3) sofre ataque hacker e opera em conting\u00eancia","datePublished":"2021-01-12T14:56:08+00:00","dateModified":"2021-06-02T01:15:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/"},"wordCount":744,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/bed53c65-hacker-jpg.webp","keywords":["ataques cibern\u00e9ticos","Ultrapar (UGPA3)"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/","url":"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/","name":"Ultrapar (UGPA3) sofre ataque hacker e opera em conting\u00eancia","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/bed53c65-hacker-jpg.webp","datePublished":"2021-01-12T14:56:08+00:00","dateModified":"2021-06-02T01:15:11+00:00","description":"A Ultrapar (UGPA3) comunicou ao mercado que sofreu ontem um ataque hacker em seu ambiente de tecnologia de informa\u00e7\u00e3o. Clique aqui","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/bed53c65-hacker-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/bed53c65-hacker-jpg.webp","width":640,"height":340,"caption":"Ultrapar (UGPA3) sofre ataque hacker e opera em conting\u00eancia"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Ultrapar (UGPA3) sofre ataque hacker e opera em conting\u00eancia"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda","name":"Poliana Santos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g","caption":"Poliana Santos"},"description":"Rep\u00f3rter no Suno Not\u00edcias, com cobertura em mercado financeiro, economia, finan\u00e7as pessoais, renda fixa e varejo. Jornalista formada pela Faculdade C\u00e1sper L\u00edbero e possui passagem na R\u00e1dio Gazeta AM com a produ\u00e7\u00e3o de conte\u00fado sobre economia, pol\u00edtica, sa\u00fade, moda e m\u00fasica. Possui certificado de conclus\u00e3o do curso de An\u00e1lise de Balan\u00e7os pela Funda\u00e7\u00e3o Bradesco, Agenda Brasil pela FAAP, Educa\u00e7\u00e3o Pol\u00edtica por Alexandre Garcia e do Tesouro Direto e Mercado de A\u00e7\u00f5es pela B3.","url":"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/bed53c65-hacker-400x200.webp\" alt=\"Ultrapar (UGPA3) sofre ataque hacker e opera em conting\u00eancia\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/ultrapar-ugpa3-ataque-hacker-empresas\/\"><h2 class=\"content__title\">Ultrapar (UGPA3) sofre ataque hacker e opera em conting\u00eancia<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/7ef34026-whatsapp-image-2020-08-03-at-12.37.57-150x150.webp\" alt=\"Poliana Santos\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\"><span itemprop=\"author\">Poliana Santos<\/span><\/a><\/span><time datetime=\"2021-01-12T11:56:08-03:00\" itemprop=\"datePublished\">12\/01\/2021 11:56<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/112653"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=112653"}],"version-history":[{"count":1,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/112653\/revisions"}],"predecessor-version":[{"id":153959,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/112653\/revisions\/153959"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/112674"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=112653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=112653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=112653"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=112653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}