{"id":112097,"date":"2021-01-08T21:00:40","date_gmt":"2021-01-09T00:00:40","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=112097"},"modified":"2021-06-13T23:28:12","modified_gmt":"2021-06-14T02:28:12","slug":"twitter-suspende-conta-donald-trump","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/","title":{"rendered":"Twitter suspende permanentemente conta de Donald Trump"},"content":{"rendered":"<p>O Twitter suspendeu permanentemente a conta do presidente dos Estados Unidos <a href=\"https:\/\/www.suno.com.br\/tudo-sobre\/donald-trump\/\"><strong>Donald Trump<\/strong><\/a> nesta sexta-feira (8) por &#8220;risco de mais incita\u00e7\u00e3o \u00e0 viol\u00eancia&#8221;, o que viola os termos de uso da plataforma.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/4ab9550a-08_01_2021_20_57_29-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/4ab9550a-08_01_2021_20_57_29-jpg.webp\" width=\"800\" height=\"450\" alt=\"Twitter suspende permanentemente conta de Donald Trump\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">O Twitter suspendeu a conta de Donald Trump alegando &quot;risco de mais incita\u00e7\u00e3o \u00e0 viol\u00eancia&quot;<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-controle-gastos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Planilha-controle-de-gastos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t\tdata-promo-id=\"101751\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>&#8220;Ap\u00f3s uma an\u00e1lise detalhada dos tweets recentes da conta <strong>@realDonaldTrump<\/strong> e do contexto em torno deles &#8211; especificamente como est\u00e3o sendo recebidos e interpretados dentro e fora do Twitter &#8211; suspendemos permanentemente a conta devido ao risco de mais incita\u00e7\u00e3o \u00e0 viol\u00eancia&#8221;, salientou a empresa de rede social <a href=\"https:\/\/blog.twitter.com\/en_us\/topics\/company\/2020\/suspension.html\">em nota<\/a>.<\/p>\n<p>No comunicado, o <strong>Twitter<\/strong> ressaltou que deixou &#8220;claro&#8221; ap\u00f3s o mandat\u00e1rio incitar apoiadores a impedir a confirma\u00e7\u00e3o de Joe Biden como o pr\u00f3ximo presidente dos Estados Unidos, o que levou \u00e0 invas\u00e3o do Capit\u00f3lio na quarta-feira (6), que mais incentivos \u00e0 viol\u00eancia resultariam neste bloqueio.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">After close review of recent Tweets from the <a href=\"https:\/\/twitter.com\/realDonaldTrump?ref_src=twsrc%5Etfw\">@realDonaldTrump<\/a> account and the context around them we have permanently suspended the account due to the risk of further incitement of violence.<a href=\"https:\/\/t.co\/CBpE1I6j8Y\">https:\/\/t.co\/CBpE1I6j8Y<\/a><\/p>\n<p>\u2014 Twitter Safety (@TwitterSafety) <a href=\"https:\/\/twitter.com\/TwitterSafety\/status\/1347684877634838528?ref_src=twsrc%5Etfw\">January 8, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Autoridades eleitas e l\u00edderes mundiais &#8220;n\u00e3o est\u00e3o totalmente acima de nossas regras e n\u00e3o podem usar o Twitter para incitar a viol\u00eancia, entre outras coisas&#8221;, comunicou o Twitter na nota.<\/p>\n<h2>Tweets que levaram ao banimento de Donald Trump<\/h2>\n<p>Embora por conta da decis\u00e3o da empresa de <a href=\"https:\/\/www.suno.com.br\/tudo-sobre\/Jack-Dorsey\/\">Jack Dorsey<\/a> n\u00e3o seja poss\u00edvel acessar os tweets que levaram ao bloqueio da <strong>conta de Donald Trump<\/strong>, a empresa divulgou os detalhes das duas publica\u00e7\u00f5es que acabariam por se tornar as \u00faltimos do republicano.<\/p>\n<p>A primeira, postada em 8 de janeiro de 2021, o presidente norte-americano publicou: &#8220;Os 75.000,000 grandes Patriotas Americanos que votaram em mim, AMERICA FIRST, e MAKE AMERICA GREAT AGAIN, ter\u00e3o um VOZ GIGANTE por muito tempo no futuro. Eles n\u00e3o ser\u00e3o desrespeitados ou amea\u00e7ados injustamente em nenhum sentido, modo ou forma!!!&#8221;.<\/p>\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Veja mais<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/donald-trump-nao-acusado-tumulto-capitolio\/\">\n\t\t\tDonald Trump n\u00e3o deve ser acusado de incitar tumulto no Capit\u00f3lio, diz Departamento de Justi\u00e7a\t\t<\/a>\n\t<\/div>\n\n\n<p>Em seguida, Donald Trump postou em sua conta: &#8220;Para todos aqueles que perguntaram, eu n\u00e3o irei \u00e0 Posse em 20 de janeiro&#8221;.<\/p>\n<p>Segundo o Twitter, as publica\u00e7\u00e3o violam a <a href=\"https:\/\/help.twitter.com\/en\/rules-and-policies\/violent-threats-glorification\">Pol\u00edtica de Glorifica\u00e7\u00e3o da Viol\u00eancia<\/a>, o que justificaria o banimento da conta permanentemente.<\/p>\n<p>&#8220;Devido \u00e0s tens\u00f5es em curso nos Estados Unidos, e ao aumento na discuss\u00e3o global envolvendo as pessoas que invadiram violentamente o Capit\u00f3lio em 6 de janeiro de 2021, esses dois tweets devem ser lidos no contexto de eventos mais amplos no pa\u00eds e no sentido no qual as declara\u00e7\u00f5es do presidente podem mobilizar diferentes p\u00fablicos, incluindo para incitar a viol\u00eancia, assim como no contexto do padr\u00e3o de comportamento dessa conta nas \u00faltimas semanas&#8221;, argumentou a empresa.<\/p>\n<h2>Amea\u00e7a de impeachment<\/h2>\n<p>Esse n\u00e3o foi o \u00fanico golpe sofrido por Donald Trump nesta sexta-feira. Mais cedo, a presidente da C\u00e2mara dos Representantes dos Estados Unidos, Nancy Pelosi, disse que o partido Democrata estava preparado para mover um <strong>processo de impeachment <\/strong>j\u00e1 nesta segunda-feira (11) se o republicano n\u00e3o renunciasse antes do fim do mandato.<\/p>\n<p>&#8220;\u00c9 a esperan\u00e7a do membros [do Congresso norte-americano] de que o presidente renuncie imediatamente. Mas se ele n\u00e3o o fizer, eu orientei o Rules Committee para se preparar para avan\u00e7ar com a 25\u00aa emenda legislativa do congressista Jamie Raskin e uma mo\u00e7\u00e3o de impeachment&#8221;, disse Pelosi.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/ebook-como-analisar-uma-acao\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Mobile.jpg\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t\tdata-promo-id=\"378302\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='286'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/Ebook-Acoes-Desktop.jpg\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>O imbr\u00f3glio envolvendo o presidente <strong>Donald Trump<\/strong> se d\u00e1 ap\u00f3s milhares de apoiadores do republicano invadirem os corredores do Capit\u00f3lio ap\u00f3s um com\u00edcio no qual o mandat\u00e1rio incitou-os a impedir a confirma\u00e7\u00e3o de Joe Biden como o pr\u00f3ximo presidente dos Estados Unidos.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-de-controle-de-investimentos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Controle-de-Investimentos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t\tdata-promo-id=\"75934\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>O Twitter suspendeu permanentemente a conta do presidente dos Estados Unidos Donald Trump nesta sexta-feira (8) por &#8220;risco de mais incita\u00e7\u00e3o \u00e0 viol\u00eancia&#8221;, o que viola os termos de uso da plataforma. O Twitter suspendeu a conta de Donald Trump alegando &quot;risco de mais incita\u00e7\u00e3o \u00e0 viol\u00eancia&quot; &#8220;Ap\u00f3s uma an\u00e1lise detalhada dos tweets recentes da [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":112099,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[63],"tags":[724,793,1110],"suno_strategy":[],"class_list":["post-112097","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-donald-trump","tag-estados-unidos-eua","tag-twitter-twtr34"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Twitter suspende permanentemente conta de Donald Trump<\/title>\n<meta name=\"description\" content=\"O Twitter anunciou a suspens\u00e3o permanentemente da conta do presidente dos Estados Unidos Donald Trump. Clique para saber mais\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Twitter suspende permanentemente conta de Donald Trump\" \/>\n<meta property=\"og:description\" content=\"O Twitter anunciou a suspens\u00e3o permanentemente da conta do presidente dos Estados Unidos Donald Trump. Clique para saber mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/4ab9550a-08_01_2021_20_57_29.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"378\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arthur Guimar\u00e3es\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arthur Guimar\u00e3es\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/\"},\"author\":{\"name\":\"Arthur Guimar\u00e3es\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/053a750a709a263919a20f976caae91c\"},\"headline\":\"Twitter suspende permanentemente conta de Donald Trump\",\"datePublished\":\"2021-01-09T00:00:40+00:00\",\"dateModified\":\"2021-06-14T02:28:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/\"},\"wordCount\":635,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/4ab9550a-08_01_2021_20_57_29-jpg.webp\",\"keywords\":[\"Donald Trump\",\"Estados Unidos (EUA)\",\"Twitter (TWTR34)\"],\"articleSection\":[\"Internacional\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/\",\"name\":\"Twitter suspende permanentemente conta de Donald Trump\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/4ab9550a-08_01_2021_20_57_29-jpg.webp\",\"datePublished\":\"2021-01-09T00:00:40+00:00\",\"dateModified\":\"2021-06-14T02:28:12+00:00\",\"description\":\"O Twitter anunciou a suspens\u00e3o permanentemente da conta do presidente dos Estados Unidos Donald Trump. Clique para saber mais\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/4ab9550a-08_01_2021_20_57_29-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/4ab9550a-08_01_2021_20_57_29-jpg.webp\",\"width\":600,\"height\":378,\"caption\":\"O Twitter suspendeu a conta de Donald Trump alegando \\\"risco de mais incita\u00e7\u00e3o \u00e0 viol\u00eancia\\\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Internacional\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/internacional\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Twitter suspende permanentemente conta de Donald Trump\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/053a750a709a263919a20f976caae91c\",\"name\":\"Arthur Guimar\u00e3es\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1affd86a11209ae09eb6dd3bcad3e96c?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1affd86a11209ae09eb6dd3bcad3e96c?s=96&r=g\",\"caption\":\"Arthur Guimar\u00e3es\"},\"description\":\"Arthur Guimar\u00e3es escreve sobre pol\u00edtica, economia e neg\u00f3cios para o portal de not\u00edcias da Suno Research. Atualmente, \u00e9 estudante de jornalismo pela Faculdade C\u00e1sper L\u00edbero.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/arthur-guimaraes\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Twitter suspende permanentemente conta de Donald Trump","description":"O Twitter anunciou a suspens\u00e3o permanentemente da conta do presidente dos Estados Unidos Donald Trump. Clique para saber mais","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/","og_locale":"pt_BR","og_type":"article","og_title":"Twitter suspende permanentemente conta de Donald Trump","og_description":"O Twitter anunciou a suspens\u00e3o permanentemente da conta do presidente dos Estados Unidos Donald Trump. Clique para saber mais","og_url":"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":600,"height":378,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/4ab9550a-08_01_2021_20_57_29.jpg","type":"image\/jpeg"}],"author":"Arthur Guimar\u00e3es","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Arthur Guimar\u00e3es","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/"},"author":{"name":"Arthur Guimar\u00e3es","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/053a750a709a263919a20f976caae91c"},"headline":"Twitter suspende permanentemente conta de Donald Trump","datePublished":"2021-01-09T00:00:40+00:00","dateModified":"2021-06-14T02:28:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/"},"wordCount":635,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/4ab9550a-08_01_2021_20_57_29-jpg.webp","keywords":["Donald Trump","Estados Unidos (EUA)","Twitter (TWTR34)"],"articleSection":["Internacional"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/","url":"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/","name":"Twitter suspende permanentemente conta de Donald Trump","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/4ab9550a-08_01_2021_20_57_29-jpg.webp","datePublished":"2021-01-09T00:00:40+00:00","dateModified":"2021-06-14T02:28:12+00:00","description":"O Twitter anunciou a suspens\u00e3o permanentemente da conta do presidente dos Estados Unidos Donald Trump. Clique para saber mais","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/4ab9550a-08_01_2021_20_57_29-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/4ab9550a-08_01_2021_20_57_29-jpg.webp","width":600,"height":378,"caption":"O Twitter suspendeu a conta de Donald Trump alegando \"risco de mais incita\u00e7\u00e3o \u00e0 viol\u00eancia\""},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Internacional","item":"https:\/\/www.suno.com.br\/noticias\/internacional\/"},{"@type":"ListItem","position":3,"name":"Twitter suspende permanentemente conta de Donald Trump"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/053a750a709a263919a20f976caae91c","name":"Arthur Guimar\u00e3es","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1affd86a11209ae09eb6dd3bcad3e96c?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1affd86a11209ae09eb6dd3bcad3e96c?s=96&r=g","caption":"Arthur Guimar\u00e3es"},"description":"Arthur Guimar\u00e3es escreve sobre pol\u00edtica, economia e neg\u00f3cios para o portal de not\u00edcias da Suno Research. Atualmente, \u00e9 estudante de jornalismo pela Faculdade C\u00e1sper L\u00edbero.","url":"https:\/\/www.suno.com.br\/noticias\/author\/arthur-guimaraes\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/01\/4ab9550a-08_01_2021_20_57_29-400x200.webp\" alt=\"Twitter suspende permanentemente conta de Donald Trump\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/internacional\/\">Internacional<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/twitter-suspende-conta-donald-trump\/\"><h2 class=\"content__title\">Twitter suspende permanentemente conta de Donald Trump<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/arthur-guimaraes\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/02\/dfb40897-eu-150x150.webp\" alt=\"Arthur Guimar\u00e3es\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/arthur-guimaraes\/\"><span itemprop=\"author\">Arthur Guimar\u00e3es<\/span><\/a><\/span><time datetime=\"2021-01-08T21:00:40-03:00\" itemprop=\"datePublished\">08\/01\/2021 21:00<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/112097"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=112097"}],"version-history":[{"count":1,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/112097\/revisions"}],"predecessor-version":[{"id":156747,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/112097\/revisions\/156747"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/112099"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=112097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=112097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=112097"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=112097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}