{"id":109513,"date":"2020-12-21T18:44:59","date_gmt":"2020-12-21T21:44:59","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=109513"},"modified":"2021-06-13T23:28:35","modified_gmt":"2021-06-14T02:28:35","slug":"empresas-fugindo-california-texas","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/","title":{"rendered":"A grande fuga: por que as empresas est\u00e3o fugindo da Calif\u00f3rnia para o Texas"},"content":{"rendered":"<p>A not\u00edcia mais recente foi que <a href=\"https:\/\/www.suno.com.br\/tudo-sobre\/elon-musk\/\">Elon Musk<\/a> vai se mudar da <strong>Calif\u00f3rnia<\/strong> para o Texas. O empres\u00e1rio j\u00e1 tem nesse \u00faltimo estado sua nova base espacial da SpaceX e est\u00e1 construindo uma f\u00e1brica da Tesla (<a href=\"https:\/\/www.suno.com.br\/artigos\/NASDAQ\/\">NASDAQ<\/a>: TSLA).<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/7c9d5528-texas-vs-california-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/7c9d5528-texas-vs-california-800x450.webp\" width=\"800\" height=\"450\" alt=\"A grande fuga: por que as empresas est\u00e3o fugindo da Calif\u00f3rnia para o Texas\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Por que as empresas est\u00e3o fugindo da Calif\u00f3rnia para o Texas<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-controle-gastos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Planilha-controle-de-gastos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t\tdata-promo-id=\"101751\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>A not\u00edcia gerou surpresa, pois a Calif\u00f3rnia, com seu <strong>Vale do Sil\u00edcio,<\/strong> \u00e9 considerada o ber\u00e7o das empresas de tecnologia. Um ecossistema \u00fanico, onde as <strong>start-ups<\/strong> surgem, se desenvolvem e se tornam gigantes mundiais.<\/p>\n<p>O clima agrad\u00e1vel do Vale do Sil\u00edcio, as oportunidades educacionais e as perspectivas de emprego atra\u00edram trabalhadores por mais de um s\u00e9culo e ajudaram a transformar a regi\u00e3o no epicentro da ind\u00fastria de tecnologia do mudo.<\/p>\n<p><a href=\"https:\/\/lp.suno.com.br\/suno-one\/\">Suno One: acesse gratuitamente eBooks, Minicursos, Artigos e Video Aulas sobre investimentos com um \u00fanico cadastro. Clique para saber mais!<\/a><\/p>\n<p>Entretanto, a sa\u00edda de Musk do &#8220;estado do sol&#8221; n\u00e3o \u00e9 um caso \u00fanico.<\/p>\n<h2>Calif\u00f3rnia (n\u00e3o mais) terra de oportunidades?<\/h2>\n<p>A <strong>Oracle<\/strong> de <strong>Larry Elison<\/strong> tamb\u00e9m decidiu mudar sua sede da Calif\u00f3rnia para o Texas.\u00a0 Mesmo roteiro para a <strong>Hewlett Packard<\/strong> (<a href=\"https:\/\/www.suno.com.br\/artigos\/NYSE\/\">NYSE<\/a>: HPE), <strong>Dell<\/strong> e <strong>Advanced Micro Devices.<\/strong> E por dezenas de outras empresas menores.<\/p>\n<p>O rico estado do Pac\u00edfico deixou de ser a &#8220;terra prometida&#8221; da Am\u00e9rica e se tornou o epicentro das reclama\u00e7\u00f5es de empres\u00e1rios, que se queixam dos impostos muito elevados e pelas regras excessivas que deixam muito complicado fazer neg\u00f3cios.<\/p>\n<p>Isso sem contar as secas mortais, inc\u00eandios devastadores, apag\u00f5es de energia el\u00e9trica e a pandemia do novo <strong>coronav\u00edrus (Covid-19)<\/strong> que flagelaram a Calif\u00f3rnia nos \u00faltimos anos.<\/p>\n<p>Al\u00e9m das empresas, estaria ocorrendo tamb\u00e9m um \u00eaxodo de habitantes.<\/p>\n<p>Nos \u00faltimos dez anos, 687 mil californianos se mudaram para o <strong>Texas,<\/strong> enquanto os texanos que fizeram o caminho inverso foram pouco mais de 300 mil.<\/p>\n<p>Entre as causas dessa &#8220;grande fuga&#8221; est\u00e1 tamb\u00e9m o custo de vida que se tornou insustent\u00e1vel em meio a impostos excessivos e alugu\u00e9is que chegaram \u00e0s alturas.<\/p>\n\t<p>\n\t\t<a href=\"\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"\"\n\t\t\t\t\tdata-promo-id=\"106782\"\t\t\t\t\t\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>E os texanos, conhecidos por serem cidad\u00e3os orgulhosos e um tanto arrogantes, d\u00e3o as boas-vindas aos imigrantes que chegam da Costa Oeste com um slogan que parece mais uma chacota: &#8220;Don&#8217;t California my Texas&#8221;, ou seja, n\u00e3o transforme meu estado em outra Calif\u00f3rnia.<\/p>\n<h2>Grande fuga para o Texas<\/h2>\n<p>Mas estamos realmente assistindo a uma &#8220;grande fuga&#8221; das empresas de tecnologia e de cidad\u00e3os? E o Texas \u00e9 realmente o novo <strong>Eldorado?<\/strong><\/p>\n\t<p>\n\t\t<a href=\"\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"\"\n\t\t\t\t\tdata-promo-id=\"107544\"\t\t\t\t\t\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>O que est\u00e1 ocorrendo com a <strong>Calif\u00f3rnia<\/strong> e o Texas n\u00e3o \u00e9 apenas um fen\u00f4meno econ\u00f4mico ou geogr\u00e1fico, mas se tornou o palco de uma nova batalha pol\u00edtica nos <strong>Estados<\/strong>\u00a0Unidos.<\/p>\n<p>Os conservadores, ressentidos pela derrota de <a href=\"https:\/\/www.suno.com.br\/tudo-sobre\/donald-trump\/\"><strong>Donald Trump<\/strong><\/a> e fartos de serem considerados uma for\u00e7a retr\u00f3grada, consideram o Texas um laborat\u00f3rio de uma nova direita que est\u00e1 olhando para o futuro, conseguindo atrair empresas da economia digital.<\/p>\n<p>Al\u00e9m disso, a Calif\u00f3rnia, governada h\u00e1 uma d\u00e9cada pelo Partido Democrata, est\u00e1 sendo utilizada como exemplo de tudo o que pode dar errado com a presid\u00eancia de <strong>Joe Biden.<\/strong> Ou seja, aumento dos impostos, regras que deixam imposs\u00edvel qualquer atividade econ\u00f4mica e fuga de empresas.<\/p>\n<p>Alguns radicais que n\u00e3o aceitam a ideia de serem governados por um presidente democrata tamb\u00e9m come\u00e7aram a sugerir a secess\u00e3o do Texas da Uni\u00e3o. Algo que o presidente do partido republicano do grande estado do Sul acaba de propor.<\/p>\n<p>Todavia, muitos pol\u00edticos californianos consideram &#8220;o novo \u00edm\u00e3 texano&#8221; apenas como um truque de marketing pol\u00edtico.<\/p>\n<p>Por exemplo, Musk estaria se mudando apenas por conveni\u00eancia tribut\u00e1ria, pois a sede da <strong>Tesla<\/strong> permanecer\u00e1 em San Bruno, perto de <strong>San Francisco,<\/strong> enquanto a f\u00e1brica texana se juntar\u00e1 \u00e0 californiana, que continua produzindo.<\/p>\n<p>Quanto \u00e0 Oracle, <a href=\"https:\/\/www.suno.com.br\/tudo-sobre\/larry-ellison\/#:~:text=Larry%20Ellison%20%C3%A9%20um%20dos,inform%C3%A1tica%2C%20sediada%20nos%20Estados%20Unidos.&amp;text=De%20acordo%20com%20levantamento%20da,US%24%2058%2C5%20bilh%C3%B5es.\"><strong>Larry Ellison<\/strong><\/a> vai se mudar, mas n\u00e3o para o Texas: ele vai morar no Hava\u00ed. E os funcion\u00e1rios da gigante do software ter\u00e3o a liberdade de escolher entre a nova sede em Austin e a antiga em Redwood City, no Vale do Sil\u00edcio, que permanece ativa.<\/p>\n<p>Outras empresas, por sua vez, est\u00e3o se mudando da Calif\u00f3rnia mas n\u00e3o rumo ao <strong>Texas,<\/strong> e sim a outros estados, como o Colorado. Esse foi o caso do <strong>Palantir<\/strong> de Peter Thiel.<\/p>\n\t<p>\n\t\t<a href=\"\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"\"\n\t\t\t\t\tdata-promo-id=\"108129\"\t\t\t\t\t\t\t\t\t\t\t\t\t\t\talt=\"\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>Portanto, decretar o fim da Calif\u00f3rnia como polo tecnol\u00f3gico dos <strong>EUA<\/strong> e do mundo pode parecer ainda prematuro. Isso pois tamb\u00e9m outros grandes grupos de tecnologia, do <strong>Facebook<\/strong> (NASDAQ: FB) ao <strong>Google<\/strong> (NASDAQ: GOOG), n\u00e3o pretendem se mudar do estado. Enquanto a Apple, mesmo que quisesse, n\u00e3o poderia abandonar sua nova sede de Cupertino, que custou US$ 5 bilh\u00f5es (cerca de R$ 30 bilh\u00f5es), constru\u00edda em forma de nave espacial circular.<\/p>\n<p>Mas a &#8220;grande fuga&#8221; das empresas de tecnologia da <strong>Calif\u00f3rnia<\/strong> j\u00e1 est\u00e1 preocupando muitos em San Francisco e em Washington tamb\u00e9m.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-de-controle-de-investimentos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Controle-de-Investimentos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t\tdata-promo-id=\"75934\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>A not\u00edcia mais recente foi que Elon Musk vai se mudar da Calif\u00f3rnia para o Texas. O empres\u00e1rio j\u00e1 tem nesse \u00faltimo estado sua nova base espacial da SpaceX e est\u00e1 construindo uma f\u00e1brica da Tesla (NASDAQ: TSLA). Por que as empresas est\u00e3o fugindo da Calif\u00f3rnia para o Texas A not\u00edcia gerou surpresa, pois a [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":109829,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[63],"tags":[726,793,727,105558],"suno_strategy":[],"class_list":["post-109513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-elon-musk","tag-estados-unidos-eua","tag-tesla-tsla34","tag-vale-do-silicio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Por que as empresas est\u00e3o fugindo da Calif\u00f3rnia para o Texas<\/title>\n<meta name=\"description\" content=\"A grande fuga: entenda por que muitas empresas est\u00e3o fugindo da Calif\u00f3rnia para o Texas. Clique aqui e saiba mais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por que as empresas est\u00e3o fugindo da Calif\u00f3rnia para o Texas\" \/>\n<meta property=\"og:description\" content=\"A grande fuga: entenda por que muitas empresas est\u00e3o fugindo da Calif\u00f3rnia para o Texas. Clique aqui e saiba mais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/7c9d5528-texas-vs-california.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carlo Cauti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carlo Cauti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/\"},\"author\":{\"name\":\"Carlo Cauti\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/e6e0f723cc177805027f4566c1d5e0c8\"},\"headline\":\"A grande fuga: por que as empresas est\u00e3o fugindo da Calif\u00f3rnia para o Texas\",\"datePublished\":\"2020-12-21T21:44:59+00:00\",\"dateModified\":\"2021-06-14T02:28:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/\"},\"wordCount\":861,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/7c9d5528-texas-vs-california-jpg.webp\",\"keywords\":[\"Elon Musk\",\"Estados Unidos (EUA)\",\"Tesla (TSLA34)\",\"vale do sil\u00edcio\"],\"articleSection\":[\"Internacional\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/\",\"name\":\"Por que as empresas est\u00e3o fugindo da Calif\u00f3rnia para o Texas\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/7c9d5528-texas-vs-california-jpg.webp\",\"datePublished\":\"2020-12-21T21:44:59+00:00\",\"dateModified\":\"2021-06-14T02:28:35+00:00\",\"description\":\"A grande fuga: entenda por que muitas empresas est\u00e3o fugindo da Calif\u00f3rnia para o Texas. Clique aqui e saiba mais.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/7c9d5528-texas-vs-california-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/7c9d5528-texas-vs-california-jpg.webp\",\"width\":800,\"height\":600,\"caption\":\"Por que as empresas est\u00e3o fugindo da Calif\u00f3rnia para o Texas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Internacional\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/internacional\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"A grande fuga: por que as empresas est\u00e3o fugindo da Calif\u00f3rnia para o Texas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/e6e0f723cc177805027f4566c1d5e0c8\",\"name\":\"Carlo Cauti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3ada9e0bd164c23abd4792a9606d583c?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3ada9e0bd164c23abd4792a9606d583c?s=96&r=g\",\"caption\":\"Carlo Cauti\"},\"description\":\"Editor multim\u00eddia do SUNO Not\u00edcias. Italiano, formado em Ci\u00eancias Pol\u00edticas pela universidade LUISS G. Carli de Roma e mestre cum laude em Rela\u00e7\u00f5es Internacionais, Jornalismo Internacional e de Guerra e em Economia Internacional. Concluiu tamb\u00e9m um MBA em Finan\u00e7as na B3. No Brasil, teve passagem por ve\u00edculos como Estad\u00e3o, Globo, Veja e EXAME. e nas ag\u00eancias de not\u00edcias italianas ANSA e NOVA.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/carlo-cauti\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por que as empresas est\u00e3o fugindo da Calif\u00f3rnia para o Texas","description":"A grande fuga: entenda por que muitas empresas est\u00e3o fugindo da Calif\u00f3rnia para o Texas. Clique aqui e saiba mais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/","og_locale":"pt_BR","og_type":"article","og_title":"Por que as empresas est\u00e3o fugindo da Calif\u00f3rnia para o Texas","og_description":"A grande fuga: entenda por que muitas empresas est\u00e3o fugindo da Calif\u00f3rnia para o Texas. Clique aqui e saiba mais.","og_url":"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":800,"height":600,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/7c9d5528-texas-vs-california.jpg","type":"image\/jpeg"}],"author":"Carlo Cauti","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Carlo Cauti","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/"},"author":{"name":"Carlo Cauti","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/e6e0f723cc177805027f4566c1d5e0c8"},"headline":"A grande fuga: por que as empresas est\u00e3o fugindo da Calif\u00f3rnia para o Texas","datePublished":"2020-12-21T21:44:59+00:00","dateModified":"2021-06-14T02:28:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/"},"wordCount":861,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/7c9d5528-texas-vs-california-jpg.webp","keywords":["Elon Musk","Estados Unidos (EUA)","Tesla (TSLA34)","vale do sil\u00edcio"],"articleSection":["Internacional"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/","url":"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/","name":"Por que as empresas est\u00e3o fugindo da Calif\u00f3rnia para o Texas","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/7c9d5528-texas-vs-california-jpg.webp","datePublished":"2020-12-21T21:44:59+00:00","dateModified":"2021-06-14T02:28:35+00:00","description":"A grande fuga: entenda por que muitas empresas est\u00e3o fugindo da Calif\u00f3rnia para o Texas. Clique aqui e saiba mais.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/7c9d5528-texas-vs-california-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/7c9d5528-texas-vs-california-jpg.webp","width":800,"height":600,"caption":"Por que as empresas est\u00e3o fugindo da Calif\u00f3rnia para o Texas"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Internacional","item":"https:\/\/www.suno.com.br\/noticias\/internacional\/"},{"@type":"ListItem","position":3,"name":"A grande fuga: por que as empresas est\u00e3o fugindo da Calif\u00f3rnia para o Texas"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/e6e0f723cc177805027f4566c1d5e0c8","name":"Carlo Cauti","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3ada9e0bd164c23abd4792a9606d583c?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ada9e0bd164c23abd4792a9606d583c?s=96&r=g","caption":"Carlo Cauti"},"description":"Editor multim\u00eddia do SUNO Not\u00edcias. Italiano, formado em Ci\u00eancias Pol\u00edticas pela universidade LUISS G. Carli de Roma e mestre cum laude em Rela\u00e7\u00f5es Internacionais, Jornalismo Internacional e de Guerra e em Economia Internacional. Concluiu tamb\u00e9m um MBA em Finan\u00e7as na B3. No Brasil, teve passagem por ve\u00edculos como Estad\u00e3o, Globo, Veja e EXAME. e nas ag\u00eancias de not\u00edcias italianas ANSA e NOVA.","url":"https:\/\/www.suno.com.br\/noticias\/author\/carlo-cauti\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/7c9d5528-texas-vs-california-400x200.webp\" alt=\"A grande fuga: por que as empresas est\u00e3o fugindo da Calif\u00f3rnia para o Texas\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/internacional\/\">Internacional<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/empresas-fugindo-california-texas\/\"><h2 class=\"content__title\">A grande fuga: por que as empresas est\u00e3o fugindo da Calif\u00f3rnia para o Texas<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/carlo-cauti\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/e3745f9a-perfil-carlo-cauti-150x150.webp\" alt=\"Carlo Cauti\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/carlo-cauti\/\"><span itemprop=\"author\">Carlo Cauti<\/span><\/a><\/span><time datetime=\"2020-12-21T18:44:59-03:00\" itemprop=\"datePublished\">21\/12\/2020 18:44<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/109513"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=109513"}],"version-history":[{"count":1,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/109513\/revisions"}],"predecessor-version":[{"id":156762,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/109513\/revisions\/156762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/109829"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=109513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=109513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=109513"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=109513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}