{"id":108178,"date":"2020-12-15T13:49:11","date_gmt":"2020-12-15T16:49:11","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=108178"},"modified":"2020-12-15T13:49:11","modified_gmt":"2020-12-15T16:49:11","slug":"aie-revisao-demanda-global-petroleo","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/","title":{"rendered":"AIE corta previs\u00e3o para alta na demanda global por petr\u00f3leo em 2021"},"content":{"rendered":"<p>A Ag\u00eancia Internacional de Energia (AIE) reduziu nesta ter\u00e7a-feira (15) em 170 mil barris por dia (bpd) sua previs\u00e3o para o crescimento da demanda global por <a href=\"https:\/\/www.suno.com.br\/artigos\/cotacao-do-petroleo\/\"><strong>petr\u00f3leo<\/strong> <\/a>em 2021.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/8c20298d-petroleo-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/8c20298d-petroleo-jpg.webp\" width=\"800\" height=\"450\" alt=\"AIE corta previs\u00e3o para alta na demanda global por petr\u00f3leo em 2021\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">AIE corta previs\u00e3o para alta na demanda global por petr\u00f3leo em 2021<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-controle-gastos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Planilha-controle-de-gastos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t\tdata-promo-id=\"101751\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>Para 2020, a expectativa contida no relat\u00f3rio de dezembro, publicado hoje, \u00e9 bastante similar ao relat\u00f3rio do m\u00eas anterior, com corte de 50 mil bpd. A AIE diz que a redu\u00e7\u00e3o na expectativa para aumento na <strong>demanda<\/strong> de <strong>petr\u00f3leo<\/strong> no pr\u00f3ximo ano foi fruto de mais um corte na previs\u00e3o para a demanda por <strong>combust\u00edveis<\/strong> par avia\u00e7\u00e3o e <strong>querosene<\/strong>.<\/p>\n<p>&#8220;Em 2021, a demanda por <strong>gasolina<\/strong> e <strong>diesel<\/strong> deve retornar a 97% a 99% de seus n\u00edveis de 2019&#8243;, compara a AIE, ap\u00f3s o choque do ano atual com a pandemia da covid-19.<\/p>\n<p><a href=\"https:\/\/lp.suno.com.br\/suno-one\/\">Suno One: acesse gratuitamente eBooks, Minicursos, Artigos e Video Aulas sobre investimentos com um \u00fanico cadastro. Clique para saber mais!<\/a><\/p>\n<p>A entidade sediada em Paris diz tamb\u00e9m que a<strong> oferta global<\/strong> de petr\u00f3leo subiu 1,5 milh\u00e3o de bpd em novembro, a 92,7 milh\u00f5es de bpd, com os <strong>Estados Unidos<\/strong> recuperando-se de problemas recentes com furac\u00f5es em zonas produtoras e a <strong>L\u00edbia<\/strong> elevando sua produ\u00e7\u00e3o.<\/p>\n<h2>Oferta global de Petr\u00f3leo pode aumentar<\/h2>\n<p>Em dezembro, a AIE diz que a oferta global da <a href=\"https:\/\/www.suno.com.br\/artigos\/o-que-commodities\/\">commodity<\/a> pode aumentar mais, al\u00e9m de lembrar que a<a href=\"https:\/\/www.suno.com.br\/artigos\/opep\/\"> Organiza\u00e7\u00e3o dos Pa\u00edses Exportadores de Petr\u00f3leo e aliados (Opep+)<\/a> elevou sua cota de produ\u00e7\u00e3o no atual acordo em 500 mil bpd em janeiro.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"106682\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>A Opep+ domina o crescimento global da oferta no curto prazo, afirma a AIE. Em 2021 como um todo, produtores de fora da <strong>Opep<\/strong> e tamb\u00e9m da Opep+ devem aumentar sua produ\u00e7\u00e3o em 400 mil bpd, ap\u00f3s queda de 1,3 milh\u00e3o de bpd em 2020, diz o relat\u00f3rio.<\/p>\n<p>A Opep+ registrou 101% de cumprimento de seu acordo para conter a <strong>oferta<\/strong> em novembro, segundo a AIE. J\u00e1 os <strong>EUA<\/strong> tiveram aumento de 500 mil de bpd em sua produ\u00e7\u00e3o em novembro ante o m\u00eas anterior, a 11,1 milh\u00f5es de bpd.<\/p>\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Saiba Mais<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/petroleo-estoques-eua-caem-doe\/\">\n\t\t\tPetr\u00f3leo: estoques nos EUA caem 754 mil barris na semana, diz DoE\t\t<\/a>\n\t<\/div>\n\n\n<p>A AIE aponta ainda que os pre\u00e7os do <strong>petr\u00f3leo<\/strong> reagiram em novembro. Os contratos futuros do <a href=\"https:\/\/www.suno.com.br\/noticias\/tags\/brent\/\">Brent<\/a> subiram US$ 2,46 no m\u00eas passado, a US$ 43,98 em m\u00e9dia, fechando em US$ 49,97 em 11 de dezembro. O relat\u00f3rio lembra que o Brent superou a marca de US$ 50 o barril em dezembro.<\/p>\n<p>Para a AIE, h\u00e1 uma &#8220;euforia compreens\u00edvel&#8221; com o in\u00edcio de programas de vacina\u00e7\u00e3o, o que explica em parte os pre\u00e7os mais altos. A entidade lembra, por\u00e9m, que ainda levar\u00e1 &#8220;v\u00e1rios meses&#8221; at\u00e9 que uma parcela consider\u00e1vel das pessoas tenham sido vacinadas, a ponto de afetar a demanda por <strong>petr\u00f3leo<\/strong>. Adverte tamb\u00e9m para o risco trazido pela nova onda da covid-19 e de mais medidas de restri\u00e7\u00e3o \u00e0 circula\u00e7\u00e3o para conter o v\u00edrus.<\/p>\n<p><em>Com informa\u00e7\u00f5es do Estad\u00e3o Conte\u00fado.<\/em><\/p>\n<p><span style=\"font-weight: 400;\">\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-de-controle-de-investimentos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Controle-de-Investimentos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t\tdata-promo-id=\"75934\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\u00a0\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Ag\u00eancia Internacional de Energia (AIE) reduziu nesta ter\u00e7a-feira (15) em 170 mil barris por dia (bpd) sua previs\u00e3o para o crescimento da demanda global por petr\u00f3leo em 2021. AIE corta previs\u00e3o para alta na demanda global por petr\u00f3leo em 2021 Para 2020, a expectativa contida no relat\u00f3rio de dezembro, publicado hoje, \u00e9 bastante similar [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":108324,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[60],"tags":[811,766,104982],"suno_strategy":[],"class_list":["post-108178","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado","tag-opep","tag-petroleo","tag-petroleo-brent"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AIE corta previs\u00e3o para alta na demanda global por petr\u00f3leo em 2021<\/title>\n<meta name=\"description\" content=\"A AIE reduziu em 170 mil barris por dia sua previs\u00e3o para o crescimento da demanda global por petr\u00f3leo em 2021. Clique aqui e saiba mais\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AIE corta previs\u00e3o para alta na demanda global por petr\u00f3leo em 2021\" \/>\n<meta property=\"og:description\" content=\"A AIE reduziu em 170 mil barris por dia sua previs\u00e3o para o crescimento da demanda global por petr\u00f3leo em 2021. Clique aqui e saiba mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/8c20298d-petroleo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"713\" \/>\n\t<meta property=\"og:image:height\" content=\"475\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Poliana Santos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Poliana Santos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/\"},\"author\":{\"name\":\"Poliana Santos\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda\"},\"headline\":\"AIE corta previs\u00e3o para alta na demanda global por petr\u00f3leo em 2021\",\"datePublished\":\"2020-12-15T16:49:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/\"},\"wordCount\":512,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/8c20298d-petroleo-jpg.webp\",\"keywords\":[\"OPEP\",\"Petr\u00f3leo\",\"Petr\u00f3leo Brent\"],\"articleSection\":[\"Mercado\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/\",\"name\":\"AIE corta previs\u00e3o para alta na demanda global por petr\u00f3leo em 2021\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/8c20298d-petroleo-jpg.webp\",\"datePublished\":\"2020-12-15T16:49:11+00:00\",\"description\":\"A AIE reduziu em 170 mil barris por dia sua previs\u00e3o para o crescimento da demanda global por petr\u00f3leo em 2021. Clique aqui e saiba mais\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/8c20298d-petroleo-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/8c20298d-petroleo-jpg.webp\",\"width\":713,\"height\":475,\"caption\":\"AIE corta previs\u00e3o para alta na demanda global por petr\u00f3leo em 2021\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/mercado\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"AIE corta previs\u00e3o para alta na demanda global por petr\u00f3leo em 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda\",\"name\":\"Poliana Santos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g\",\"caption\":\"Poliana Santos\"},\"description\":\"Rep\u00f3rter no Suno Not\u00edcias, com cobertura em mercado financeiro, economia, finan\u00e7as pessoais, renda fixa e varejo. Jornalista formada pela Faculdade C\u00e1sper L\u00edbero e possui passagem na R\u00e1dio Gazeta AM com a produ\u00e7\u00e3o de conte\u00fado sobre economia, pol\u00edtica, sa\u00fade, moda e m\u00fasica. Possui certificado de conclus\u00e3o do curso de An\u00e1lise de Balan\u00e7os pela Funda\u00e7\u00e3o Bradesco, Agenda Brasil pela FAAP, Educa\u00e7\u00e3o Pol\u00edtica por Alexandre Garcia e do Tesouro Direto e Mercado de A\u00e7\u00f5es pela B3.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AIE corta previs\u00e3o para alta na demanda global por petr\u00f3leo em 2021","description":"A AIE reduziu em 170 mil barris por dia sua previs\u00e3o para o crescimento da demanda global por petr\u00f3leo em 2021. Clique aqui e saiba mais","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/","og_locale":"pt_BR","og_type":"article","og_title":"AIE corta previs\u00e3o para alta na demanda global por petr\u00f3leo em 2021","og_description":"A AIE reduziu em 170 mil barris por dia sua previs\u00e3o para o crescimento da demanda global por petr\u00f3leo em 2021. Clique aqui e saiba mais","og_url":"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":713,"height":475,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/8c20298d-petroleo.jpg","type":"image\/jpeg"}],"author":"Poliana Santos","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Poliana Santos","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/"},"author":{"name":"Poliana Santos","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda"},"headline":"AIE corta previs\u00e3o para alta na demanda global por petr\u00f3leo em 2021","datePublished":"2020-12-15T16:49:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/"},"wordCount":512,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/8c20298d-petroleo-jpg.webp","keywords":["OPEP","Petr\u00f3leo","Petr\u00f3leo Brent"],"articleSection":["Mercado"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/","url":"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/","name":"AIE corta previs\u00e3o para alta na demanda global por petr\u00f3leo em 2021","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/8c20298d-petroleo-jpg.webp","datePublished":"2020-12-15T16:49:11+00:00","description":"A AIE reduziu em 170 mil barris por dia sua previs\u00e3o para o crescimento da demanda global por petr\u00f3leo em 2021. Clique aqui e saiba mais","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/8c20298d-petroleo-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/8c20298d-petroleo-jpg.webp","width":713,"height":475,"caption":"AIE corta previs\u00e3o para alta na demanda global por petr\u00f3leo em 2021"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Mercado","item":"https:\/\/www.suno.com.br\/noticias\/mercado\/"},{"@type":"ListItem","position":3,"name":"AIE corta previs\u00e3o para alta na demanda global por petr\u00f3leo em 2021"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/02ec1f752758247878a2bf4abee1aeda","name":"Poliana Santos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0645bd32f23d87b2130f2b2dff1d3f8d?s=96&r=g","caption":"Poliana Santos"},"description":"Rep\u00f3rter no Suno Not\u00edcias, com cobertura em mercado financeiro, economia, finan\u00e7as pessoais, renda fixa e varejo. Jornalista formada pela Faculdade C\u00e1sper L\u00edbero e possui passagem na R\u00e1dio Gazeta AM com a produ\u00e7\u00e3o de conte\u00fado sobre economia, pol\u00edtica, sa\u00fade, moda e m\u00fasica. Possui certificado de conclus\u00e3o do curso de An\u00e1lise de Balan\u00e7os pela Funda\u00e7\u00e3o Bradesco, Agenda Brasil pela FAAP, Educa\u00e7\u00e3o Pol\u00edtica por Alexandre Garcia e do Tesouro Direto e Mercado de A\u00e7\u00f5es pela B3.","url":"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/8c20298d-petroleo-400x200.webp\" alt=\"AIE corta previs\u00e3o para alta na demanda global por petr\u00f3leo em 2021\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/mercado\/\">Mercado<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/aie-revisao-demanda-global-petroleo\/\"><h2 class=\"content__title\">AIE corta previs\u00e3o para alta na demanda global por petr\u00f3leo em 2021<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/7ef34026-whatsapp-image-2020-08-03-at-12.37.57-150x150.webp\" alt=\"Poliana Santos\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/poliana-santos\/\"><span itemprop=\"author\">Poliana Santos<\/span><\/a><\/span><time datetime=\"2020-12-15T13:49:11-03:00\" itemprop=\"datePublished\">15\/12\/2020 13:49<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/108178"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=108178"}],"version-history":[{"count":0,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/108178\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/108324"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=108178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=108178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=108178"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=108178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}