{"id":107152,"date":"2020-12-10T15:50:23","date_gmt":"2020-12-10T18:50:23","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=107152"},"modified":"2021-06-13T23:28:51","modified_gmt":"2021-06-14T02:28:51","slug":"auxilio-desemprego-eua-semana-dezembro","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/","title":{"rendered":"Aux\u00edlio-desemprego: pedidos nos EUA avan\u00e7am 137 mil na semana, a 853 mil"},"content":{"rendered":"<p>O Departamento do Trabalho dos EUA informou nesta quinta-feira (10) que os novos pedidos de<a href=\"https:\/\/www.suno.com.br\/noticias\/tags\/seguro-desemprego\/\"><strong> aux\u00edlio-desemprego<\/strong><\/a> no Pa\u00eds cresceram 137 mil na semana encerrada em 5 de dezembro e chegaram a 853 mil.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/1d9788a3-auxiliodesemprego-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/1d9788a3-auxiliodesemprego-800x450.webp\" width=\"800\" height=\"450\" alt=\"Aux\u00edlio-desemprego: pedidos nos EUA avan\u00e7am 137 mil na semana, a 853 mil\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">O n\u00famero de pedidos de aux\u00edlio-desemprego ficou abaixo das expectativas.<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-controle-gastos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Planilha-controle-de-gastos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t\tdata-promo-id=\"101751\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>Contudo, o resultado da semana passada ficou abaixo da expectativa dos analistas consultados pelo &#8216;Wall Street Journal&#8217;, que previam 730 mil <strong>solicita\u00e7\u00f5es de aux\u00edlio-desemprego<\/strong> no per\u00edodo.<\/p>\n<p>Al\u00e9m disso, o Departamento do Trabalho revisou pra cima o total de solicita\u00e7\u00f5es do benef\u00edcio da semana anterior. Com isso, o n\u00famero de pedidos no per\u00edodo ficou em 716 mil, ante 712 mil.<\/p>\n<p>Por sua vez, o n\u00famero de pedidos continuados cresceu 230 mil, ficando em 5,757 milh\u00f5es, na semana que se encerrou em 28 de novembro.<\/p>\n<p><a href=\"https:\/\/lp.suno.com.br\/suno-one\/\">Suno One: acesse gratuitamente eBooks, Minicursos, Artigos e Video Aulas sobre investimentos com um \u00fanico cadastro. Clique para saber mais!<\/a><\/p>\n<p>Vale destacar que esse indicador \u00e9 divulgado com uma semana de atraso pelo Departamento do Trabalho dos <strong>EUA.<\/strong><\/p>\n<p>Al\u00e9m disso, o &#8216;<a href=\"https:\/\/www.suno.com.br\/artigos\/payroll\/\">Payroll,<\/a>&#8216; divulgado na semana passada, apontou que o Pa\u00eds norte-americano criou 245 mil <strong>empregos<\/strong> em novembro deste ano, enquanto a taxa de desemprego caiu de 6,9% em outubro, para 6,7% no m\u00eas passado.<\/p>\n<p>Especialistas consultados pelo Proje\u00e7\u00f5es Broadcast esperavam que os EUA criassem 450 mil novas vagas em novembro, ou seja, mais do que foram criadas.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-da-vida-financeira\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/400x300-Planilha-vida-financeira-true.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t\tdata-promo-id=\"106682\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/04\/1420x240-Planilha-vida-financeira-true.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>J\u00e1 a taxa de desemprego, caiu para al\u00e9m das expectativas dos especialistas, que esperavam o indicador em 6,8%.<\/p>\n<h2>Pedidos de aux\u00edlio-desemprego atingem menor n\u00edvel da pandemia nos EUA<\/h2>\n<p>No \u00faltimo dia 3, o departamento do Trabalho dos EUA havia divulgado dados informando que o n\u00famero de pedidos de seguro-desemprego nos Estados Unidos foi de 712 mil na \u00faltima semana de novembro, menor patamar desde o in\u00edcio da crise econ\u00f4mica causada pela<a href=\"https:\/\/www.suno.com.br\/noticias\/tags\/coronavirus\/\"> pandemia do <strong>coronav\u00edrus<\/strong> (Covid-19).<\/a><\/p>\n<p>Os n\u00fameros revelam uma queda consider\u00e1vel na compara\u00e7\u00e3o com a semana anterior, quando 787 mil pessoas fizeram novos <strong>pedidos de seguro-desemprego<\/strong>.<\/p>\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Veja tamb\u00e9m<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/desemprego-eua-criaram-empregos-novembro\/\">\n\t\t\tDesemprego: EUA criaram 245 mil empregos em novembro\t\t<\/a>\n\t<\/div>\n\n\n<p>Al\u00e9m disso, o n\u00famero de pedidos pelo <strong>aux\u00edlio-desemprego<\/strong> especial da pandemia, que d\u00e1 benef\u00edcios para aqueles que normalmente estariam aptos a trabalhar, tamb\u00e9m caiu naquela semana, chegando a 288,701. Para o programa de emerg\u00eancia, que perderam seus benef\u00edcios normais, houve alta de 60 mil nos pedidos.<\/p>\n<p><em>Com informa\u00e7\u00f5es do Estad\u00e3o Conte\u00fado.<\/em><\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-de-controle-de-investimentos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Controle-de-Investimentos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t\tdata-promo-id=\"75934\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>O Departamento do Trabalho dos EUA informou nesta quinta-feira (10) que os novos pedidos de aux\u00edlio-desemprego no Pa\u00eds cresceram 137 mil na semana encerrada em 5 de dezembro e chegaram a 853 mil. O n\u00famero de pedidos de aux\u00edlio-desemprego ficou abaixo das expectativas. Contudo, o resultado da semana passada ficou abaixo da expectativa dos analistas [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":107179,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[63],"tags":[1296,793,2274],"suno_strategy":[],"class_list":["post-107152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-desemprego","tag-estados-unidos-eua","tag-seguro-desemprego"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aux\u00edlio-desemprego: pedidos nos EUA avan\u00e7am 137 mil na semana<\/title>\n<meta name=\"description\" content=\"Os novos pedidos de aux\u00edlio-desemprego nos EUA cresceram 137 mil, a 853 mil, na semana encerrada em 5 de dezembro. Clique aqui e saiba mais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aux\u00edlio-desemprego: pedidos nos EUA avan\u00e7am 137 mil na semana\" \/>\n<meta property=\"og:description\" content=\"Os novos pedidos de aux\u00edlio-desemprego nos EUA cresceram 137 mil, a 853 mil, na semana encerrada em 5 de dezembro. Clique aqui e saiba mais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/1d9788a3-auxiliodesemprego.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Laura Moutinho\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laura Moutinho\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/\"},\"author\":{\"name\":\"Laura Moutinho\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/3df0d2808748b74496efe5dbeaef2c72\"},\"headline\":\"Aux\u00edlio-desemprego: pedidos nos EUA avan\u00e7am 137 mil na semana, a 853 mil\",\"datePublished\":\"2020-12-10T18:50:23+00:00\",\"dateModified\":\"2021-06-14T02:28:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/\"},\"wordCount\":404,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/1d9788a3-auxiliodesemprego-jpg.webp\",\"keywords\":[\"Desemprego\",\"Estados Unidos (EUA)\",\"seguro desemprego\"],\"articleSection\":[\"Internacional\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/\",\"name\":\"Aux\u00edlio-desemprego: pedidos nos EUA avan\u00e7am 137 mil na semana\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/1d9788a3-auxiliodesemprego-jpg.webp\",\"datePublished\":\"2020-12-10T18:50:23+00:00\",\"dateModified\":\"2021-06-14T02:28:51+00:00\",\"description\":\"Os novos pedidos de aux\u00edlio-desemprego nos EUA cresceram 137 mil, a 853 mil, na semana encerrada em 5 de dezembro. Clique aqui e saiba mais.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/1d9788a3-auxiliodesemprego-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/1d9788a3-auxiliodesemprego-jpg.webp\",\"width\":960,\"height\":640,\"caption\":\"O n\u00famero de pedidos de aux\u00edlio-desemprego ficou abaixo das expectativas.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Internacional\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/internacional\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aux\u00edlio-desemprego: pedidos nos EUA avan\u00e7am 137 mil na semana, a 853 mil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/3df0d2808748b74496efe5dbeaef2c72\",\"name\":\"Laura Moutinho\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7571c7c8ca3a6fca5e41384ece5557ff?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7571c7c8ca3a6fca5e41384ece5557ff?s=96&r=g\",\"caption\":\"Laura Moutinho\"},\"description\":\"Estagi\u00e1ria na Suno Not\u00edcias, escreve not\u00edcias que afetam o mercado financeiro. Estuda administra\u00e7\u00e3o na Universidade Presbiteriana Mackenzie.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/laura-moutinho\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aux\u00edlio-desemprego: pedidos nos EUA avan\u00e7am 137 mil na semana","description":"Os novos pedidos de aux\u00edlio-desemprego nos EUA cresceram 137 mil, a 853 mil, na semana encerrada em 5 de dezembro. Clique aqui e saiba mais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/","og_locale":"pt_BR","og_type":"article","og_title":"Aux\u00edlio-desemprego: pedidos nos EUA avan\u00e7am 137 mil na semana","og_description":"Os novos pedidos de aux\u00edlio-desemprego nos EUA cresceram 137 mil, a 853 mil, na semana encerrada em 5 de dezembro. Clique aqui e saiba mais.","og_url":"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":960,"height":640,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/1d9788a3-auxiliodesemprego.jpg","type":"image\/jpeg"}],"author":"Laura Moutinho","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Laura Moutinho","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/"},"author":{"name":"Laura Moutinho","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/3df0d2808748b74496efe5dbeaef2c72"},"headline":"Aux\u00edlio-desemprego: pedidos nos EUA avan\u00e7am 137 mil na semana, a 853 mil","datePublished":"2020-12-10T18:50:23+00:00","dateModified":"2021-06-14T02:28:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/"},"wordCount":404,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/1d9788a3-auxiliodesemprego-jpg.webp","keywords":["Desemprego","Estados Unidos (EUA)","seguro desemprego"],"articleSection":["Internacional"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/","url":"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/","name":"Aux\u00edlio-desemprego: pedidos nos EUA avan\u00e7am 137 mil na semana","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/1d9788a3-auxiliodesemprego-jpg.webp","datePublished":"2020-12-10T18:50:23+00:00","dateModified":"2021-06-14T02:28:51+00:00","description":"Os novos pedidos de aux\u00edlio-desemprego nos EUA cresceram 137 mil, a 853 mil, na semana encerrada em 5 de dezembro. Clique aqui e saiba mais.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/1d9788a3-auxiliodesemprego-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/1d9788a3-auxiliodesemprego-jpg.webp","width":960,"height":640,"caption":"O n\u00famero de pedidos de aux\u00edlio-desemprego ficou abaixo das expectativas."},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Internacional","item":"https:\/\/www.suno.com.br\/noticias\/internacional\/"},{"@type":"ListItem","position":3,"name":"Aux\u00edlio-desemprego: pedidos nos EUA avan\u00e7am 137 mil na semana, a 853 mil"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/3df0d2808748b74496efe5dbeaef2c72","name":"Laura Moutinho","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7571c7c8ca3a6fca5e41384ece5557ff?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7571c7c8ca3a6fca5e41384ece5557ff?s=96&r=g","caption":"Laura Moutinho"},"description":"Estagi\u00e1ria na Suno Not\u00edcias, escreve not\u00edcias que afetam o mercado financeiro. Estuda administra\u00e7\u00e3o na Universidade Presbiteriana Mackenzie.","url":"https:\/\/www.suno.com.br\/noticias\/author\/laura-moutinho\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/12\/1d9788a3-auxiliodesemprego-400x200.webp\" alt=\"Aux\u00edlio-desemprego: pedidos nos EUA avan\u00e7am 137 mil na semana, a 853 mil\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/internacional\/\">Internacional<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/auxilio-desemprego-eua-semana-dezembro\/\"><h2 class=\"content__title\">Aux\u00edlio-desemprego: pedidos nos EUA avan\u00e7am 137 mil na semana, a 853 mil<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/laura-moutinho\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/531ff69d-whatsapp-image-2020-08-03-at-14.54.38-150x150.webp\" alt=\"Laura Moutinho\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/laura-moutinho\/\"><span itemprop=\"author\">Laura Moutinho<\/span><\/a><\/span><time datetime=\"2020-12-10T15:50:23-03:00\" itemprop=\"datePublished\">10\/12\/2020 15:50<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/107152"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=107152"}],"version-history":[{"count":1,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/107152\/revisions"}],"predecessor-version":[{"id":156770,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/107152\/revisions\/156770"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/107179"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=107152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=107152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=107152"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=107152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}