{"id":103279,"date":"2020-11-26T09:25:04","date_gmt":"2020-11-26T12:25:04","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=103279"},"modified":"2021-02-17T23:05:43","modified_gmt":"2021-02-18T02:05:43","slug":"guararapes-guar3-jcp","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/","title":{"rendered":"Guararapes (GUAR3) aprova pagamento de R$ 202,5 milh\u00f5es em JCP"},"content":{"rendered":"<p>A <a href=\"https:\/\/www.suno.com.br\/acoes\/guar3\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Guararapes<\/strong> (GUAR3)<\/a> aprovou o pagamento de<a href=\"https:\/\/www.suno.com.br\/artigos\/entenda-o-jcp\/\" target=\"_blank\" rel=\"noopener noreferrer\"> juros sobre o capital pr\u00f3prio (JCP)<\/a> de R$ 202,5 milh\u00f5es, correspondentes a R$ 0,4058 por a\u00e7\u00e3o da companhia. De acordo com<a href=\"https:\/\/www.suno.com.br\/artigos\/fato-relevante\/\" target=\"_blank\" rel=\"noopener noreferrer\"> fato relevante<\/a> enviado \u00e0 <a href=\"https:\/\/www.suno.com.br\/artigos\/cvm\/\" target=\"_blank\" rel=\"noopener noreferrer\">Comiss\u00e3o de Valores Mobili\u00e1rios (CVM)<\/a>, os JCP ser\u00e3o imputados ao dividendo obrigat\u00f3rio do exerc\u00edcio de 2020.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/88202602-riachuelo-300x300-1-jpg.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/88202602-riachuelo-300x300-1-jpg.webp\" width=\"800\" height=\"450\" alt=\"Guararapes (GUAR3) aprova pagamento de R$ 202,5 milh\u00f5es em JCP\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">Riachuelo busca formas de chegar ao que cliente procura durante a pandemia<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n<p><span style=\"font-weight: 400;\">\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-controle-gastos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Planilha-controle-de-gastos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t\tdata-promo-id=\"101751\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n<\/span><\/p>\n<p>A data de pagamento ser\u00e1 definida na <a href=\"https:\/\/www.suno.com.br\/artigos\/assembleia-geral-ordinaria\/\" target=\"_blank\" rel=\"noopener noreferrer\">Assembleia Geral Ordin\u00e1ria<\/a> de 2021. Far\u00e3o jus aos juros os <a href=\"https:\/\/www.suno.com.br\/artigos\/acionista-companhias-abertas\/\" target=\"_blank\" rel=\"noopener noreferrer\">acionistas<\/a> da companhia detentores de a\u00e7\u00f5es em 30 de novembro de 2020. A partir de 1\u00ba de dezembro (inclusive), as a\u00e7\u00f5es ser\u00e3o negociadas &#8220;ex-JCP&#8221;.<\/p>\n<h2>Guararapes registrou preju\u00edzo no terceiro trimestre<\/h2>\n<p>No \u00faltimo dia 11, a Guararapes divulgou seus resultados no terceiro trimestre desse ano. A dona da <strong>Riachuelo<\/strong>\u00a0reportou preju\u00edzo de R$ 51,4 milh\u00f5es no per\u00edodo, revertend<a href=\"https:\/\/www.suno.com.br\/artigos\/lucro-liquido\/\">o lucro l\u00edquido<\/a> de R$ 67,9 milh\u00f5es registrado no mesmo per\u00edodo em 2019.<\/p>\n<p><span style=\"font-weight: 400;\">\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-controle-gastos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Planilha-controle-de-gastos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t\tdata-promo-id=\"101751\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n<\/span><\/p>\n<p>A <strong>Guararapes<\/strong>\u00a0apontou que sua\u00a0<a href=\"https:\/\/www.suno.com.br\/artigos\/o-que-receita-liquida\/\"><strong>receita l\u00edquida<\/strong><\/a>\u00a0entre julho e setembro desse ano ficou em R$ 1,523 bilh\u00e3o, sendo 19,2% menor que os R$ 1,885 bilh\u00e3o apurados no mesmo per\u00edodo de 2019.<\/p>\n<p>O\u00a0<a href=\"https:\/\/www.suno.com.br\/artigos\/ebitda\/\"><strong>Ebitda<\/strong>\u00a0(lucros antes de juros, impostos, deprecia\u00e7\u00e3o e amortiza\u00e7\u00e3o)<\/a>, por sua vez, finalizou o semestre em 84,153 milh\u00f5es, com queda de 66,9% na compara\u00e7\u00e3o anualizada.\u00a0As vendas do e-commerce saltaram 380% no terceiro trimestre e passaram a representar 12% das vendas totais da\u00a0<strong>Guararapes.<\/strong><\/p>\n<p>A\u00a0Guararapes\u00a0produziu 11,3 milh\u00f5es de pe\u00e7as de julho a setembro, queda de 13% frente aos 12,9 milh\u00f5es do terceiro trimestre de 2019. As unidades representaram 30,3% da venda total da Riachuelo.<\/p>\n<p>Al\u00e9m disso, a <strong>Guararapes<\/strong> informou, em outubro, que seu <a href=\"https:\/\/www.suno.com.br\/artigos\/conselho-administracao\/\">conselho de administra\u00e7\u00e3o<\/a>\u00a0decidiu dar in\u00edcio aos procedimentos de necess\u00e1rios para a migra\u00e7\u00e3o da companhia para o\u00a0<a href=\"https:\/\/www.suno.com.br\/artigos\/novo-mercado\/\">Novo Mercado<\/a>\u00a0da\u00a0<a href=\"https:\/\/www.suno.com.br\/artigos\/b3\/\">B3<\/a>. Vale destacar que para se listar no\u00a0Novo Mercado<strong>,<\/strong>\u00a0\u00e9 necess\u00e1rio converter as<a href=\"https:\/\/www.suno.com.br\/artigos\/acoes-ordinarias\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u00a0a\u00e7\u00f5es ordin\u00e1rias<\/a>\u00a0em\u00a0<a href=\"https:\/\/www.suno.com.br\/artigos\/acoes-preferenciais\/\" target=\"_blank\" rel=\"noopener noreferrer\">preferenciais<\/a><strong>,<\/strong> al\u00e9m de adotar pr\u00e1ticas de <a href=\"https:\/\/www.suno.com.br\/artigos\/governanca-corporativa\/\" target=\"_blank\" rel=\"noopener noreferrer\">governan\u00e7a corporativa<\/a> que s\u00e3o complementares \u00e0s exigidas por lei.<\/p>\n<p><span style=\"font-weight: 400;\">\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-de-controle-de-investimentos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Controle-de-Investimentos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t\tdata-promo-id=\"75934\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Guararapes (GUAR3) aprovou o pagamento de juros sobre o capital pr\u00f3prio (JCP) de R$ 202,5 milh\u00f5es, correspondentes a R$ 0,4058 por a\u00e7\u00e3o da companhia. De acordo com fato relevante enviado \u00e0 Comiss\u00e3o de Valores Mobili\u00e1rios (CVM), os JCP ser\u00e3o imputados ao dividendo obrigat\u00f3rio do exerc\u00edcio de 2020. Riachuelo busca formas de chegar ao que [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":80932,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[64],"tags":[295,494,1957],"suno_strategy":[],"class_list":["post-103279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-dividendos","tag-guararapes-guar3","tag-juros-sobre-capital-proprio-jcp"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Guararapes (GUAR3) aprova pagamento de R$ 202,5 milh\u00f5es em JCP<\/title>\n<meta name=\"description\" content=\"A Guararapes (GUAR3) aprovou o pagamento de juros sobre o capital pr\u00f3prio (JCP) de R$ 202,5 milh\u00f5es. Clique para saber mais informa\u00e7\u00f5es.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guararapes (GUAR3) aprova pagamento de R$ 202,5 milh\u00f5es em JCP\" \/>\n<meta property=\"og:description\" content=\"A Guararapes (GUAR3) aprovou o pagamento de juros sobre o capital pr\u00f3prio (JCP) de R$ 202,5 milh\u00f5es. Clique para saber mais informa\u00e7\u00f5es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/88202602-riachuelo-300x300-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Natalia G\u00f3mez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Natalia G\u00f3mez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/\"},\"author\":{\"name\":\"Natalia G\u00f3mez\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1b24d67c140a42e864ef414497edb164\"},\"headline\":\"Guararapes (GUAR3) aprova pagamento de R$ 202,5 milh\u00f5es em JCP\",\"datePublished\":\"2020-11-26T12:25:04+00:00\",\"dateModified\":\"2021-02-18T02:05:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/\"},\"wordCount\":340,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/88202602-riachuelo-300x300-1-jpg.webp\",\"keywords\":[\"dividendos\",\"Guararapes (GUAR3)\",\"juros sobre capital pr\u00f3prio (JCP)\"],\"articleSection\":[\"Neg\u00f3cios\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/\",\"name\":\"Guararapes (GUAR3) aprova pagamento de R$ 202,5 milh\u00f5es em JCP\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/88202602-riachuelo-300x300-1-jpg.webp\",\"datePublished\":\"2020-11-26T12:25:04+00:00\",\"dateModified\":\"2021-02-18T02:05:43+00:00\",\"description\":\"A Guararapes (GUAR3) aprovou o pagamento de juros sobre o capital pr\u00f3prio (JCP) de R$ 202,5 milh\u00f5es. Clique para saber mais informa\u00e7\u00f5es.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/88202602-riachuelo-300x300-1-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/88202602-riachuelo-300x300-1-jpg.webp\",\"width\":300,\"height\":300,\"caption\":\"Riachuelo busca formas de chegar ao que cliente procura durante a pandemia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neg\u00f3cios\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/negocios\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Guararapes (GUAR3) aprova pagamento de R$ 202,5 milh\u00f5es em JCP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1b24d67c140a42e864ef414497edb164\",\"name\":\"Natalia G\u00f3mez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9e957e0b2b485c2d42c3f4145c16d940?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9e957e0b2b485c2d42c3f4145c16d940?s=96&r=g\",\"caption\":\"Natalia G\u00f3mez\"},\"description\":\"Editora do Suno Not\u00edcias desde outubro de 2020, \u00e9 jornalista formada pela PUC-SP, com p\u00f3s-gradua\u00e7\u00e3o em jornalismo liter\u00e1rio. Atua no mercado financeiro desde 2003, quando iniciou a carreira no jornal econ\u00f4mico DCI, cobrindo o setor de alimentos no caderno de Ind\u00fastria. Foi trainee do jornal Valor Econ\u00f4mico, onde atuou no Caderno de Empresas por quase tr\u00eas anos. L\u00e1, cobriu o setor de ind\u00fastria, com foco em siderurgia, embalagens e aeroespacial. Fez coberturas setoriais em viagens para S\u00e3o Jos\u00e9 dos Campos e Franca (SP), al\u00e9m de coberturas internacionais na Alemanha e na Su\u00e9cia. Trabalhou por cinco anos na Ag\u00eancia Estado\/Broadcast, do Grupo Estado, onde foi rep\u00f3rter dos setores de minera\u00e7\u00e3o e siderurgia, alimentos e bebidas e finan\u00e7as. Foi premiada como o pr\u00eamio Destaque de Reportagem da AE em 2007 e 2008. Al\u00e9m de atuar no servi\u00e7o de not\u00edcias em tempo real, fez participa\u00e7\u00f5es no caderno de Economia do jornal Estado de S.Paulo e na R\u00e1dio Eldorado. Ainda no Grupo Estado, foi editora assistente da editoria Empresas e Setores, atuando com edi\u00e7\u00e3o e pauta, al\u00e9m de cobrir mercados diariamente com o cen\u00e1rio de bolsa e fazer reportagens especiais com foco em governan\u00e7a corporativa. Trabalhou tamb\u00e9m como correspondente de finan\u00e7as no servi\u00e7o da Thomson Reuters em portugu\u00eas por quase um ano. Atuou por cerca de oito anos como jornalista independente, contribuindo para ve\u00edculos como UOL Economia, Infomoney e Revista Voc\u00ea SA, al\u00e9m de ter trabalhado em projetos na \u00e1rea de conte\u00fado e comunica\u00e7\u00e3o de institui\u00e7\u00f5es financeiras como Anbima, Banco BS2, Banco Pine, Ita\u00fa BBA e EQI.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/natalia-gomez\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guararapes (GUAR3) aprova pagamento de R$ 202,5 milh\u00f5es em JCP","description":"A Guararapes (GUAR3) aprovou o pagamento de juros sobre o capital pr\u00f3prio (JCP) de R$ 202,5 milh\u00f5es. Clique para saber mais informa\u00e7\u00f5es.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/","og_locale":"pt_BR","og_type":"article","og_title":"Guararapes (GUAR3) aprova pagamento de R$ 202,5 milh\u00f5es em JCP","og_description":"A Guararapes (GUAR3) aprovou o pagamento de juros sobre o capital pr\u00f3prio (JCP) de R$ 202,5 milh\u00f5es. Clique para saber mais informa\u00e7\u00f5es.","og_url":"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":300,"height":300,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/88202602-riachuelo-300x300-1.jpg","type":"image\/jpeg"}],"author":"Natalia G\u00f3mez","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Natalia G\u00f3mez","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/"},"author":{"name":"Natalia G\u00f3mez","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1b24d67c140a42e864ef414497edb164"},"headline":"Guararapes (GUAR3) aprova pagamento de R$ 202,5 milh\u00f5es em JCP","datePublished":"2020-11-26T12:25:04+00:00","dateModified":"2021-02-18T02:05:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/"},"wordCount":340,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/88202602-riachuelo-300x300-1-jpg.webp","keywords":["dividendos","Guararapes (GUAR3)","juros sobre capital pr\u00f3prio (JCP)"],"articleSection":["Neg\u00f3cios"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/","url":"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/","name":"Guararapes (GUAR3) aprova pagamento de R$ 202,5 milh\u00f5es em JCP","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/88202602-riachuelo-300x300-1-jpg.webp","datePublished":"2020-11-26T12:25:04+00:00","dateModified":"2021-02-18T02:05:43+00:00","description":"A Guararapes (GUAR3) aprovou o pagamento de juros sobre o capital pr\u00f3prio (JCP) de R$ 202,5 milh\u00f5es. Clique para saber mais informa\u00e7\u00f5es.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/88202602-riachuelo-300x300-1-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/88202602-riachuelo-300x300-1-jpg.webp","width":300,"height":300,"caption":"Riachuelo busca formas de chegar ao que cliente procura durante a pandemia"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Neg\u00f3cios","item":"https:\/\/www.suno.com.br\/noticias\/negocios\/"},{"@type":"ListItem","position":3,"name":"Guararapes (GUAR3) aprova pagamento de R$ 202,5 milh\u00f5es em JCP"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/1b24d67c140a42e864ef414497edb164","name":"Natalia G\u00f3mez","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9e957e0b2b485c2d42c3f4145c16d940?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9e957e0b2b485c2d42c3f4145c16d940?s=96&r=g","caption":"Natalia G\u00f3mez"},"description":"Editora do Suno Not\u00edcias desde outubro de 2020, \u00e9 jornalista formada pela PUC-SP, com p\u00f3s-gradua\u00e7\u00e3o em jornalismo liter\u00e1rio. Atua no mercado financeiro desde 2003, quando iniciou a carreira no jornal econ\u00f4mico DCI, cobrindo o setor de alimentos no caderno de Ind\u00fastria. Foi trainee do jornal Valor Econ\u00f4mico, onde atuou no Caderno de Empresas por quase tr\u00eas anos. L\u00e1, cobriu o setor de ind\u00fastria, com foco em siderurgia, embalagens e aeroespacial. Fez coberturas setoriais em viagens para S\u00e3o Jos\u00e9 dos Campos e Franca (SP), al\u00e9m de coberturas internacionais na Alemanha e na Su\u00e9cia. Trabalhou por cinco anos na Ag\u00eancia Estado\/Broadcast, do Grupo Estado, onde foi rep\u00f3rter dos setores de minera\u00e7\u00e3o e siderurgia, alimentos e bebidas e finan\u00e7as. Foi premiada como o pr\u00eamio Destaque de Reportagem da AE em 2007 e 2008. Al\u00e9m de atuar no servi\u00e7o de not\u00edcias em tempo real, fez participa\u00e7\u00f5es no caderno de Economia do jornal Estado de S.Paulo e na R\u00e1dio Eldorado. Ainda no Grupo Estado, foi editora assistente da editoria Empresas e Setores, atuando com edi\u00e7\u00e3o e pauta, al\u00e9m de cobrir mercados diariamente com o cen\u00e1rio de bolsa e fazer reportagens especiais com foco em governan\u00e7a corporativa. Trabalhou tamb\u00e9m como correspondente de finan\u00e7as no servi\u00e7o da Thomson Reuters em portugu\u00eas por quase um ano. Atuou por cerca de oito anos como jornalista independente, contribuindo para ve\u00edculos como UOL Economia, Infomoney e Revista Voc\u00ea SA, al\u00e9m de ter trabalhado em projetos na \u00e1rea de conte\u00fado e comunica\u00e7\u00e3o de institui\u00e7\u00f5es financeiras como Anbima, Banco BS2, Banco Pine, Ita\u00fa BBA e EQI.","url":"https:\/\/www.suno.com.br\/noticias\/author\/natalia-gomez\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/08\/88202602-riachuelo-300x300-1-jpg.webp\" alt=\"Guararapes (GUAR3) aprova pagamento de R$ 202,5 milh\u00f5es em JCP\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/negocios\/\">Neg\u00f3cios<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/guararapes-guar3-jcp\/\"><h2 class=\"content__title\">Guararapes (GUAR3) aprova pagamento de R$ 202,5 milh\u00f5es em JCP<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/natalia-gomez\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/secure.gravatar.com\/avatar\/9e957e0b2b485c2d42c3f4145c16d940?s=96&#038;r=g\" alt=\"Natalia G\u00f3mez\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/natalia-gomez\/\"><span itemprop=\"author\">Natalia G\u00f3mez<\/span><\/a><\/span><time datetime=\"2020-11-26T09:25:04-03:00\" itemprop=\"datePublished\">26\/11\/2020 09:25<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/103279"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=103279"}],"version-history":[{"count":0,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/103279\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/80932"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=103279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=103279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=103279"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=103279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}