{"id":102384,"date":"2020-11-23T15:17:08","date_gmt":"2020-11-23T18:17:08","guid":{"rendered":"https:\/\/www.suno.com.br\/noticias\/?p=102384"},"modified":"2021-06-13T23:29:27","modified_gmt":"2021-06-14T02:29:27","slug":"eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit","status":"publish","type":"post","link":"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/","title":{"rendered":"EUA: Ind\u00fastria e servi\u00e7os est\u00e3o se recuperando, diz IHS Markit"},"content":{"rendered":"<p>A IHS Markit divulgou nesta segunda-feira (23) dados preliminares sobre a\u00a0atividade econ\u00f4mica no setor privado dos <strong>EUA<\/strong>, revelando que houve uma alta na ind\u00fastria e no setor de servi\u00e7os em novembro, apesar do aumento de <a href=\"https:\/\/www.suno.com.br\/noticias\/tags\/coronavirus\/\">casos de covid-19<\/a> no pa\u00eds.<\/p>\t<div class=\"wrapper-featured-image\">\n\t\t<figure class=\"spotlightImg\">\n\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 768px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/11\/26e28569-eua-2-400x200.webp\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"newsContent__article__imgCapa lazyloadDisabled \" src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/11\/26e28569-eua-2-jpg.webp\" width=\"800\" height=\"450\" alt=\"EUA: Ind\u00fastria e servi\u00e7os est\u00e3o se recuperando, diz IHS Markit\" fetchpriority=high \/>\n\t\t\t<\/picture>\n\n\t\t\t<figcaption class=\"wp-caption-text wp-caption-text--show\">EUA: Ind\u00fastria e servi\u00e7os est\u00e3o se recuperando, diz IHS Markit<\/figcaption>\n\t\t<\/figure>\n\t<\/div>\n\n\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-controle-gastos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Planilha-controle-de-gastos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t\tdata-promo-id=\"101751\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>De acordo com o relat\u00f3rio, o <strong>\u00cdndice de Gerente de Compras<\/strong> (PMI, na sigla em ingl\u00eas) industrial nos EUA, subiu para 56,7 pontos neste m\u00eas, ante 53,3 em outubro. O resultado foi melhor que o projetado por economistas consultados pelo \u201cWall Street Journal\u201d, que previam uma leve redu\u00e7\u00e3o para 53 pontos.<\/p>\n<p>Al\u00e9m disso, o <strong>PMI de servi\u00e7os<\/strong> tamb\u00e9m subiu para 57,7 pontos em novembro, de 56,9 em outubro, segundo os dados preliminares da IHS Markit. Desta forma, o PMI composto, que inclui ind\u00fastria e servi\u00e7os, aumentou para 57,9 neste m\u00eas, ap\u00f3s marcar 56,3 em outubro. Leituras acima de 50 indicam expans\u00e3o da atividade, enquanto abaixo de 50 apontam contra\u00e7\u00e3o.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-controle-gastos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Planilha-controle-de-gastos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t\tdata-promo-id=\"101751\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Planilha-controle-de-gastos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n<p>\u201cA atividade empresarial em ambos, ind\u00fastria e servi\u00e7os, subiu em novembro no ritmo mais forte desde mar\u00e7o de 2015. A recupera\u00e7\u00e3o refletiu um maior fortalecimento da demanda, que, por sua vez, encorajou as empresas a contratar funcion\u00e1rios a uma taxa n\u00e3o vista anteriormente desde o in\u00edcio da pesquisa em 2009\u201d, informou em nota o economista-chefe da <strong>IHS Markit<\/strong>, Chris Williamson.<\/p>\n<h2>EUA: economia pode encolher no 1\u00ba tri de 2021, aponta JPMorgan<\/h2>\n<p>A economia dos <strong>EUA <\/strong>deve recuar a uma taxa anualizada de 1% no primeiro trimestre do ano que vem em fun\u00e7\u00e3o das novas medidas de restri\u00e7\u00e3o em diversos estados para barrar a segunda de covid-19. \u00c9 o que apontam os analistas do JPMorgan, segundo informa\u00e7\u00f5es divulgadas pelo jornal &#8220;Valor Econ\u00f4mico&#8221;.<\/p>\n<p><a href=\"https:\/\/lp.suno.com.br\/suno-one\/\">Suno One: acesse gratuitamente eBooks, Minicursos, Artigos e Video Aulas sobre investimentos com um \u00fanico cadastro. Clique para saber mais!<\/a><\/p>\n<p>De acordo com relat\u00f3rio do <strong>JPMorgan\u00a0<\/strong>da \u00faltima sexta-feira (20), os analistas esperam um crescimento de 2,8% do <a href=\"https:\/\/www.suno.com.br\/artigos\/pib-produto-interno-bruto\/\">Produto Interno Bruto (PIB)<\/a> no quarto trimestre de 2020. O avan\u00e7o viria depois de uma expans\u00e3o de 33,1% na economia dos EUA no per\u00edodo entre julho e setembro.<\/p>\n<p>Os Estados Unidos n\u00e3o possuem mais \u201co vento a favor\u201d que os empurraram ap\u00f3s a reabertura econ\u00f4mica, avaliaram os economistas do banco Michael Feroli, Jesse Edgerton e Daniel Silver.<\/p>\n<p>Segundo os especialistas, a recupera\u00e7\u00e3o mais forte do que aquela esperada pelos analistas em raz\u00e3o do grande pacote de est\u00edmulos aprovado pelo Congresso no in\u00edcio da crise e da <a href=\"https:\/\/www.suno.com.br\/artigos\/politica-monetaria\/\">pol\u00edtica monet\u00e1ria expansiva<\/a> adotada pelo <a href=\"https:\/\/www.suno.com.br\/artigos\/fed\/\">Federal Reserve (Fed)<\/a>.<\/p>\n\t<div data-element=\"shortcode-read-more\" class=\"knowMore\">\n\t\t\t\t<span class=\"knowMore__title\">Saiba mais<\/span>\n\t\t\t\t<a class=\"knowMore__link\" href=\"https:\/\/www.suno.com.br\/noticias\/economia-eua-pode-encolher-2021\/\">\n\t\t\tEUA: economia pode encolher no 1\u00ba tri de 2021, aponta JPMorgan\t\t<\/a>\n\t<\/div>\n\n\n<p>O cen\u00e1rio era bem diferente do que vemos atualmente. Al\u00e9m da volta do coronav\u00edrus \u00e0s ruas norte-americanas, o Parlamento se mant\u00e9m em um impasse que j\u00e1 dura meses, enquanto democratas e republicanos divergem sobre qual deve ser o tamanho do pr\u00f3ximo pacote de al\u00edvio.<\/p>\n<p>Na sexta-feira, o secret\u00e1rio do Tesouro dos <strong>EUA<\/strong>, Steven Mnuchin, sinalizou que poderia reabrir as discuss\u00f5es com a oposi\u00e7\u00e3o, por\u00e9m indicou que o projeto poder\u00e1 ser menos ambicioso do que o desejado.<\/p>\n\t<p>\n\t\t<a href=\"https:\/\/lp.suno.com.br\/planilha-de-controle-de-investimentos\/\" target=\"_blank\" data-element=\"shortcode-suno-banner\" title=\"Banner SUNO, clique e saiba mais\">\n\t\t\t<picture>\n\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/400x300-Controle-de-Investimentos.png\">\n\t\t\t\t<img class=\"newsContent__article__imgCapa newsContent__article__imgCapa--banner\"\n\t\t\t\t\tsrc=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t\tdata-promo-id=\"75934\"\t\t\t\t\t\t\t\t\t\twidth='1420' height='240'\t\t\t\t\talt=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2023\/03\/1420x240-Controle-de-Investimentos.png\"\n\t\t\t\t>\n\t\t\t<\/picture>\n\t\t<\/a>\n\t<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>A IHS Markit divulgou nesta segunda-feira (23) dados preliminares sobre a\u00a0atividade econ\u00f4mica no setor privado dos EUA, revelando que houve uma alta na ind\u00fastria e no setor de servi\u00e7os em novembro, apesar do aumento de casos de covid-19 no pa\u00eds. EUA: Ind\u00fastria e servi\u00e7os est\u00e3o se recuperando, diz IHS Markit De acordo com o relat\u00f3rio, [&hellip;]<\/p>\n","protected":false},"author":56,"featured_media":102388,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[63],"tags":[740,793],"suno_strategy":[],"class_list":["post-102384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-economia","tag-estados-unidos-eua"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EUA: Ind\u00fastria e servi\u00e7os est\u00e3o se recuperando, diz IHS Markit<\/title>\n<meta name=\"description\" content=\"A\u00a0atividade econ\u00f4mica no setor privado dos EUA teve alta em novembro, apesar do aumento de casos de covid-19. Clique aqui para saber mais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EUA: Ind\u00fastria e servi\u00e7os est\u00e3o se recuperando, diz IHS Markit\" \/>\n<meta property=\"og:description\" content=\"A\u00a0atividade econ\u00f4mica no setor privado dos EUA teve alta em novembro, apesar do aumento de casos de covid-19. Clique aqui para saber mais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/\" \/>\n<meta property=\"og:site_name\" content=\"Suno Not\u00edcias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/sunoresearch\" \/>\n<meta property=\"og:image\" content=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/11\/26e28569-eua-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rafaela La Regina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:site\" content=\"@sunoresearch\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rafaela La Regina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/\"},\"author\":{\"name\":\"Rafaela La Regina\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/e672ca8cea627fe715fa29bca7da95e0\"},\"headline\":\"EUA: Ind\u00fastria e servi\u00e7os est\u00e3o se recuperando, diz IHS Markit\",\"datePublished\":\"2020-11-23T18:17:08+00:00\",\"dateModified\":\"2021-06-14T02:29:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/\"},\"wordCount\":539,\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/11\/26e28569-eua-2-jpg.webp\",\"keywords\":[\"Economia\",\"Estados Unidos (EUA)\"],\"articleSection\":[\"Internacional\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/\",\"name\":\"EUA: Ind\u00fastria e servi\u00e7os est\u00e3o se recuperando, diz IHS Markit\",\"isPartOf\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/11\/26e28569-eua-2-jpg.webp\",\"datePublished\":\"2020-11-23T18:17:08+00:00\",\"dateModified\":\"2021-06-14T02:29:27+00:00\",\"description\":\"A\u00a0atividade econ\u00f4mica no setor privado dos EUA teve alta em novembro, apesar do aumento de casos de covid-19. Clique aqui para saber mais.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/#primaryimage\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/11\/26e28569-eua-2-jpg.webp\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/11\/26e28569-eua-2-jpg.webp\",\"width\":800,\"height\":450,\"caption\":\"EUA: Ind\u00fastria e servi\u00e7os est\u00e3o se recuperando, diz IHS Markit\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Not\u00edcias\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Internacional\",\"item\":\"https:\/\/www.suno.com.br\/noticias\/internacional\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"EUA: Ind\u00fastria e servi\u00e7os est\u00e3o se recuperando, diz IHS Markit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#website\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"name\":\"Suno Not\u00edcias\",\"description\":\"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos\",\"publisher\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#organization\",\"name\":\"Suno Not\u00edcias\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"contentUrl\":\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png\",\"width\":180,\"height\":180,\"caption\":\"Suno Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/sunoresearch\",\"https:\/\/x.com\/sunoresearch\",\"https:\/\/www.instagram.com\/suno\",\"https:\/\/www.linkedin.com\/company\/suno-research\/\",\"https:\/\/www.youtube.com\/c\/sunoresearch\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/e672ca8cea627fe715fa29bca7da95e0\",\"name\":\"Rafaela La Regina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d2c75a52d243deb93d0465fdcb21bd37?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d2c75a52d243deb93d0465fdcb21bd37?s=96&r=g\",\"caption\":\"Rafaela La Regina\"},\"description\":\"Estagi\u00e1ria no Suno Not\u00edcias. Escreve sobre economia, pol\u00edtica e neg\u00f3cios. Estuda Rela\u00e7\u00f5es Internacionais no IBMEC-SP.\",\"url\":\"https:\/\/www.suno.com.br\/noticias\/author\/rafaela-la-regina\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EUA: Ind\u00fastria e servi\u00e7os est\u00e3o se recuperando, diz IHS Markit","description":"A\u00a0atividade econ\u00f4mica no setor privado dos EUA teve alta em novembro, apesar do aumento de casos de covid-19. Clique aqui para saber mais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/","og_locale":"pt_BR","og_type":"article","og_title":"EUA: Ind\u00fastria e servi\u00e7os est\u00e3o se recuperando, diz IHS Markit","og_description":"A\u00a0atividade econ\u00f4mica no setor privado dos EUA teve alta em novembro, apesar do aumento de casos de covid-19. Clique aqui para saber mais.","og_url":"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/","og_site_name":"Suno Not\u00edcias","article_publisher":"https:\/\/facebook.com\/sunoresearch","og_image":[{"width":800,"height":450,"url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/11\/26e28569-eua-2.jpg","type":"image\/jpeg"}],"author":"Rafaela La Regina","twitter_card":"summary_large_image","twitter_creator":"@sunoresearch","twitter_site":"@sunoresearch","twitter_misc":{"Escrito por":"Rafaela La Regina","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/#article","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/"},"author":{"name":"Rafaela La Regina","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/e672ca8cea627fe715fa29bca7da95e0"},"headline":"EUA: Ind\u00fastria e servi\u00e7os est\u00e3o se recuperando, diz IHS Markit","datePublished":"2020-11-23T18:17:08+00:00","dateModified":"2021-06-14T02:29:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/"},"wordCount":539,"publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/11\/26e28569-eua-2-jpg.webp","keywords":["Economia","Estados Unidos (EUA)"],"articleSection":["Internacional"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/","url":"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/","name":"EUA: Ind\u00fastria e servi\u00e7os est\u00e3o se recuperando, diz IHS Markit","isPartOf":{"@id":"https:\/\/www.suno.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/#primaryimage"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/#primaryimage"},"thumbnailUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/11\/26e28569-eua-2-jpg.webp","datePublished":"2020-11-23T18:17:08+00:00","dateModified":"2021-06-14T02:29:27+00:00","description":"A\u00a0atividade econ\u00f4mica no setor privado dos EUA teve alta em novembro, apesar do aumento de casos de covid-19. Clique aqui para saber mais.","breadcrumb":{"@id":"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/#primaryimage","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/11\/26e28569-eua-2-jpg.webp","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/11\/26e28569-eua-2-jpg.webp","width":800,"height":450,"caption":"EUA: Ind\u00fastria e servi\u00e7os est\u00e3o se recuperando, diz IHS Markit"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Not\u00edcias","item":"https:\/\/www.suno.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Internacional","item":"https:\/\/www.suno.com.br\/noticias\/internacional\/"},{"@type":"ListItem","position":3,"name":"EUA: Ind\u00fastria e servi\u00e7os est\u00e3o se recuperando, diz IHS Markit"}]},{"@type":"WebSite","@id":"https:\/\/www.suno.com.br\/noticias\/#website","url":"https:\/\/www.suno.com.br\/noticias\/","name":"Suno Not\u00edcias","description":"Seu portal de informa\u00e7\u00e3o sobre o mundo dos investimentos","publisher":{"@id":"https:\/\/www.suno.com.br\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suno.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.suno.com.br\/noticias\/#organization","name":"Suno Not\u00edcias","url":"https:\/\/www.suno.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","contentUrl":"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2021\/09\/suno-logo.png","width":180,"height":180,"caption":"Suno Not\u00edcias"},"image":{"@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/sunoresearch","https:\/\/x.com\/sunoresearch","https:\/\/www.instagram.com\/suno","https:\/\/www.linkedin.com\/company\/suno-research\/","https:\/\/www.youtube.com\/c\/sunoresearch"]},{"@type":"Person","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/e672ca8cea627fe715fa29bca7da95e0","name":"Rafaela La Regina","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.suno.com.br\/noticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d2c75a52d243deb93d0465fdcb21bd37?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d2c75a52d243deb93d0465fdcb21bd37?s=96&r=g","caption":"Rafaela La Regina"},"description":"Estagi\u00e1ria no Suno Not\u00edcias. Escreve sobre economia, pol\u00edtica e neg\u00f3cios. Estuda Rela\u00e7\u00f5es Internacionais no IBMEC-SP.","url":"https:\/\/www.suno.com.br\/noticias\/author\/rafaela-la-regina\/"}]}},"default_loop_html":"<div class=\"cardsPage__listCard__boxs\"><div class=\"cardsPage__listCard__boxs__img\"><a href=\"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/\"><img class=\"mask\" src=\"https:\/\/www.suno.com.br\/noticias\/wp-content\/themes\/suno\/resources\/images\/spotlight\/spotlight1img\/bg-mask.png\" alt=\"Image Mask\"\/><img src=\"https:\/\/files.sunoresearch.com.br\/n\/uploads\/2020\/11\/26e28569-eua-2-400x200.webp\" alt=\"EUA: Ind\u00fastria e servi\u00e7os est\u00e3o se recuperando, diz IHS Markit\"\/><\/a><span class=\"spotlightCategory\"><a href=\"https:\/\/www.suno.com.br\/noticias\/internacional\/\">Internacional<\/a><\/span><\/div><div class=\"cardsPage__listCard__boxs__content\"><a href=\"https:\/\/www.suno.com.br\/noticias\/eua-industria-e-servicos-estao-se-recuperando-diz-ihs-markit\/\"><h2 class=\"content__title\">EUA: Ind\u00fastria e servi\u00e7os est\u00e3o se recuperando, diz IHS Markit<\/h2><\/a><div class=\"newsContent__article__meta\"><div class=\"newsContent__article__meta__authorBox\"><a href=\"https:\/\/www.suno.com.br\/noticias\/author\/rafaela-la-regina\/\" class=\"authorBox__avatar noMobi\"><img src=\"https:\/\/secure.gravatar.com\/avatar\/d2c75a52d243deb93d0465fdcb21bd37?s=96&#038;r=g\" alt=\"Rafaela La Regina\"><\/a><div class=\"authorBox__name\"><span>por\n\t\t\t<a href=\"https:\/\/www.suno.com.br\/noticias\/author\/rafaela-la-regina\/\"><span itemprop=\"author\">Rafaela La Regina<\/span><\/a><\/span><time datetime=\"2020-11-23T15:17:08-03:00\" itemprop=\"datePublished\">23\/11\/2020 15:17<\/time><\/div><\/div><\/div><\/div><\/div>","single_layout":"posts","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/102384"}],"collection":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=102384"}],"version-history":[{"count":1,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/102384\/revisions"}],"predecessor-version":[{"id":156791,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/posts\/102384\/revisions\/156791"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media\/102388"}],"wp:attachment":[{"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=102384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=102384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=102384"},{"taxonomy":"suno_strategy","embeddable":true,"href":"https:\/\/www.suno.com.br\/noticias\/wp-json\/wp\/v2\/suno_strategy?post=102384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}